



{"id":946207,"date":"2024-01-06T19:46:48","date_gmt":"2024-01-06T19:46:48","guid":{"rendered":"https:\/\/mindspa.me\/?p=946207"},"modified":"2024-01-06T19:46:51","modified_gmt":"2024-01-06T19:46:51","slug":"culpable-sin-culpa-5-hechos-honestos-sobre-la-culpa-despues-de-una-ruptura","status":"publish","type":"post","link":"https:\/\/mindspa.me\/it\/culpable-sin-culpa-5-hechos-honestos-sobre-la-culpa-despues-de-una-ruptura\/","title":{"rendered":"Culpable sin culpa. 5 hechos honestos sobre la culpa despu\u00e9s de una ruptura"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"660\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41.jpg\" alt=\"\" class=\"wp-image-946203\" style=\"width:277px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41.jpg 980w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41-300x202.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41-768x517.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41-18x12.jpg 18w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41-600x404.jpg 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/01\/Nuovo-progetto-41-64x43.jpg 64w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>La culpa es una fiel compa\u00f1era de las personas que atraviesan una ruptura. Esto es lo que es importante saber al respecto:<\/p>\n\n\n\n<p>Hecho uno<\/p>\n\n\n\n<p>La culpa obsesiva es una especie de control. Si todo es culpa m\u00eda, entonces est\u00e1 en mi poder cambiarlo todo, reproducir la situaci\u00f3n, deshacer las cosas. \u00a1Si pude romperlo, puedo arreglarlo!<\/p>\n\n\n\n<p>S\u00f3lo necesito averiguar c\u00f3mo. Spoiler: si te apegas a esta ilusi\u00f3n, te resultar\u00e1 muy dif\u00edcil deshacerte de tu dolorosa culpa.<\/p>\n\n\n\n<p>Hecho dos<\/p>\n\n\n\n<p>La culpa puede ser adecuada e inadecuada (neur\u00f3tica). Culpa adecuada significa que hay una falta espec\u00edfica, alg\u00fan da\u00f1o claro, y sabes c\u00f3mo reparar este da\u00f1o; solo eres responsable de ti mismo y de tu comportamiento. La culpa neur\u00f3tica significa que no hay detalles, solo evaluaci\u00f3n generalizada, responsabilidad total por uno mismo y por el comportamiento de la otra persona, autorrechazo.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><!--<ul class=\"products columns---><!--\">-->\n<style>\n \n    .woocommerce span.onsale{\n        display: none;\n    }\n    .woocommerce-Price-amount.amount{\n        color: #fff;\n    }\n    .often_buy-list::before, .often_buy-list::after{\n        display: none!important;\n    }\n    .related.products h2{\n        margin-bottom: 40px;\n    }\n<\/style>\n<ul class=\"often_buy-list\">\n\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\t\u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 40 \u0434\u043d\u0435\u0439\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/946207?add-to-cart=961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Aggiungi al carrello: &quot;Ludopat\u00eda&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Ludopat\u00eda&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04ebd573901\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\tDurata: 30 giorni\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/946207?add-to-cart=11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Aggiungi al carrello: &quot;Superar una separaci\u00f3n (para mujer)&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Superar una separaci\u00f3n (para mujer)&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04ebd57432a\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p>Hecho tres<\/p>\n\n\n\n<p>La mentalidad \u201cNo puedo perdonarme a m\u00ed mismo\u201d es un signo de conflicto interno. La frase en s\u00ed implica dos partes: la que tiene la culpa y la que est\u00e1 culpando. Tienes que ponerte en contacto con la parte acusadora y preguntarle qu\u00e9 quiere, qu\u00e9 intenta conseguir acus\u00e1ndote y qu\u00e9 tiene que pasar para que se sienta mejor.<\/p>\n\n\n\n<p>Hecho cuatro<\/p>\n\n\n\n<p>La culpa neur\u00f3tica despu\u00e9s de una ruptura puede indicar que tiendes a asumir la responsabilidad de otra persona y tienes el complejo de sentirte culpable todo el tiempo. Por regla general, se desarrolla en personas que provienen de familias destructivas, donde los adultos manipulan el sentimiento de culpa del ni\u00f1o para ense\u00f1arle y hacer que se comporte de la forma deseada.<\/p>\n\n\n\n<p>Hecho cinco<\/p>\n\n\n\n<p>La culpa y la capacidad de superarla est\u00e1n relacionadas con la autoestima y la autoimagen. Las personas que tienen problemas con la autopercepci\u00f3n se enfrentan peor a la culpa que aquellas que tienen una imagen propia adecuada y positiva.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La culpa es una fiel compa\u00f1era de las personas que atraviesan una ruptura. Esto es lo que es importante saber al respecto: Hecho uno La culpa obsesiva es una especie de control. Si todo es culpa m\u00eda, entonces est\u00e1 en mi poder cambiarlo todo, reproducir la situaci\u00f3n, deshacer las cosas. \u00a1Si pude romperlo, puedo arreglarlo!&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/it\/culpable-sin-culpa-5-hechos-honestos-sobre-la-culpa-despues-de-una-ruptura\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Culpable sin culpa. 5 hechos honestos sobre la culpa despu\u00e9s de una ruptura<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":946203,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[83,100,883,927,1165,2536],"class_list":["post-946207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-amar","tag-ansiedad","tag-mindspa","tag-nervioso","tag-relaciones","tag-romper"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/946207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/comments?post=946207"}],"version-history":[{"count":0,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/946207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media\/946203"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media?parent=946207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/categories?post=946207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/tags?post=946207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}