



{"id":9058,"date":"2021-10-22T13:35:28","date_gmt":"2021-10-22T13:35:28","guid":{"rendered":"https:\/\/www.mindspa.me\/?p=9058"},"modified":"2021-10-22T13:35:28","modified_gmt":"2021-10-22T13:35:28","slug":"shinrin-yoku-3","status":"publish","type":"post","link":"https:\/\/mindspa.me\/it\/shinrin-yoku-3\/","title":{"rendered":"Shinrin Yoku"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10.jpg\" alt=\"\" class=\"wp-image-9054\" width=\"285\" height=\"174\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10.jpg 980w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-600x367.jpg 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-64x39.jpg 64w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-300x184.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-768x470.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-18x12.jpg 18w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-10-500x306.jpg 500w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Shinrin Yoku es una pr\u00e1ctica terap\u00e9utica japonesa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su esencia, se trata de un proceso de relajaci\u00f3n disfrutando de la naturaleza e intentando hacerse uno con ella. Se trata de un m\u00e9todo \u00fanico para tratar el estr\u00e9s y la depresi\u00f3n sin la ayuda de m\u00e9dicos y medicamentos. La terapia del bosque est\u00e1 reconocida oficialmente en Jap\u00f3n y Corea del Sur. Las investigaciones cient\u00edficas han confirmado que ayuda a reducir los niveles de agresividad y las hormonas del estr\u00e9s y, al mismo tiempo, aumenta la productividad y la inmunidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Ve a un bosque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Busca un lugar apartado.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><ul class=\"products columns-2\">\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 961407 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/9058?add-to-cart=961407\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Aggiungi al carrello: &quot;Ludopat\u00eda&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Ludopat\u00eda&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_961407\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a57c3a86fede\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 11403 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/9058?add-to-cart=11403\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Aggiungi al carrello: &quot;Superar una separaci\u00f3n (para mujer)&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Superar una separaci\u00f3n (para mujer)&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_11403\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a57c3a870637\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Pon en marcha tus cinco sentidos: observa tu entorno, respira profundamente, escucha los sonidos del bosque, toca los \u00e1rboles, &#171;saborea&#187; el aire que te rodea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Cierra los ojos y siente la paz y la armon\u00eda.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>El Shinrin Yoku es una pr\u00e1ctica terap\u00e9utica japonesa.&nbsp; En su esencia, se trata de un proceso de relajaci\u00f3n disfrutando de la naturaleza e intentando hacerse uno con ella. Se trata de un m\u00e9todo \u00fanico para tratar el estr\u00e9s y la depresi\u00f3n sin la ayuda de m\u00e9dicos y medicamentos. La terapia del bosque est\u00e1 reconocida oficialmente&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/it\/shinrin-yoku-3\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Shinrin Yoku<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":9054,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[65,498,525,883,1273,1410],"class_list":["post-9058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-agresion","tag-enfado","tag-estres","tag-mindspa","tag-sentidos","tag-terapia"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/9058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/comments?post=9058"}],"version-history":[{"count":0,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/9058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media\/9054"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media?parent=9058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/categories?post=9058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/tags?post=9058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}