



{"id":8937,"date":"2021-10-12T17:32:22","date_gmt":"2021-10-12T17:32:22","guid":{"rendered":"https:\/\/www.mindspa.me\/?p=8937"},"modified":"2021-10-12T17:32:22","modified_gmt":"2021-10-12T17:32:22","slug":"como-tratar-con-personas-conflictivas","status":"publish","type":"post","link":"https:\/\/mindspa.me\/it\/como-tratar-con-personas-conflictivas\/","title":{"rendered":"\u00bfC\u00f3mo tratar con personas conflictivas?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5.jpg\" alt=\"\" class=\"wp-image-8933\" width=\"293\" height=\"196\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5.jpg 980w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-600x404.jpg 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-64x43.jpg 64w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-300x202.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-768x517.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-18x12.jpg 18w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-930x620.jpg 930w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/10\/Nuovo-progetto-1-5-500x337.jpg 500w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/figure><\/div>\n\n\n\n<p>Si no te has encontrado con personas conflictivas, consid\u00e9rate una persona afortunada. Parece que estas personas viven para tener conflictos y discutir por todo. Hay un rasgo de personalidad especial que determina la probabilidad de que una persona entre en una disputa, independientemente de la raz\u00f3n objetiva.<\/p>\n\n\n\n<p>Las razones para discutir pueden ser diferentes.&nbsp; Durante ciertos periodos, cuando se experimentan problemas, cuando todo no va bien y el estr\u00e9s es alto, cada uno de nosotros puede volverse agresivo. Pero esto es un conflicto situacional. Otra historia es la de los tipos de personalidad para los que la agresividad es una caracter\u00edstica estable que es completamente independiente de las circunstancias.<\/p>\n\n\n\n<p>Hay varios tipos de confrontaci\u00f3n. Teniendo un conocimiento general de ellos, podemos desarrollar una estrategia que nos salvar\u00e1 cuando interactuemos con ellos.<\/p>\n\n\n\n<p>Tipo demostrativo \u2013 &#171;\u00a1M\u00edrame!&#187;<\/p>\n\n\n\n<p>Una persona as\u00ed est\u00e1 siempre en el centro de atenci\u00f3n. Siempre. Completamente. El tipo demostrativo observa con atenci\u00f3n lo que los dem\u00e1s piensan de ellos, c\u00f3mo se ven a los ojos de los dem\u00e1s. A cualquier precio, deben estar en la cima. Si para ello ser\u00e1 necesario empujarte lejos, te empujar\u00e1n sin dudarlo. Las situaciones de conflicto los encienden. A menudo se convierten en participantes activos y brillan intensamente en la arena. La alta emocionalidad tambi\u00e9n le da m\u00e1s le\u00f1a al fuego, porque primero hay una reacci\u00f3n y el pensamiento viene mucho despu\u00e9s, si es que llega.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo interactuar con este tipo?<\/p>\n\n\n\n<p>Ten preparados un par de cumplidos, esc\u00fachalos, trata de encontrar algo que admirar de ellos. Si la situaci\u00f3n requiere que negocies algo con una persona demostrativa, es mejor no discutir de frente, sino hacerlo como si te propusieran algo y t\u00fa estuvieras de acuerdo.<\/p>\n\n\n\n<p>Eleanore es una mujer brillante de la edad de Balzac, es contadora. Est\u00e1 orientada al conflicto y discute en voz alta tratando de persuadir a la gente para que est\u00e9 de su lado. Nadie puede encontrar un lenguaje com\u00fan con ella, excepto Renee del departamento de ventas. Todo el mundo est\u00e1 perplejo: \u00bfc\u00f3mo es esto posible? Y Renee simplemente entra y comienza un di\u00e1logo preguntando d\u00f3nde se hizo Eleanore una manicura tan hermosa o pide consejo sobre alg\u00fan asunto trivial. Despu\u00e9s de eso, Eleanore se calma y brilla con amabilidad.<\/p>\n\n\n\n<p>Tipo r\u00edgido \u2013 &#171;A mi manera o nada&#187; y &#171;\u00bfQu\u00e9 quisiste decir cuando me miraste as\u00ed?&#187;<\/p>\n\n\n\n<p>Este tipo tiende a atascarse y es muy inflexible. Se valoran mucho a s\u00ed mismos y pueden sentirse profundamente ofendidos si alguien no est\u00e1 de acuerdo con ellos. Ellos perciben el cambio como duro y dif\u00edcil. Ser conservadores les permite sentirse en tierra firme. Son directos y comunicativos, pero su &#171;verdad&#187; les parece la \u00fanica posible. Son sospechosos. Si tienes una pelea con ellos, es muy dif\u00edcil hacer las paces. Recuerdan los agravios durante mucho tiempo, y no importa si son reales o inventados.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo interactuar?<\/p>\n\n\n\n<p>Apela a los hechos, sin ning\u00fan &#171;sinsentido&#187; como emociones y opiniones. Los estereotipos son geniales, la innovaci\u00f3n no. En la interacci\u00f3n personal, cuida tu bienestar emocional y no intentes demostrar nada \u2013 es una p\u00e9rdida de tiempo.<\/p>\n\n\n\n<p>Neha es bibliotecaria de la escuela. Todos los profesores conocen su susceptibilidad y su corrosividad. Una vez la invitaron a una fiesta de cumplea\u00f1os una hora m\u00e1s tarde que las dem\u00e1s. Debido a esto, ha puesto a todos en la categor\u00eda de personas desvergonzadas con las que no puedes interactuar. Neha est\u00e1 muy bien informada. No tiene comparaci\u00f3n en la organizaci\u00f3n de ex\u00e1menes para los ni\u00f1os en la escuela, pero es mejor comunicarse con ella solo en el trabajo.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><!--<ul class=\"products columns---><!--\">-->\n<style>\n \n    .woocommerce span.onsale{\n        display: none;\n    }\n    .woocommerce-Price-amount.amount{\n        color: #fff;\n    }\n    .often_buy-list::before, .often_buy-list::after{\n        display: none!important;\n    }\n    .related.products h2{\n        margin-bottom: 40px;\n    }\n<\/style>\n<ul class=\"often_buy-list\">\n\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\t\u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 40 \u0434\u043d\u0435\u0439\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/8937?add-to-cart=961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Aggiungi al carrello: &quot;Ludopat\u00eda&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Ludopat\u00eda&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04f93a13e00\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\tDurata: 30 giorni\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/it\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Leggi di pi\u00f9\n            <\/a><a href=\"\/it\/wp-json\/wp\/v2\/posts\/8937?add-to-cart=11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Aggiungi al carrello: &quot;Superar una separaci\u00f3n (para mujer)&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Superar una separaci\u00f3n (para mujer)&quot; \u00e8 stato aggiunto al tuo carrello.\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Aggiungi al carrello<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04f93a16bbe\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo originale era: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Il prezzo attuale \u00e8: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p>Tipo ultrapreciso \u2013 &#171;\u00bfY si?&#187;<\/p>\n\n\n\n<p>Estas &#171;personas ansiosas&#187; siempre est\u00e1n preocupadas por si corresponden a la idea que los dem\u00e1s tienen de s\u00ed mismas, si agradan a los dem\u00e1s o hablan a sus espaldas. Pueden hacer suposiciones sobre las intenciones de las personas y llegar al extremo. Las personas ultraprecisas se preocupan mucho, a menudo se sienten culpables e intentan hacer todo a la perfecci\u00f3n.<\/p>\n\n\n\n<p>Cuando Karen trabaja en equipo, genera estr\u00e9s tanto para ella como&#8230; para todos los dem\u00e1s, porque Karen est\u00e1 tratando de superar a todos y verificar el trabajo de todos. Las situaciones de conflicto laboral le causan mucho estr\u00e9s.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo interactuar?<\/p>\n\n\n\n<p>Lo principal es no presionar. Persuadir suavemente, mostrar beneficios, usar cortes\u00edas psicol\u00f3gicas (elogios, cumplidos).<\/p>\n\n\n\n<p>Tipo inmanejable \u2013 &#171;Hago lo que quiero&#187;.<\/p>\n\n\n\n<p>Impulsivo, explosivo, propenso a enfurecerse. Es imposible predecir su comportamiento. Pueden ignorar las normas aceptadas en la sociedad. La inconsistencia de su comportamiento puede resultar impactante.<\/p>\n\n\n\n<p>Sean es un gran jefe. Nadie sabe c\u00f3mo estar\u00e1 hoy &#8212; sonreir\u00e1 y tararear\u00e1 o empezar\u00e1 a gritarle a todo el mundo. Todas las ma\u00f1anas, todos los empleados aguantan la respiraci\u00f3n escuchando sus pasos en el pasillo, tratando de entender lo que les espera hoy&#8230;<\/p>\n\n\n\n<p>\u00bfC\u00f3mo interactuar?<\/p>\n\n\n\n<p>Es mejor no interactuar, pero si es necesario &#8212; no entres en &#171;su&#187; territorio. Es mejor no dar una reacci\u00f3n agresiva para que el conflicto no se intensifique.<\/p>\n\n\n\n<p>Tipo de evitaci\u00f3n de conflictos \u2013 &#171;No estoy aqu\u00ed, no me vean&#187;.<\/p>\n\n\n\n<p>S\u00ed, el tipo que evita los conflictos tambi\u00e9n es un tipo de personalidad de confrontaci\u00f3n, incluso si suena extra\u00f1o.<\/p>\n\n\n\n<p>Rara vez discuten, intentan &#171;tomar la direcci\u00f3n del viento&#187;, estar de acuerdo con la mayor\u00eda y proporcionarse consuelo psicol\u00f3gico.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo interactuar?<\/p>\n\n\n\n<p>Apelar a la opini\u00f3n de la mayor\u00eda y citar autoridades. Si muestras el deseo de llegar a un compromiso y estar de acuerdo, no habr\u00e1 problemas.<\/p>\n\n\n\n<p>Si se maneja el conflicto &#8212; y el conocimiento de los rasgos de personalidad del interlocutor ayuda mucho en esto &#8212; deja de ser destructivo y es muy posible dirigirlo por un canal pac\u00edfico. \u00a1Y esto es exactamente lo que necesitamos!<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Si no te has encontrado con personas conflictivas, consid\u00e9rate una persona afortunada. Parece que estas personas viven para tener conflictos y discutir por todo. Hay un rasgo de personalidad especial que determina la probabilidad de que una persona entre en una disputa, independientemente de la raz\u00f3n objetiva. Las razones para discutir pueden ser diferentes.&nbsp; Durante&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/it\/como-tratar-con-personas-conflictivas\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">\u00bfC\u00f3mo tratar con personas conflictivas?<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":8933,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[164,194,264,292,609,883,1087],"class_list":["post-8937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-bienestar","tag-calma","tag-comparacion","tag-conflicto","tag-gente","tag-mindspa","tag-problemas"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/8937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/comments?post=8937"}],"version-history":[{"count":0,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/posts\/8937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media\/8933"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/media?parent=8937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/categories?post=8937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/it\/wp-json\/wp\/v2\/tags?post=8937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}