



{"id":977760,"date":"2024-12-10T16:42:00","date_gmt":"2024-12-10T16:42:00","guid":{"rendered":"https:\/\/mindspa.me\/?p=977760"},"modified":"2024-12-10T16:42:01","modified_gmt":"2024-12-10T16:42:01","slug":"tu-propio-abogado","status":"publish","type":"post","link":"https:\/\/mindspa.me\/es\/tu-propio-abogado\/","title":{"rendered":"Tu Propio Abogado"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-1024x683.jpg\" alt=\"\" class=\"wp-image-977756\" style=\"width:209px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-1024x683.jpg 1024w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-300x200.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-768x512.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-gabby-k-7114755-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El cr\u00edtico interior es una parte de la personalidad que vigila atentamente nuestro comportamiento. A menudo se vuelve excesivamente estricto y exigente, y te impide desarrollar o tomar acci\u00f3n. Aqu\u00ed hay una t\u00e9cnica que te ayudar\u00e1 a manejarlo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paso uno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toma una hoja de papel y escribe todos los \u201cargumentos\u201d que te caracterizan a ti y a tus acciones recientes negativamente. Esto te dar\u00e1 material visible para el an\u00e1lisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No lo llam\u00e9 cuando lo promet\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No planch\u00e9 su camisa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No le dije lo suficiente cu\u00e1nto significaba para m\u00ed, cu\u00e1nto lo amaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la ruptura, me volv\u00ed menos eficiente en el trabajo, constantemente me distraigo con sentimientos y recuerdos del pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sub\u00ed de peso despu\u00e9s de romper con mi novio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siento que no valgo nada y que nadie m\u00e1s me querr\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo paso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imagina que te encuentras en una sala del tribunal donde un panel est\u00e1 considerando tu caso. Lee todos los cargos que has escrito en nombre del fiscal. Habla de ti en tercera persona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy no llam\u00f3 a su novio cuando se lo prometi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella no planch\u00f3 su camisa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy no le dijo a su novio lo mucho que significaba para ella y cu\u00e1nto lo amaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la ruptura, se volvi\u00f3 menos eficiente en el trabajo, constantemente se distrae con sentimientos y recuerdos del pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gan\u00f3 peso despu\u00e9s de romper con tu novio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy es una persona sin valor y nadie m\u00e1s la querr\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paso tres<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora imag\u00ednate a ti mismo como un abogado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para cada una de las acusaciones haz una respuesta por escrito en nombre del defensor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede que te resulte dif\u00edcil encontrar argumentos de defensa al principio (porque no est\u00e1s acostumbrado a hablar de ti mismo y verte de manera positiva), pero hazlo de todos modos. No dejes un solo punto sin un contraargumento. Intenta tratarte con comprensi\u00f3n y cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy no llam\u00f3 a su novio como prometi\u00f3, porque estaba haciendo un informe mensual en el trabajo y no pod\u00eda distraerse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy no planch\u00f3 su camisa, pero dado lo cansada que ha estado \u00faltimamente, no es el peor crimen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy rara vez le dec\u00eda a su novio lo mucho que significaba para ella, porque le resultaba dif\u00edcil expresar tus sentimientos, pero lo hac\u00eda lo mejor que pod\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la ruptura, Judy se volvi\u00f3 menos eficiente en el trabajo porque estaba bajo un estr\u00e9s severo que es dif\u00edcil de sobrellevar; es genial que incluso siguiera trabajando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Judy aument\u00f3 de peso despu\u00e9s de la ruptura porque trat\u00f3 de comerse sus sentimientos; es bueno que no haya empezado a beber ni a desquitarse con otras personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Romper con una pareja no significa que Judy nunca encontrar\u00e1 otra. Ella es hermosa, exitosa y amable: estas cualidades son atractivas para los hombres.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><ul class=\"products columns-2\">\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/es\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 961407 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/es\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Lee m\u00e1s\n            <\/a><a href=\"\/es\/wp-json\/wp\/v2\/posts\/977760?add-to-cart=961407\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"A\u00f1adir al carrito: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u00abLudopat\u00eda\u00bb se ha a\u00f1adido a tu carrito\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">A\u00f1adir al carrito<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_961407\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"USD\" data-redraw-id=\"6a56efff7d011\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>99.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El precio original era: 99.99&#036;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>44.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El precio actual es: 44.99&#036;.<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/es\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 11403 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/es\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Lee m\u00e1s\n            <\/a><a href=\"\/es\/wp-json\/wp\/v2\/posts\/977760?add-to-cart=11403\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"A\u00f1adir al carrito: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u00abSuperar una separaci\u00f3n (para mujer)\u00bb se ha a\u00f1adido a tu carrito\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">A\u00f1adir al carrito<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_11403\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"USD\" data-redraw-id=\"6a56efff7d6dd\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>99.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El precio original era: 99.99&#036;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>44.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El precio actual es: 44.99&#036;.<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paso cuatro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lee tus respuestas en voz alta y expresivamente: imagina que te diriges al juez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paso cinco<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toma la posici\u00f3n del juez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Absu\u00e9lvete en tu nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Form\u00falalo primero en papel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teniendo en cuenta todas las circunstancias del caso, Judy es absuelta de todos los cargos. Ten\u00eda buenas razones para todo lo que hac\u00eda. Actu\u00f3 de acuerdo con su condici\u00f3n emocional y f\u00edsica, as\u00ed como en funci\u00f3n de sus capacidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para evitar tales condiciones en el futuro, el tribunal dictamina que Judy debe:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf proporcionarse ayuda antiestr\u00e9s;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf practicar ejercicios de respiraci\u00f3n para recuperar la capacidad de concentraci\u00f3n;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf intentar salir en una cita con un hombre interesado en ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paso seis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lee el veredicto del juez en voz alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Repite esta t\u00e9cnica una vez a la semana, y tu actitud hacia ti mismo y tus acciones cambiar\u00e1n para mejor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por cierto, si tienes la oportunidad de moverte por la sala durante el ejercicio, de modo que el fiscal, el abogado y el juez hablen desde diferentes puntos, hazlo, potenciar\u00e1 el efecto de esta t\u00e9cnica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>El cr\u00edtico interior es una parte de la personalidad que vigila atentamente nuestro comportamiento. A menudo se vuelve excesivamente estricto y exigente, y te impide desarrollar o tomar acci\u00f3n. Aqu\u00ed hay una t\u00e9cnica que te ayudar\u00e1 a manejarlo: Paso uno Toma una hoja de papel y escribe todos los \u201cargumentos\u201d que te caracterizan a ti&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/es\/tu-propio-abogado\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Tu Propio Abogado<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":977756,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[100,138,2742,525,2741,877,883,1276],"class_list":["post-977760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-ansiedad","tag-autoestima","tag-critico-2","tag-estres","tag-gente-negativa","tag-miedo","tag-mindspa","tag-sentimientos"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/posts\/977760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/comments?post=977760"}],"version-history":[{"count":1,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/posts\/977760\/revisions"}],"predecessor-version":[{"id":977762,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/posts\/977760\/revisions\/977762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/media\/977756"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/media?parent=977760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/categories?post=977760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/tags?post=977760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}