



{"id":1003814,"date":"2026-01-28T21:03:48","date_gmt":"2026-01-28T18:03:48","guid":{"rendered":"https:\/\/mindspa.me\/?page_id=1003814"},"modified":"2026-01-29T12:51:30","modified_gmt":"2026-01-29T09:51:30","slug":"genatik","status":"publish","type":"page","link":"https:\/\/mindspa.me\/es\/genatik\/","title":{"rendered":"\u0416\u0435\u043d\u0430\u0442\u0438\u043a"},"content":{"rendered":"<!--allrecords--> <div id=\"allrecords\" class=\"t-records\" data-hook=\"blocks-collection-content-node\" data-tilda-project-id=\"10433953\" data-tilda-page-id=\"114155056\" data-tilda-page-alias=\"genatik\" data-tilda-formskey=\"467142ce835c15fd8b4bc26810433953\" data-tilda-cookie=\"no\" data-tilda-lazy=\"yes\" data-tilda-root-zone=\"com\" data-tilda-project-headcode=\"yes\" data-tilda-project-country=\"RU\"> <div id=\"rec1845164141\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845164141 .t396__artboard {height:721px;background-color:#eef5f6;}#rec1845164141 .t396__filter {height:721px;}#rec1845164141 .t396__carrier{height:721px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845164141 .t396__artboard,#rec1845164141 .t396__filter,#rec1845164141 .t396__carrier {height:721px;}#rec1845164141 .t396__filter {}#rec1845164141 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845164141 .t396__artboard,#rec1845164141 .t396__filter,#rec1845164141 .t396__carrier {height:721px;}#rec1845164141 .t396__filter {}#rec1845164141 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845164141 .t396__artboard,#rec1845164141 .t396__filter,#rec1845164141 .t396__carrier {height:721px;}#rec1845164141 .t396__filter {}#rec1845164141 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845164141 .t396__artboard,#rec1845164141 .t396__filter,#rec1845164141 .t396__carrier {height:1121px;}#rec1845164141 .t396__filter {}#rec1845164141 .t396__carrier {background-attachment:scroll;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"]{color:#192032;z-index:3;top:130px;;left:calc(50% - 600px + 20px);;width:656px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"] .tn-atom{vertical-align:middle;color:#192032;font-size:48px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"]{display:table;top:131px;;left:calc(50% - 160px + 10px);;width:310px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609056061\"] .tn-atom{font-size:36px;background-size:cover;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"]{color:#192032;z-index:3;top:344px;;left:calc(50% - 600px + 20px);;width:584px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"]{display:table;top:406px;;left:calc(50% - 160px + 10px);;width:263px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609375434000002\"] .tn-atom{font-size:20px;background-size:cover;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"]{color:#192032;z-index:3;top:266px;;left:calc(50% - 600px + 20px);;width:584px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:600;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"]{display:table;top:319px;;left:calc(50% - 160px + 10px);;width:310px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609334301000001\"] .tn-atom{font-size:20px;background-size:cover;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"]{z-index:3;top:393px;;left:calc(50% - 600px + 370px);;width:160px;height:160px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609345108\"]{display:table;top:651px;;left:calc(50% - 160px + 10px);;width:300px;height:80px;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"]{color:#192032;z-index:3;top:481px;;left:calc(50% - 600px + 385px);;width:104px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609292605\"]{display:table;top:672px;;left:calc(50% - 160px + 90px);;width:167px;height:auto;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"]{z-index:3;top:408px;;left:calc(50% - 600px + 465px);;width:50px;height:50px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609398205\"]{display:table;top:666px;;left:calc(50% - 160px + 25px);;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"]{z-index:3;top:393px;;left:calc(50% - 600px + 195px);;width:160px;height:160px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000009\"]{display:table;top:559px;;left:calc(50% - 160px + 10px);;width:301px;height:80px;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"]{color:#192032;z-index:3;top:481px;;left:calc(50% - 600px + 210px);;width:129px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000010\"]{display:table;top:580px;;left:calc(50% - 160px + 90px);;width:182px;height:auto;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"]{z-index:3;top:408px;;left:calc(50% - 600px + 290px);;width:50px;height:50px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609495463000011\"]{display:table;top:574px;;left:calc(50% - 160px + 25px);;width:50px;height:50px;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"]{z-index:3;top:393px;;left:calc(50% - 600px + 20px);;width:160px;height:160px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000005\"]{display:table;top:470px;;left:calc(50% - 160px + 10px);;width:300px;height:80px;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"]{color:#192032;z-index:3;top:481px;;left:calc(50% - 600px + 35px);;width:103px;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000006\"]{display:table;top:491px;;left:calc(50% - 160px + 90px);;width:182px;height:auto;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"]{z-index:3;top:408px;;left:calc(50% - 600px + 115px);;width:50px;height:50px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609484533000007\"]{display:table;top:485px;;left:calc(50% - 160px + 25px);;}}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"]{color:#ffffff;text-align:center;z-index:3;top:583px;;left:calc(50% - 600px + 20px);;width:209px;height:48px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom{color:#ffffff;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.55;font-weight:600;border-radius:30px 30px 30px 30px;background-position:center center;--t396-speedhover:0.2s;transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-bgcolor-color:#3f89c4;--t396-bgcolor-image:none;--t396-bgcolor-hover-color:#20649a;--t396-bgcolor-hover-image:none;background-color:var(--t396-bgcolor-color,transparent);-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom::after{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-content{column-gap:10px;padding:0px 0px 0px 0px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-text{transition:color var(--t396-speedhover,0s) ease-in-out;color:#ffffff;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover::after{opacity:0;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{color:#ffffff;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover .tn-atom__button-text{color:#ffffff;}}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"]{display:block;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom::after{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover::after{opacity:0;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"]{display:block;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom::after{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover::after{opacity:0;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"]{display:block;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom::after{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover::after{opacity:0;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"]{display:block;top:758px;;left:calc(50% - 160px + 10px);;height:auto;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom::after{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover::after{opacity:0;}#rec1845164141 .tn-elem[data-elem-id=\"1769609521326\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"]{z-index:3;top:130px;;left:calc(50% - 600px + 676px);;width:507px;height:591px;}#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"]{display:table;}}@media screen and (max-width:959px){#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"]{display:table;}}@media screen and (max-width:639px){#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"]{display:table;}}@media screen and (max-width:479px){#rec1845164141 .tn-elem[data-elem-id=\"1769609574551\"]{display:table;top:819px;;left:calc(50% - 160px + 19px);;width:282px;height:328px;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845164141\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"721\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"1121\" data-artboard-height-res-480=\"721\" data-artboard-height-res-640=\"721\" data-artboard-height-res-960=\"721\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845164141\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845164141\"><\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609056061' data-elem-id='1769609056061' data-elem-type='text' data-field-top-value=\"130\" data-field-left-value=\"20\" data-field-height-value=\"116\" data-field-width-value=\"656\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"48\" data-field-top-res-320-value=\"131\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"310\" data-field-fontsize-res-320-value=\"36\"> <div class='tn-atom'field='tn_text_1769609056061'><span style=\"font-weight: 600;\">\u0416\u0435\u043d\u0430\u0442\u0438\u043a: <\/span>\u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c, \u0435\u0441\u043b\u0438 \u0442\u0432\u043e\u0439 \u043b\u044e\u0431\u0438\u043c\u044b\u0439 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u0435\u043d<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609375434000002' data-elem-id='1769609375434000002' data-elem-type='text' data-field-top-value=\"344\" data-field-left-value=\"20\" data-field-height-value=\"29\" data-field-width-value=\"584\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"406\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"263\" data-field-fontsize-res-320-value=\"20\"> <div class='tn-atom'field='tn_text_1769609375434000002'>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0430\u043c\u0438, \u0447\u0442\u043e\u0431\u044b \u0442\u044b:<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609334301000001' data-elem-id='1769609334301000001' data-elem-type='text' data-field-top-value=\"266\" data-field-left-value=\"20\" data-field-height-value=\"58\" data-field-width-value=\"584\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"319\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"72\" data-field-width-res-320-value=\"310\" data-field-fontsize-res-320-value=\"20\"> <div class='tn-atom'field='tn_text_1769609334301000001'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442, \u0435\u0441\u043b\u0438 \u0442\u044b&nbsp;\u043f\u043e\u043f\u0430\u043b\u0430 \u0432&nbsp;\u043b\u044e\u0431\u043e\u0432\u043d\u044b\u0439 \u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u0438\u043a \u0438&nbsp;\u0441\u043e\u0432\u0441\u0435\u043c \u0437\u0430\u043f\u0443\u0442\u0430\u043b\u0430\u0441\u044c<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609345108' data-elem-id='1769609345108' data-elem-type='shape' data-field-top-value=\"393\" data-field-left-value=\"370\" data-field-height-value=\"160\" data-field-width-value=\"160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"651\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"80\" data-field-width-res-320-value=\"300\" data-field-container-res-320-value=\"grid\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609292605' data-elem-id='1769609292605' data-elem-type='text' data-field-top-value=\"481\" data-field-left-value=\"385\" data-field-height-value=\"57\" data-field-width-value=\"104\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"672\" data-field-left-res-320-value=\"90\" data-field-width-res-320-value=\"167\"> <div class='tn-atom'field='tn_text_1769609292605'>\u0420\u0430\u0437\u043e\u0431\u0440\u0430\u043b\u0430\u0441\u044c, \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c \u0434\u0430\u043b\u044c\u0448\u0435<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609398205' data-elem-id='1769609398205' data-elem-type='shape' data-field-top-value=\"408\" data-field-left-value=\"465\" data-field-height-value=\"50\" data-field-width-value=\"50\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"666\" data-field-left-res-320-value=\"25\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3566-6335-4933-b963-363466373865\/Mask_group_3.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609495463000009' data-elem-id='1769609495463000009' data-elem-type='shape' data-field-top-value=\"393\" data-field-left-value=\"195\" data-field-height-value=\"160\" data-field-width-value=\"160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"559\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"80\" data-field-width-res-320-value=\"301\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609495463000010' data-elem-id='1769609495463000010' data-elem-type='text' data-field-top-value=\"481\" data-field-left-value=\"210\" data-field-height-value=\"57\" data-field-width-value=\"129\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"580\" data-field-left-res-320-value=\"90\" data-field-width-res-320-value=\"182\"> <div class='tn-atom'field='tn_text_1769609495463000010'>\u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u043b\u0430 \u043d\u0430 \u0441\u0432\u043e\u0438 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609495463000011' data-elem-id='1769609495463000011' data-elem-type='shape' data-field-top-value=\"408\" data-field-left-value=\"290\" data-field-height-value=\"50\" data-field-width-value=\"50\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"574\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"50\" data-field-width-res-320-value=\"50\" data-field-container-res-320-value=\"grid\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3865-3230-4631-b936-323631363534\/Mask_group.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609484533000005' data-elem-id='1769609484533000005' data-elem-type='shape' data-field-top-value=\"393\" data-field-left-value=\"20\" data-field-height-value=\"160\" data-field-width-value=\"160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"470\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"80\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609484533000006' data-elem-id='1769609484533000006' data-elem-type='text' data-field-top-value=\"481\" data-field-left-value=\"35\" data-field-height-value=\"57\" data-field-width-value=\"103\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"491\" data-field-left-res-320-value=\"90\" data-field-width-res-320-value=\"182\"> <div class='tn-atom'field='tn_text_1769609484533000006'>\u0418\u0437\u0431\u0430\u0432\u0438\u043b\u0430\u0441\u044c \u043e\u0442 \u0441\u043b\u0430\u0434\u043a\u0438\u0445 \u0438\u043b\u043b\u044e\u0437\u0438\u0439<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609484533000007' data-elem-id='1769609484533000007' data-elem-type='shape' data-field-top-value=\"408\" data-field-left-value=\"115\" data-field-height-value=\"50\" data-field-width-value=\"50\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"485\" data-field-left-res-320-value=\"25\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6262-3236-4231-b030-336130343530\/Mask_group_1.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609521326' data-elem-id='1769609521326' data-elem-type='button' data-field-top-value=\"583\" data-field-left-value=\"20\" data-field-height-value=\"48\" data-field-width-value=\"209\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"758\" data-field-left-res-320-value=\"10\"> <a class='tn-atom' href=\"https:\/\/sbsite.pro\/\/married_man_1\"> <div class='tn-atom__button-content'> <span class=\"tn-atom__button-text\">\u0417\u0430\u0431\u0440\u0430\u0442\u044c \u0433\u0430\u0439\u0434<\/span> <\/div> <span class=\"tn-atom__button-border\"><\/span> <\/a> <\/div> <div class='t396__elem tn-elem tn-elem__18451641411769609574551' data-elem-id='1769609574551' data-elem-type='shape' data-field-top-value=\"130\" data-field-left-value=\"676\" data-field-height-value=\"591\" data-field-width-value=\"507\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"819\" data-field-left-res-320-value=\"19\" data-field-height-res-320-value=\"328\" data-field-width-res-320-value=\"282\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3561-3738-4538-a136-356261363533\/Rectangle.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845164141');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845338401\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845338401 .t396__artboard {height:339px;background-color:#ffffff;}#rec1845338401 .t396__filter {height:339px;}#rec1845338401 .t396__carrier{height:339px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845338401 .t396__artboard,#rec1845338401 .t396__filter,#rec1845338401 .t396__carrier {height:339px;}#rec1845338401 .t396__filter {}#rec1845338401 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845338401 .t396__artboard,#rec1845338401 .t396__filter,#rec1845338401 .t396__carrier {height:339px;}#rec1845338401 .t396__filter {}#rec1845338401 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845338401 .t396__artboard,#rec1845338401 .t396__filter,#rec1845338401 .t396__carrier {height:339px;}#rec1845338401 .t396__filter {}#rec1845338401 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845338401 .t396__artboard,#rec1845338401 .t396__filter,#rec1845338401 .t396__carrier {height:533px;}#rec1845338401 .t396__filter {}#rec1845338401 .t396__carrier {background-attachment:scroll;}}#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"]{color:#192032;z-index:3;top:100px;;left:calc(50% - 600px + 620px);;width:560px;height:auto;}#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"]{display:table;top:80px;;left:calc(50% - 160px + 10px);;width:300px;height:137px;}#rec1845338401 .tn-elem[data-elem-id=\"1769609655107\"] .tn-atom{vertical-align:middle;white-space:normal;font-size:28px;background-size:cover;}}#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"]{color:#192032;z-index:3;top:247px;;left:calc(50% - 600px + 620px);;width:560px;height:auto;}#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845338401 .tn-elem[data-elem-id=\"1769609670955\"]{display:table;top:237px;;left:calc(50% - 160px + 10px);;width:302px;height:auto;}}#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"]{z-index:3;top:0px;;left:calc(50% - 600px + 20px);;width:459px;height:339px;}#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"]{display:table;}}@media screen and (max-width:959px){#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"]{display:table;}}@media screen and (max-width:639px){#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"]{display:table;}}@media screen and (max-width:479px){#rec1845338401 .tn-elem[data-elem-id=\"1769609853955\"]{display:table;top:284px;;left:calc(50% - 160px + -1px);;width:339px;height:249px;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845338401\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"339\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"533\" data-artboard-height-res-480=\"339\" data-artboard-height-res-640=\"339\" data-artboard-height-res-960=\"339\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845338401\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845338401\"><\/div> <div class='t396__elem tn-elem tn-elem__18453384011769609655107' data-elem-id='1769609655107' data-elem-type='text' data-field-top-value=\"100\" data-field-left-value=\"620\" data-field-height-value=\"129\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"137\" data-field-width-res-320-value=\"300\" data-field-textfit-res-320-value=\"fixedsize\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769609655107'>\u041f\u0440\u0438\u0432\u0435\u0442. \u0422\u044b&nbsp;\u0437\u0434\u0435\u0441\u044c, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043f\u043e\u043f\u0430\u043b\u0430 \u0432&nbsp;\u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441&nbsp;\u0436\u0435\u043d\u0430\u0442\u044b\u043c \u043c\u0443\u0436\u0447\u0438\u043d\u043e\u0439<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453384011769609670955' data-elem-id='1769609670955' data-elem-type='text' data-field-top-value=\"247\" data-field-left-value=\"620\" data-field-height-value=\"38\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"237\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"57\" data-field-width-res-320-value=\"302\"> <div class='tn-atom'field='tn_text_1769609670955'>\u0418\u043d\u043e\u0433\u0434\u0430 \u043e\u043d&nbsp;\u0433\u043e\u0432\u043e\u0440\u0438\u0442: \u00ab\u041f\u043e\u0442\u0435\u0440\u043f\u0438 \u0435\u0449\u0451 \u0447\u0443\u0442\u044c-\u0447\u0443\u0442\u044c, \u0441\u043a\u043e\u0440\u043e \u0443&nbsp;\u043d\u0430\u0441 \u0432\u0441\u0451 \u043d\u0430\u043b\u0430\u0434\u0438\u0442\u0441\u044f\u00bb, \u043d\u043e&nbsp;\u0432\u0441\u0451 \u043e\u0441\u0442\u0430\u0435\u0442\u0441\u044f \u043f\u043e&nbsp;\u043f\u0440\u0435\u0436\u043d\u0435\u043c\u0443:<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453384011769609853955' data-elem-id='1769609853955' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"20\" data-field-height-value=\"339\" data-field-width-value=\"459\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"284\" data-field-left-res-320-value=\"-1\" data-field-height-res-320-value=\"249\" data-field-width-res-320-value=\"339\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3035-3964-4431-b466-333566396661\/image_35_1.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845338401');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845364351\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845364351 .t396__artboard {height:145px;background-color:#ffffff;}#rec1845364351 .t396__filter {height:145px;}#rec1845364351 .t396__carrier{height:145px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845364351 .t396__artboard,#rec1845364351 .t396__filter,#rec1845364351 .t396__carrier {height:145px;}#rec1845364351 .t396__filter {}#rec1845364351 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845364351 .t396__artboard,#rec1845364351 .t396__filter,#rec1845364351 .t396__carrier {height:145px;}#rec1845364351 .t396__filter {}#rec1845364351 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845364351 .t396__artboard,#rec1845364351 .t396__filter,#rec1845364351 .t396__carrier {height:145px;}#rec1845364351 .t396__filter {}#rec1845364351 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845364351 .t396__artboard,#rec1845364351 .t396__filter,#rec1845364351 .t396__carrier {height:205px;}#rec1845364351 .t396__filter {}#rec1845364351 .t396__carrier {background-attachment:scroll;}}#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"]{z-index:3;top:0px;;left:calc(50% - 600px + 1720px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769609949483\"]{display:table;top:0px;;left:calc(50% - 160px + 1465px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1745px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769609984899\"]{display:table;top:25px;;left:calc(50% - 160px + 1490px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1810px);;width:201px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610010155\"]{display:table;top:80px;;left:calc(50% - 160px + 1490px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"]{z-index:3;top:80px;;left:calc(50% - 600px + 1745px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:0.000% 0.000%;background-size:100.000%;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610048988\"]{display:table;top:25px;;left:calc(50% - 160px + 1676px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"]{z-index:3;top:0px;;left:calc(50% - 600px + 1380px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000008\"]{display:table;top:0px;;left:calc(50% - 160px + 1174px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1405px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000009\"]{display:table;top:25px;;left:calc(50% - 160px + 1199px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1470px);;width:199px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000010\"]{display:table;top:80px;;left:calc(50% - 160px + 1199px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"]{z-index:3;top:80px;;left:calc(50% - 600px + 1405px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:0.000% 0.000%;background-size:100.000%;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610152518000011\"]{display:table;top:25px;;left:calc(50% - 160px + 1385px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"]{z-index:3;top:0px;;left:calc(50% - 600px + 2060px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000003\"]{display:table;top:0px;;left:calc(50% - 160px + 1756px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 2085px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000004\"]{display:table;top:25px;;left:calc(50% - 160px + 1781px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 2150px);;width:224px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610196424000012\"]{display:table;top:80px;;left:calc(50% - 160px + 1781px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"]{z-index:3;top:80px;;left:calc(50% - 600px + 2085px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610109507000006\"]{display:table;top:25px;;left:calc(50% - 160px + 1967px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"]{z-index:3;top:0px;;left:calc(50% - 600px + 1040px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000029\"]{display:table;top:0px;;left:calc(50% - 160px + 883px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1065px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000030\"]{display:table;top:25px;;left:calc(50% - 160px + 908px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 1130px);;width:224px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000031\"]{display:table;top:80px;;left:calc(50% - 160px + 908px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"]{z-index:3;top:80px;;left:calc(50% - 600px + 1065px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610208406000032\"]{display:table;top:25px;;left:calc(50% - 160px + 1094px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"]{z-index:3;top:0px;;left:calc(50% - 600px + 700px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000014\"]{display:table;top:0px;;left:calc(50% - 160px + 592px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 725px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000015\"]{display:table;top:25px;;left:calc(50% - 160px + 617px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 790px);;width:219px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000016\"]{display:table;top:81px;;left:calc(50% - 160px + 617px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"]{z-index:3;top:80px;;left:calc(50% - 600px + 725px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:0.000% 0.000%;background-size:100.000%;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000017\"]{display:table;top:25px;;left:calc(50% - 160px + 803px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"]{z-index:3;top:0px;;left:calc(50% - 600px + 360px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000019\"]{display:table;top:0px;;left:calc(50% - 160px + 301px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 385px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000020\"]{display:table;top:25px;;left:calc(50% - 160px + 326px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 450px);;width:224px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199932000021\"]{display:table;top:81px;;left:calc(50% - 160px + 326px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"]{z-index:3;top:80px;;left:calc(50% - 600px + 385px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:0.000% 0.000%;background-size:100.000%;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000022\"]{display:table;top:25px;;left:calc(50% - 160px + 512px);;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"]{z-index:3;top:0px;;left:calc(50% - 600px + 20px);;width:320px;height:145px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#eef5f6;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000024\"]{display:table;top:0px;;left:calc(50% - 160px + 10px);;width:276px;height:197px;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 45px);;width:auto;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000025\"]{display:table;top:25px;;left:calc(50% - 160px + 35px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"]{color:#192032;z-index:3;top:25px;;left:calc(50% - 600px + 110px);;width:224px;height:auto;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000026\"]{display:table;top:81px;;left:calc(50% - 160px + 35px);;height:auto;}}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"]{z-index:3;top:80px;;left:calc(50% - 600px + 45px);;width:40px;height:40px;}#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"]{display:table;}}@media screen and (max-width:959px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"]{display:table;}}@media screen and (max-width:639px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"]{display:table;}}@media screen and (max-width:479px){#rec1845364351 .tn-elem[data-elem-id=\"1769610199933000027\"]{display:table;top:25px;;left:calc(50% - 160px + 221px);;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845364351\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"145\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"205\" data-artboard-height-res-480=\"145\" data-artboard-height-res-640=\"145\" data-artboard-height-res-960=\"145\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845364351\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845364351\"><\/div> <div class='t396__elem tn-elem tn-elem__18453643511769609949483' data-elem-id='1769609949483' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"1720\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"1465\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769609984899' data-elem-id='1769609984899' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1745\" data-field-height-value=\"43\" data-field-width-value=\"42\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1490\"> <div class='tn-atom'field='tn_text_1769609984899'>06<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610010155' data-elem-id='1769610010155' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1810\" data-field-height-value=\"38\" data-field-width-value=\"201\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"1490\"> <div class='tn-atom'field='tn_text_1769610010155'>\u0422\u044b \u0442\u0430\u043a \u0440\u0435\u0434\u043a\u043e \u043e\u0449\u0443\u0449\u0430\u0435\u0448\u044c \u0441\u0435\u0431\u044f \u043b\u044e\u0431\u0438\u043c\u043e\u0439 \u0438 \u0432\u0430\u0436\u043d\u043e\u0439<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610048988' data-elem-id='1769610048988' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"1745\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1676\"> <div class='tn-atom t-bgimg' style=\"background-image:url('https:\/\/static.tildacdn.com\/tild6561-6430-4430-b936-363836663236\/Star_1.png');\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610152518000008' data-elem-id='1769610152518000008' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"1380\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"1174\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610152518000009' data-elem-id='1769610152518000009' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1405\" data-field-height-value=\"43\" data-field-width-value=\"42\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1199\"> <div class='tn-atom'field='tn_text_1769610152518000009'>05<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610152518000010' data-elem-id='1769610152518000010' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1470\" data-field-height-value=\"38\" data-field-width-value=\"199\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"1199\"> <div class='tn-atom'field='tn_text_1769610152518000010'>\u0413\u0430\u0434\u0430\u0435\u0448\u044c, \u0441\u043a\u043e\u043b\u044c\u043a\u043e \u0443 \u043d\u0435\u0433\u043e \u0435\u0449\u0435 \u0442\u0430\u043a\u0438\u0445 \u0436\u0435 \u043a\u0430\u043a \u0442\u044b<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610152518000011' data-elem-id='1769610152518000011' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"1405\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1385\"> <div class='tn-atom t-bgimg' style=\"background-image:url('https:\/\/static.tildacdn.com\/tild3765-6566-4363-b333-393734633333\/Group_2085661159.png');\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610109507000003' data-elem-id='1769610109507000003' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"2060\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"1756\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610109507000004' data-elem-id='1769610109507000004' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"2085\" data-field-height-value=\"43\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1781\"> <div class='tn-atom'field='tn_text_1769610109507000004'>07<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610196424000012' data-elem-id='1769610196424000012' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"2150\" data-field-height-value=\"38\" data-field-width-value=\"224\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"1781\"> <div class='tn-atom'field='tn_text_1769610196424000012'>\u0427\u0443\u0432\u0441\u0442\u0432\u0443\u0435\u0448\u044c, \u0447\u0442\u043e \u044d\u0442\u0438 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0442\u0435\u0431\u044f \u0432\u044b\u043c\u043e\u0442\u0430\u043b\u0438<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610109507000006' data-elem-id='1769610109507000006' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"2085\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1967\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6331-6439-4232-a261-386663346265\/Group_4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610208406000029' data-elem-id='1769610208406000029' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"1040\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"883\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610208406000030' data-elem-id='1769610208406000030' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1065\" data-field-height-value=\"43\" data-field-width-value=\"44\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"908\"> <div class='tn-atom'field='tn_text_1769610208406000030'>04<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610208406000031' data-elem-id='1769610208406000031' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"1130\" data-field-height-value=\"38\" data-field-width-value=\"224\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"908\"> <div class='tn-atom'field='tn_text_1769610208406000031'>\u041a\u043e\u0433\u0434\u0430 \u043e\u043d \u0432 \u0442\u0435\u043b\u0435\u0444\u043e\u043d\u0435, \u0442\u044b \u0434\u0443\u043c\u0430\u0435\u0448\u044c, \u0447\u0442\u043e \u043f\u0438\u0448\u0435\u0442 \u0436\u0435\u043d\u0435<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610208406000032' data-elem-id='1769610208406000032' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"1065\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"1094\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6331-6439-4232-a261-386663346265\/Group_4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000014' data-elem-id='1769610199932000014' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"700\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"592\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000015' data-elem-id='1769610199932000015' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"725\" data-field-height-value=\"43\" data-field-width-value=\"41\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"617\"> <div class='tn-atom'field='tn_text_1769610199932000015'>03<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000016' data-elem-id='1769610199932000016' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"790\" data-field-height-value=\"95\" data-field-width-value=\"219\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"81\" data-field-left-res-320-value=\"617\"> <div class='tn-atom'field='tn_text_1769610199932000016'>\u041e\u043d&nbsp;\u0441\u0440\u044b\u0432\u0430\u0435\u0442\u0441\u044f, \u0435\u0441\u043b\u0438 \u0434\u0435\u043b\u0430\u0435\u0448\u044c \u0447\u0442\u043e-\u0442\u043e \u0431\u0435\u0437 \u0441\u043e\u0433\u043b\u0430\u0441\u043e\u0432\u0430\u043d\u0438\u044f: \u043f\u0440\u0438\u0435\u0437\u0436\u0430\u0435\u0448\u044c \u043a&nbsp;\u043d\u0435\u043c\u0443 \u043d\u0430&nbsp;\u0440\u0430\u0431\u043e\u0442\u0443 \u0438\u043b\u0438 \u0434\u0435\u043b\u0430\u0435\u0448\u044c \u0441\u044e\u0440\u043f\u0440\u0438\u0437<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000017' data-elem-id='1769610199932000017' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"725\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"803\"> <div class='tn-atom t-bgimg' style=\"background-image:url('https:\/\/static.tildacdn.com\/tild6561-6430-4430-b936-363836663236\/Star_1.png');\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000019' data-elem-id='1769610199932000019' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"360\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"301\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000020' data-elem-id='1769610199932000020' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"385\" data-field-height-value=\"43\" data-field-width-value=\"41\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"326\"> <div class='tn-atom'field='tn_text_1769610199932000020'>02<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199932000021' data-elem-id='1769610199932000021' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"450\" data-field-height-value=\"57\" data-field-width-value=\"224\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"81\" data-field-left-res-320-value=\"326\"> <div class='tn-atom'field='tn_text_1769610199932000021'>\u0422\u044b \u0437\u0430\u043f\u0438\u0441\u0430\u043d\u0430 \u0443 \u043d\u0435\u0433\u043e \u0432 \u0442\u0435\u043b\u0435\u0444\u043e\u043d\u0435 \u043a\u0430\u043a \u00ab\u0421\u0435\u0440\u0433\u0435\u0439 \u0420\u0430\u0431\u043e\u0442\u0430\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199933000022' data-elem-id='1769610199933000022' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"385\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"512\"> <div class='tn-atom t-bgimg' style=\"background-image:url('https:\/\/static.tildacdn.com\/tild3765-6566-4363-b333-393734633333\/Group_2085661159.png');\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199933000024' data-elem-id='1769610199933000024' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"20\" data-field-height-value=\"145\" data-field-width-value=\"320\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"276\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199933000025' data-elem-id='1769610199933000025' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"45\" data-field-height-value=\"43\" data-field-width-value=\"34\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"35\"> <div class='tn-atom'field='tn_text_1769610199933000025'>01<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199933000026' data-elem-id='1769610199933000026' data-elem-type='text' data-field-top-value=\"25\" data-field-left-value=\"110\" data-field-height-value=\"95\" data-field-width-value=\"224\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"81\" data-field-left-res-320-value=\"35\"> <div class='tn-atom'field='tn_text_1769610199933000026'>\u041e\u043d&nbsp;\u043f\u043e\u0441\u0442\u043e\u044f\u043d\u043d\u043e \u0433\u043e\u0432\u043e\u0440\u0438\u0442, \u0447\u0442\u043e&nbsp;\u0442\u044b&nbsp;\u0443&nbsp;\u043d\u0435\u0433\u043e \u043e\u0434\u043d\u0430, \u0430&nbsp;\u0441&nbsp;\u0436\u0435\u043d\u043e\u0439 \u043e\u043d\u0438&nbsp;\u0436\u0438\u0432\u0443\u0442 \u043a\u0430\u043a&nbsp;\u0441\u043e\u0441\u0435\u0434\u0438. \u041d\u043e&nbsp;\u0432&nbsp;\u043c\u043e\u043c\u0435\u043d\u0442\u044b \u043a\u0440\u0438\u0437\u0438\u0441\u043e\u0432 \u043e\u043d&nbsp;\u0443\u0445\u043e\u0434\u0438\u0442 \u043a&nbsp;\u043d\u0435\u0439.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18453643511769610199933000027' data-elem-id='1769610199933000027' data-elem-type='shape' data-field-top-value=\"80\" data-field-left-value=\"45\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"221\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6331-6439-4232-a261-386663346265\/Group_4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845364351');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845434781\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"131\"> <!-- T123 --> <div class=\"t123\"> <div class=\"t-container_100\"> <div class=\"t-width t-width_100\"> <!-- nominify begin --> <script>\ndocument.addEventListener('DOMContentLoaded', function () {\n    \n    let pos = { top: 0, left: 0, x: 0, y: 0 };\n    let blocks = ['#rec1845364351'];\n    \n    blocks.forEach((elem) => {\n        elem = document.querySelector(elem + \" .t396__artboard\");\n        if (elem.querySelector(\"img\") !== null) {\n            elem.querySelector(\"img\").ondragstart = function() { return false; };\n        };\n        elem.style.overflowX = 'auto';\n        elem.style.overflowY = 'hidden';\n        elem.querySelector('.t396__carrier').style.position = 'sticky';\n        elem.style.cursor = 'grab';\n        const mouseDownHandler = function (e) {\n            elem.style.cursor = 'grabbing';\n            elem.style.userSelect = 'none';\n            pos = {\n                left: elem.scrollLeft,\n                x: e.clientX,\n            };\n            document.addEventListener('mousemove', mouseMoveHandler);\n            document.addEventListener('mouseup', mouseUpHandler);\n        };\n        const mouseMoveHandler = function (e) {\n            const dx = e.clientX - pos.x;\n            elem.scrollLeft = pos.left - dx;\n        };\n        const mouseUpHandler = function () {\n            elem.style.cursor = 'grab';\n            elem.style.removeProperty('user-select');\n    \n            document.removeEventListener('mousemove', mouseMoveHandler);\n            document.removeEventListener('mouseup', mouseUpHandler);\n        };\n        elem.addEventListener('mousedown', mouseDownHandler);\n        \n    function scrollHorizontally(e) {\n      e = window.event;\n      var delta = Math.max(-1, Math.min(1, (-(e.deltaY) || 0)));\n      elem.scrollLeft -= (delta * 40);\n    if((delta > 0 && elem.scrollLeft > 0) || (delta < 0 && elem.offsetWidth+elem.scrollLeft < elem.scrollWidth)) {\n        e.preventDefault();\n    };\n  };\n  elem.addEventListener('wheel', scrollHorizontally, false);\n    });\n    \n});\n<\/script> <style>\n   #rec1845364351 .t396__artboard::-webkit-scrollbar {\n      display: none;\n  }\n  #rec1845364351 .t396__artboard {\n      scrollbar-width: none;\n  }\n<\/style> <!-- nominify end --> <\/div> <\/div> <\/div> <\/div> <div id=\"rec1845446331\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845446331 .t396__artboard {height:911px;background-color:#ffffff;}#rec1845446331 .t396__filter {height:911px;}#rec1845446331 .t396__carrier{height:911px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845446331 .t396__artboard,#rec1845446331 .t396__filter,#rec1845446331 .t396__carrier {height:911px;}#rec1845446331 .t396__filter {}#rec1845446331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845446331 .t396__artboard,#rec1845446331 .t396__filter,#rec1845446331 .t396__carrier {height:911px;}#rec1845446331 .t396__filter {}#rec1845446331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845446331 .t396__artboard,#rec1845446331 .t396__filter,#rec1845446331 .t396__carrier {height:911px;}#rec1845446331 .t396__filter {}#rec1845446331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845446331 .t396__artboard,#rec1845446331 .t396__filter,#rec1845446331 .t396__carrier {height:2011px;}#rec1845446331 .t396__filter {}#rec1845446331 .t396__carrier {background-attachment:scroll;}}#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"]{color:#192032;text-align:center;z-index:3;top:80px;;left:calc(50% - 600px + 320px);;width:560px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"]{display:table;left:calc(50% - 160px + 0px);;width:320px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769610788450000001\"] .tn-atom{font-size:28px;background-size:cover;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"]{z-index:3;top:218px;;left:calc(50% - 600px + 447px);;width:317px;height:449px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611363090\"]{display:table;top:173px;;left:calc(50% - 160px + 19px);;width:283px;height:402px;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"]{z-index:3;top:627px;;left:calc(50% - 600px + 297px);;width:190px;height:61px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611476874\"]{display:table;top:-163px;;left:calc(50% - 160px + 151px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"]{z-index:3;top:626px;;left:calc(50% - 600px + 738px);;width:156px;height:84px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611846381000005\"]{display:table;top:-186px;;left:calc(50% - 160px + 254px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"]{z-index:3;top:474px;;left:calc(50% - 600px + 738px);;width:124px;height:37px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612279591000005\"]{display:table;top:-338px;;left:calc(50% - 160px + 254px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"]{z-index:3;top:287px;;left:calc(50% - 600px + 714px);;width:190px;height:82px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612161257000023\"]{display:table;top:-525px;;left:calc(50% - 160px + 230px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"]{z-index:3;top:287px;;left:calc(50% - 600px + 296px);;width:190px;height:82px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612088779000015\"]{display:table;top:-503px;;left:calc(50% - 160px + 150px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"]{z-index:3;top:610px;;left:calc(50% - 600px + 20px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611418746\"]{display:table;top:1007px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"]{z-index:3;top:685px;;left:calc(50% - 600px + 20px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611443322\"]{display:table;top:1082px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"]{color:#192032;z-index:3;top:706px;;left:calc(50% - 600px + 20px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611773618\"]{display:table;top:1103px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"]{z-index:3;top:456px;;left:calc(50% - 600px + 333px);;width:136px;height:38px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000009\"]{display:table;top:-334px;;left:calc(50% - 160px + 187px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"]{z-index:3;top:418px;;left:calc(50% - 600px + 56px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000007\"]{display:table;top:813px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"]{z-index:3;top:493px;;left:calc(50% - 600px + 56px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000008\"]{display:table;top:888px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"]{color:#192032;z-index:3;top:514px;;left:calc(50% - 600px + 56px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611929818000010\"]{display:table;top:909px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"]{z-index:3;top:435px;;left:calc(50% - 600px + 862px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000017\"]{display:table;top:1453px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"]{z-index:3;top:510px;;left:calc(50% - 600px + 862px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000018\"]{display:table;top:1528px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"]{color:#192032;z-index:3;top:531px;;left:calc(50% - 600px + 862px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612141395000019\"]{display:table;top:1549px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"]{z-index:3;top:629px;;left:calc(50% - 600px + 894px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000020\"]{display:table;top:1647px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"]{z-index:3;top:704px;;left:calc(50% - 600px + 894px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000021\"]{display:table;top:1722px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"]{color:#192032;z-index:3;top:725px;;left:calc(50% - 600px + 894px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612156428000022\"]{display:table;top:1743px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"]{z-index:3;top:212px;;left:calc(50% - 600px + 897px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000002\"]{display:table;top:1230px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"]{z-index:3;top:287px;;left:calc(50% - 600px + 897px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000003\"]{display:table;top:1305px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"]{color:#192032;z-index:3;top:308px;;left:calc(50% - 600px + 897px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612272960000004\"]{display:table;top:1326px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"]{z-index:3;top:212px;;left:calc(50% - 600px + 20px);;width:54px;height:54px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000012\"]{display:table;top:619px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"]{z-index:3;top:287px;;left:calc(50% - 600px + 20px);;width:276px;height:1px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000013\"]{display:table;top:694px;;left:calc(50% - 160px + 10px);;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"]{color:#192032;z-index:3;top:308px;;left:calc(50% - 600px + 20px);;width:286px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611973595000014\"]{display:table;top:715px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"]{z-index:3;top:622px;;left:calc(50% - 600px + 486px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611809801\"]{display:table;top:-78px;;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"]{z-index:3;top:450px;;left:calc(50% - 600px + 469px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611951602000011\"]{display:table;top:-250px;;}}#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"]{z-index:3;top:626px;;left:calc(50% - 600px + 738px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769611879342000006\"]{display:table;top:-74px;;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"]{z-index:3;top:470px;;left:calc(50% - 600px + 736px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612300958000006\"]{display:table;top:-230px;;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"]{z-index:3;top:364px;;left:calc(50% - 600px + 712px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612234051000001\"]{display:table;top:-336px;;}}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"]{color:#ffffff;text-align:center;z-index:3;top:709px;;left:calc(50% - 600px + 496px);;width:209px;height:42px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom{color:#ffffff;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.55;font-weight:600;border-radius:30px 30px 30px 30px;background-position:center center;--t396-speedhover:0.2s;transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-bgcolor-color:#3f89c4;--t396-bgcolor-image:none;--t396-bgcolor-hover-color:#20649a;--t396-bgcolor-hover-image:none;background-color:var(--t396-bgcolor-color,transparent);-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom::after{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-content{column-gap:10px;padding:0px 0px 0px 0px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-text{transition:color var(--t396-speedhover,0s) ease-in-out;color:#ffffff;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover::after{opacity:0;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{color:#ffffff;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover .tn-atom__button-text{color:#ffffff;}}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"]{display:block;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom::after{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover::after{opacity:0;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"]{display:block;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom::after{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover::after{opacity:0;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"]{display:block;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom::after{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover::after{opacity:0;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"]{display:block;top:1865px;;left:calc(50% - 160px + 10px);;width:299px;height:auto;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom::after{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover::after{opacity:0;}#rec1845446331 .tn-elem[data-elem-id=\"1769612394048000001\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"]{z-index:3;top:365px;;left:calc(50% - 600px + 486px);;width:10px;height:10px;}#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"]{display:table;}}@media screen and (max-width:959px){#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"]{display:table;}}@media screen and (max-width:639px){#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"]{display:table;}}@media screen and (max-width:479px){#rec1845446331 .tn-elem[data-elem-id=\"1769612101443000016\"]{display:table;top:-335px;;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845446331\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"911\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"2011\" data-artboard-height-res-480=\"911\" data-artboard-height-res-640=\"911\" data-artboard-height-res-960=\"911\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845446331\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845446331\"><\/div> <div class='t396__elem tn-elem tn-elem__18454463311769610788450000001' data-elem-id='1769610788450000001' data-elem-type='text' data-field-top-value=\"80\" data-field-left-value=\"320\" data-field-height-value=\"86\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"0\" data-field-width-res-320-value=\"320\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769610788450000001'>\u0413\u0430\u0439\u0434 \u0416\u0435\u043d\u0430\u0442\u0438\u043a \u043f\u043e\u043c\u043e\u0436\u0435\u0442 \u0440\u0430\u0437\u043e\u0431\u0440\u0430\u0442\u044c\u0441\u044f \u0432 \u0441\u0435\u0431\u0435:<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611363090' data-elem-id='1769611363090' data-elem-type='shape' data-field-top-value=\"218\" data-field-left-value=\"447\" data-field-height-value=\"449\" data-field-width-value=\"317\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"173\" data-field-left-res-320-value=\"19\" data-field-height-res-320-value=\"402\" data-field-width-res-320-value=\"283\" data-field-container-res-320-value=\"grid\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3631-6635-4164-a437-623335383634\/57736.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611476874' data-elem-id='1769611476874' data-elem-type='shape' data-field-top-value=\"627\" data-field-left-value=\"297\" data-field-height-value=\"61\" data-field-width-value=\"190\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-163\" data-field-left-res-320-value=\"151\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3466-3536-4266-a531-316334373765\/3.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611846381000005' data-elem-id='1769611846381000005' data-elem-type='shape' data-field-top-value=\"626\" data-field-left-value=\"738\" data-field-height-value=\"84\" data-field-width-value=\"156\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-186\" data-field-left-res-320-value=\"254\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3863-6438-4462-b736-346236643463\/6.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612279591000005' data-elem-id='1769612279591000005' data-elem-type='shape' data-field-top-value=\"474\" data-field-left-value=\"738\" data-field-height-value=\"37\" data-field-width-value=\"124\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-338\" data-field-left-res-320-value=\"254\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6436-6364-4965-a231-376564343063\/5.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612161257000023' data-elem-id='1769612161257000023' data-elem-type='shape' data-field-top-value=\"287\" data-field-left-value=\"714\" data-field-height-value=\"82\" data-field-width-value=\"190\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-525\" data-field-left-res-320-value=\"230\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3639-6637-4465-b539-386263346636\/4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612088779000015' data-elem-id='1769612088779000015' data-elem-type='shape' data-field-top-value=\"287\" data-field-left-value=\"296\" data-field-height-value=\"82\" data-field-width-value=\"190\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-503\" data-field-left-res-320-value=\"150\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3562-3665-4730-a435-396163306237\/1.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611418746' data-elem-id='1769611418746' data-elem-type='shape' data-field-top-value=\"610\" data-field-left-value=\"20\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1007\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6266-3964-4465-a235-343839343566\/Frame_6.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611443322' data-elem-id='1769611443322' data-elem-type='shape' data-field-top-value=\"685\" data-field-left-value=\"20\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1082\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611773618' data-elem-id='1769611773618' data-elem-type='text' data-field-top-value=\"706\" data-field-left-value=\"20\" data-field-height-value=\"87\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"1103\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769611773618'>\u042d\u043a\u043e\u043b\u043e\u0433\u0438\u0447\u043d\u043e \u043f\u0440\u043e\u0436\u0438\u0442\u044c \u0441\u0432\u043e\u0438 \u044d\u043c\u043e\u0446\u0438\u0438 \u0438 \u043f\u043e\u043d\u044f\u0442\u044c, \u0447\u0442\u043e \u043e\u043d\u0438 \u043e\u0437\u043d\u0430\u0447\u0430\u044e\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611929818000009' data-elem-id='1769611929818000009' data-elem-type='shape' data-field-top-value=\"456\" data-field-left-value=\"333\" data-field-height-value=\"38\" data-field-width-value=\"136\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-334\" data-field-left-res-320-value=\"187\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3962-6231-4832-b465-326539323034\/2.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611929818000007' data-elem-id='1769611929818000007' data-elem-type='shape' data-field-top-value=\"418\" data-field-left-value=\"56\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"813\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6164-3036-4635-a535-323963376434\/Frame_5.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611929818000008' data-elem-id='1769611929818000008' data-elem-type='shape' data-field-top-value=\"493\" data-field-left-value=\"56\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"888\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611929818000010' data-elem-id='1769611929818000010' data-elem-type='text' data-field-top-value=\"514\" data-field-left-value=\"56\" data-field-height-value=\"58\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"909\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769611929818000010'>\u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430 \u0441\u0432\u043e\u0438 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612141395000017' data-elem-id='1769612141395000017' data-elem-type='shape' data-field-top-value=\"435\" data-field-left-value=\"862\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1453\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3735-3031-4236-a632-613036623830\/Frame_8.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612141395000018' data-elem-id='1769612141395000018' data-elem-type='shape' data-field-top-value=\"510\" data-field-left-value=\"862\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1528\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612141395000019' data-elem-id='1769612141395000019' data-elem-type='text' data-field-top-value=\"531\" data-field-left-value=\"862\" data-field-height-value=\"58\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"1549\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769612141395000019'>\u041e\u0441\u043e\u0437\u043d\u0430\u043d\u043d\u043e \u0440\u0435\u0448\u0438\u0442\u044c, \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c \u0434\u0430\u043b\u044c\u0448\u0435<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612156428000020' data-elem-id='1769612156428000020' data-elem-type='shape' data-field-top-value=\"629\" data-field-left-value=\"894\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1647\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3562-6161-4063-b230-386331363566\/Frame_9.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612156428000021' data-elem-id='1769612156428000021' data-elem-type='shape' data-field-top-value=\"704\" data-field-left-value=\"894\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1722\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612156428000022' data-elem-id='1769612156428000022' data-elem-type='text' data-field-top-value=\"725\" data-field-left-value=\"894\" data-field-height-value=\"87\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"1743\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769612156428000022'>\u0421\u0434\u0435\u043b\u0430\u0442\u044c \u0432\u044b\u0432\u043e\u0434\u044b&nbsp;\u2014 \u043a\u0430\u043a \u0438&nbsp;\u043f\u043e\u0447\u0435\u043c\u0443 \u0442\u044b&nbsp;\u0432&nbsp;\u0442\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445 \u043e\u043a\u0430\u0437\u0430\u043b\u0430\u0441\u044c<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612272960000002' data-elem-id='1769612272960000002' data-elem-type='shape' data-field-top-value=\"212\" data-field-left-value=\"897\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1230\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3936-3666-4630-a430-316264616562\/Frame_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612272960000003' data-elem-id='1769612272960000003' data-elem-type='shape' data-field-top-value=\"287\" data-field-left-value=\"897\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1305\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612272960000004' data-elem-id='1769612272960000004' data-elem-type='text' data-field-top-value=\"308\" data-field-left-value=\"897\" data-field-height-value=\"87\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"1326\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769612272960000004'>\u041f\u043e\u043d\u044f\u0442\u044c, \u0447\u0442\u043e \u043d\u0430 \u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u043c\u0435\u0436\u0434\u0443 \u0432\u0430\u043c\u0438 \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0434\u0438\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611973595000012' data-elem-id='1769611973595000012' data-elem-type='shape' data-field-top-value=\"212\" data-field-left-value=\"20\" data-field-height-value=\"54\" data-field-width-value=\"54\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"619\" data-field-left-res-320-value=\"10\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3838-3039-4365-a662-323235393763\/Frame_4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611973595000013' data-elem-id='1769611973595000013' data-elem-type='shape' data-field-top-value=\"287\" data-field-left-value=\"20\" data-field-height-value=\"1\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"694\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611973595000014' data-elem-id='1769611973595000014' data-elem-type='text' data-field-top-value=\"308\" data-field-left-value=\"20\" data-field-height-value=\"58\" data-field-width-value=\"286\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"715\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769611973595000014'>\u041f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u043e\u043f\u043e\u0440\u0443 \u043f\u043e\u0434 \u043d\u043e\u0433\u0430\u043c\u0438<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611809801' data-elem-id='1769611809801' data-elem-type='shape' data-field-top-value=\"622\" data-field-left-value=\"486\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-78\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611951602000011' data-elem-id='1769611951602000011' data-elem-type='shape' data-field-top-value=\"450\" data-field-left-value=\"469\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-250\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769611879342000006' data-elem-id='1769611879342000006' data-elem-type='shape' data-field-top-value=\"626\" data-field-left-value=\"738\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-74\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612300958000006' data-elem-id='1769612300958000006' data-elem-type='shape' data-field-top-value=\"470\" data-field-left-value=\"736\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-230\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612234051000001' data-elem-id='1769612234051000001' data-elem-type='shape' data-field-top-value=\"364\" data-field-left-value=\"712\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-336\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612394048000001' data-elem-id='1769612394048000001' data-elem-type='button' data-field-top-value=\"709\" data-field-left-value=\"496\" data-field-height-value=\"42\" data-field-width-value=\"209\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"1865\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"52\" data-field-width-res-320-value=\"299\"> <a class='tn-atom' href=\"https:\/\/sbsite.pro\/\/married_man_1\"> <div class='tn-atom__button-content'> <span class=\"tn-atom__button-text\">\u0417\u0430\u0431\u0440\u0430\u0442\u044c \u0433\u0430\u0439\u0434<\/span> <\/div> <span class=\"tn-atom__button-border\"><\/span> <\/a> <\/div> <div class='t396__elem tn-elem tn-elem__18454463311769612101443000016' data-elem-id='1769612101443000016' data-elem-type='shape' data-field-top-value=\"365\" data-field-left-value=\"486\" data-field-height-value=\"10\" data-field-width-value=\"10\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"-335\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3034-6239-4138-b139-653231336666\/Ellipse_7.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845446331');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845616441\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845616441 .t396__artboard {height:717px;background-color:#eef5f6;}#rec1845616441 .t396__filter {height:717px;}#rec1845616441 .t396__carrier{height:717px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845616441 .t396__artboard,#rec1845616441 .t396__filter,#rec1845616441 .t396__carrier {height:717px;}#rec1845616441 .t396__filter {}#rec1845616441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845616441 .t396__artboard,#rec1845616441 .t396__filter,#rec1845616441 .t396__carrier {height:717px;}#rec1845616441 .t396__filter {}#rec1845616441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845616441 .t396__artboard,#rec1845616441 .t396__filter,#rec1845616441 .t396__carrier {height:717px;}#rec1845616441 .t396__filter {}#rec1845616441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845616441 .t396__artboard,#rec1845616441 .t396__filter,#rec1845616441 .t396__carrier {height:1298px;}#rec1845616441 .t396__filter {}#rec1845616441 .t396__carrier {background-attachment:scroll;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"]{color:#192032;text-align:center;z-index:3;top:80px;;left:calc(50% - 600px + 179px);;width:842px;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"]{display:table;left:calc(50% - 160px + 0px);;width:320px;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613016544\"] .tn-atom{font-size:28px;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"]{z-index:3;top:533px;;left:calc(50% - 600px + 620px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#c7e1e5;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613523200\"]{display:table;top:1085px;;left:calc(50% - 160px + 10px);;width:299px;height:133px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"]{color:#000000;z-index:3;top:563px;;left:calc(50% - 600px + 650px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"]{display:table;top:1115px;;left:calc(50% - 160px + 40px);;width:243px;height:72px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613593320\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"]{z-index:3;top:424px;;left:calc(50% - 600px + 620px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#c7e1e5;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000007\"]{display:table;top:839px;;left:calc(50% - 160px + 10px);;width:300px;height:132px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"]{color:#000000;z-index:3;top:442px;;left:calc(50% - 600px + 650px);;width:476px;height:48px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"] .tn-atom{vertical-align:middle;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"]{display:table;top:869px;;left:calc(50% - 160px + 31px);;width:259px;height:72px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613634716000008\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"]{z-index:3;top:315px;;left:calc(50% - 600px + 620px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#c7e1e5;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000005\"]{display:table;top:592px;;left:calc(50% - 160px + 10px);;width:300px;height:108px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"]{color:#000000;z-index:3;top:345px;;left:calc(50% - 600px + 650px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"]{display:table;top:622px;;left:calc(50% - 160px + 40px);;width:242px;height:48px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613629637000006\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"]{z-index:3;top:206px;;left:calc(50% - 600px + 620px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#c7e1e5;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000003\"]{display:table;top:346px;;left:calc(50% - 160px + 10px);;width:300px;height:107px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"]{color:#000000;z-index:3;top:236px;;left:calc(50% - 600px + 650px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"]{display:table;top:376px;;left:calc(50% - 160px + 62px);;width:192px;height:48px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613621565000004\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"]{z-index:3;top:533px;;left:calc(50% - 600px + 20px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000009\"]{display:table;top:986px;;left:calc(50% - 160px + 10px);;width:300px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"]{color:#000000;z-index:3;top:563px;;left:calc(50% - 600px + 50px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"]{display:table;top:1016px;;left:calc(50% - 160px + 61px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000010\"] .tn-atom{vertical-align:middle;white-space:nowrap;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"]{z-index:3;top:424px;;left:calc(50% - 600px + 20px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000011\"]{display:table;top:715px;;left:calc(50% - 160px + 10px);;width:300px;height:109px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"]{color:#000000;z-index:3;top:454px;;left:calc(50% - 600px + 50px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"]{display:table;top:745px;;left:calc(50% - 160px + 40px);;width:239px;height:48px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000012\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"]{z-index:3;top:315px;;left:calc(50% - 600px + 20px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000013\"]{display:table;top:468px;;left:calc(50% - 160px + 10px);;width:300px;height:109px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"]{color:#000000;z-index:3;top:345px;;left:calc(50% - 600px + 50px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"]{display:table;top:498px;;left:calc(50% - 160px + 40px);;width:242px;height:48px;text-align:center;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000014\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"]{z-index:3;top:206px;;left:calc(50% - 600px + 20px);;width:560px;height:84px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000015\"]{display:table;top:246px;;left:calc(50% - 160px + 10px);;width:301px;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"]{color:#000000;z-index:3;top:236px;;left:calc(50% - 600px + 50px);;width:auto;height:auto;}#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#000000;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613665734000016\"]{display:table;top:276px;;left:calc(50% - 160px + 40px);;height:auto;text-align:center;}}#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"]{z-index:3;top:588px;;left:calc(50% - 600px + 555px);;width:102px;height:29px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"]{display:table;top:1070px;;left:calc(50% - 160px + 10px);;width:58px;height:17px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613727328\"] .tn-atom{background-size:cover;-webkit-transform:rotate(54deg);-moz-transform:rotate(54deg);transform:rotate(54deg);}}#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"]{z-index:3;top:479px;;left:calc(50% - 600px + 555px);;width:102px;height:29px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"]{display:table;top:824px;;left:calc(50% - 160px + 7px);;width:58px;height:17px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613760661000019\"] .tn-atom{background-size:cover;-webkit-transform:rotate(55deg);-moz-transform:rotate(55deg);transform:rotate(55deg);}}#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"]{z-index:3;top:379px;;left:calc(50% - 600px + 555px);;width:102px;height:29px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"]{display:table;top:577px;;left:calc(50% - 160px + 10px);;width:58px;height:17px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613756412000018\"] .tn-atom{background-size:cover;-webkit-transform:rotate(52deg);-moz-transform:rotate(52deg);transform:rotate(52deg);}}#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"]{z-index:3;top:270px;;left:calc(50% - 600px + 554px);;width:102px;height:29px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"]{display:table;}}@media screen and (max-width:959px){#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"]{display:table;}}@media screen and (max-width:639px){#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"]{display:table;}}@media screen and (max-width:479px){#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"]{display:table;top:330px;;left:calc(50% - 160px + 0px);;width:58px;height:17px;}#rec1845616441 .tn-elem[data-elem-id=\"1769613753912000017\"] .tn-atom{background-size:cover;-webkit-transform:rotate(59deg);-moz-transform:rotate(59deg);transform:rotate(59deg);}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845616441\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"717\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"1298\" data-artboard-height-res-480=\"717\" data-artboard-height-res-640=\"717\" data-artboard-height-res-960=\"717\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845616441\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845616441\"><\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613016544' data-elem-id='1769613016544' data-elem-type='text' data-field-top-value=\"80\" data-field-left-value=\"179\" data-field-height-value=\"86\" data-field-width-value=\"842\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"0\" data-field-width-res-320-value=\"320\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769613016544'>\u0413\u0430\u0439\u0434 \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u0441\u043b\u0435\u0437\u0442\u044c \u0441&nbsp;\u044d\u043c\u043e\u0446\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0445 \u043a\u0430\u0447\u0435\u043b\u0435\u0439&nbsp;\u0438&nbsp;\u0432\u0437\u0433\u043b\u044f\u043d\u0443\u0442\u044c \u043d\u0430&nbsp;\u0432\u0441\u0451&nbsp;\u0437\u0434\u0440\u0430\u0432\u043e<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613523200' data-elem-id='1769613523200' data-elem-type='shape' data-field-top-value=\"533\" data-field-left-value=\"620\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1085\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"133\" data-field-width-res-320-value=\"299\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613593320' data-elem-id='1769613593320' data-elem-type='text' data-field-top-value=\"563\" data-field-left-value=\"650\" data-field-height-value=\"24\" data-field-width-value=\"514\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1115\" data-field-left-res-320-value=\"40\" data-field-height-res-320-value=\"72\" data-field-width-res-320-value=\"243\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-widthunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613593320'>\u042f \u0437\u043d\u0430\u044e, \u043a\u0430\u043a \u0431\u0443\u0434\u0435\u0442 \u043b\u0443\u0447\u0448\u0435 \u0434\u043b\u044f \u043c\u0435\u043d\u044f \u0438 \u043a\u0430\u043a \u043a \u044d\u0442\u043e\u043c\u0443 \u043f\u0440\u0438\u0439\u0442\u0438<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613634716000007' data-elem-id='1769613634716000007' data-elem-type='shape' data-field-top-value=\"424\" data-field-left-value=\"620\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"839\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"132\" data-field-width-res-320-value=\"300\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613634716000008' data-elem-id='1769613634716000008' data-elem-type='text' data-field-top-value=\"442\" data-field-left-value=\"650\" data-field-height-value=\"48\" data-field-width-value=\"476\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"869\" data-field-left-res-320-value=\"31\" data-field-height-res-320-value=\"72\" data-field-width-res-320-value=\"259\" data-field-container-res-320-value=\"grid\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613634716000008'>\u042f&nbsp;\u043f\u043e\u043d\u0438\u043c\u0430\u044e, \u0432&nbsp;\u0447\u0435\u043c \u043f\u0440\u0438\u0447\u0438\u043d\u0430 \u0442\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u0438&nbsp;\u0447\u0442\u043e \u0441&nbsp;\u043d\u0438\u043c\u0438 \u0434\u0435\u043b\u0430\u0442\u044c.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613629637000005' data-elem-id='1769613629637000005' data-elem-type='shape' data-field-top-value=\"315\" data-field-left-value=\"620\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"592\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"108\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613629637000006' data-elem-id='1769613629637000006' data-elem-type='text' data-field-top-value=\"345\" data-field-left-value=\"650\" data-field-height-value=\"24\" data-field-width-value=\"368\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"622\" data-field-left-res-320-value=\"40\" data-field-height-res-320-value=\"48\" data-field-width-res-320-value=\"242\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-widthunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613629637000006'>\u042f \u0434\u0443\u043c\u0430\u044e \u043e \u0441\u0435\u0431\u0435 \u0438 \u0441\u0432\u043e\u0435\u043c \u0431\u043b\u0430\u0433\u043e\u043f\u043e\u043b\u0443\u0447\u0438\u0438.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613621565000003' data-elem-id='1769613621565000003' data-elem-type='shape' data-field-top-value=\"206\" data-field-left-value=\"620\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"346\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"107\" data-field-width-res-320-value=\"300\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613621565000004' data-elem-id='1769613621565000004' data-elem-type='text' data-field-top-value=\"236\" data-field-left-value=\"650\" data-field-height-value=\"24\" data-field-width-value=\"322\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"376\" data-field-left-res-320-value=\"62\" data-field-height-res-320-value=\"48\" data-field-width-res-320-value=\"192\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613621565000004'>\u042f \u0441\u0444\u043e\u043a\u0443\u0441\u0438\u0440\u043e\u0432\u0430\u043d\u0430 \u043d\u0430 \u0441\u0432\u043e\u0435\u0439 \u0436\u0438\u0437\u043d\u0438.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000009' data-elem-id='1769613665734000009' data-elem-type='shape' data-field-top-value=\"533\" data-field-left-value=\"20\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"986\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000010' data-elem-id='1769613665734000010' data-elem-type='text' data-field-top-value=\"563\" data-field-left-value=\"50\" data-field-height-value=\"24\" data-field-width-value=\"197\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1016\" data-field-left-res-320-value=\"61\" data-field-height-res-320-value=\"24\" data-field-width-res-320-value=\"197\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-widthunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autowidth\"> <div class='tn-atom'field='tn_text_1769613665734000010'>\u041d\u0443 \u0438 \u0447\u0442\u043e \u043c\u043d\u0435 \u0434\u0435\u043b\u0430\u0442\u044c?<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000011' data-elem-id='1769613665734000011' data-elem-type='shape' data-field-top-value=\"424\" data-field-left-value=\"20\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"715\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"109\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000012' data-elem-id='1769613665734000012' data-elem-type='text' data-field-top-value=\"454\" data-field-left-value=\"50\" data-field-height-value=\"24\" data-field-width-value=\"401\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"745\" data-field-left-res-320-value=\"40\" data-field-height-res-320-value=\"48\" data-field-width-res-320-value=\"239\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613665734000012'>\u042f \u043d\u0435 \u043f\u043e\u043d\u0438\u043c\u0430\u044e, \u043a\u0430\u043a \u0432\u043e\u043e\u0431\u0449\u0435 \u0442\u0443\u0442 \u043e\u043a\u0430\u0437\u0430\u043b\u0430\u0441\u044c\u2026<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000013' data-elem-id='1769613665734000013' data-elem-type='shape' data-field-top-value=\"315\" data-field-left-value=\"20\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"468\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"109\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000014' data-elem-id='1769613665734000014' data-elem-type='text' data-field-top-value=\"345\" data-field-left-value=\"50\" data-field-height-value=\"24\" data-field-width-value=\"413\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"498\" data-field-left-res-320-value=\"40\" data-field-height-res-320-value=\"48\" data-field-width-res-320-value=\"242\" data-field-textfit-res-320-value=\"fixedsize\"> <div class='tn-atom'field='tn_text_1769613665734000014'>\u041d\u0435 \u043c\u043e\u0433\u0443 \u043f\u0435\u0440\u0435\u0441\u0442\u0430\u0442\u044c \u0434\u0443\u043c\u0430\u0442\u044c \u043e \u043d\u0435\u043c \u0438 \u0435\u0433\u043e \u0436\u0435\u043d\u0435!<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000015' data-elem-id='1769613665734000015' data-elem-type='shape' data-field-top-value=\"206\" data-field-left-value=\"20\" data-field-height-value=\"84\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"246\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"301\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613665734000016' data-elem-id='1769613665734000016' data-elem-type='text' data-field-top-value=\"236\" data-field-left-value=\"50\" data-field-height-value=\"24\" data-field-width-value=\"235\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"276\" data-field-left-res-320-value=\"40\"> <div class='tn-atom'field='tn_text_1769613665734000016'>\u041a\u043e\u0433\u0434\u0430 \u0436\u0435 \u043e\u043d \u0440\u0430\u0437\u0432\u0435\u0434\u0435\u0442\u0441\u044f?<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613727328' data-elem-id='1769613727328' data-elem-type='shape' data-field-top-value=\"588\" data-field-left-value=\"555\" data-field-height-value=\"29\" data-field-width-value=\"102\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"1070\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"17\" data-field-width-res-320-value=\"58\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3433-6161-4038-a534-353763363532\/Vector.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613760661000019' data-elem-id='1769613760661000019' data-elem-type='shape' data-field-top-value=\"479\" data-field-left-value=\"555\" data-field-height-value=\"29\" data-field-width-value=\"102\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"824\" data-field-left-res-320-value=\"7\" data-field-height-res-320-value=\"17\" data-field-width-res-320-value=\"58\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3433-6161-4038-a534-353763363532\/Vector.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613756412000018' data-elem-id='1769613756412000018' data-elem-type='shape' data-field-top-value=\"379\" data-field-left-value=\"555\" data-field-height-value=\"29\" data-field-width-value=\"102\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"577\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"17\" data-field-width-res-320-value=\"58\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3433-6161-4038-a534-353763363532\/Vector.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18456164411769613753912000017' data-elem-id='1769613753912000017' data-elem-type='shape' data-field-top-value=\"270\" data-field-left-value=\"554\" data-field-height-value=\"29\" data-field-width-value=\"102\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-top-res-320-value=\"330\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"17\" data-field-width-res-320-value=\"58\" data-field-container-res-320-value=\"grid\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3433-6161-4038-a534-353763363532\/Vector.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845616441');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845725821\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845725821 .t396__artboard {height:620px;background-color:#eef5f6;}#rec1845725821 .t396__filter {height:620px;}#rec1845725821 .t396__carrier{height:620px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845725821 .t396__artboard,#rec1845725821 .t396__filter,#rec1845725821 .t396__carrier {height:620px;}#rec1845725821 .t396__filter {}#rec1845725821 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845725821 .t396__artboard,#rec1845725821 .t396__filter,#rec1845725821 .t396__carrier {height:620px;}#rec1845725821 .t396__filter {}#rec1845725821 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845725821 .t396__artboard,#rec1845725821 .t396__filter,#rec1845725821 .t396__carrier {height:620px;}#rec1845725821 .t396__filter {}#rec1845725821 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845725821 .t396__artboard,#rec1845725821 .t396__filter,#rec1845725821 .t396__carrier {height:1832px;}#rec1845725821 .t396__filter {}#rec1845725821 .t396__carrier {background-attachment:scroll;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"]{z-index:3;top:126px;;left:calc(50% - 600px + 608px);;width:274px;height:414px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"]{display:table;top:152px;;left:calc(50% - 480px + 650px);;width:300px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"]{display:table;top:612px;;left:calc(50% - 320px + 10px);;width:300px;height:457px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000002\"]{display:table;top:952px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"]{z-index:3;top:419px;;left:calc(50% - 600px + 623px);;width:244px;height:106px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"]{display:table;top:459px;;left:calc(50% - 480px + 665px);;width:270px;height:135px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"]{display:table;top:919px;;left:calc(50% - 320px + 25px);;width:270px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000004\"]{display:table;top:1243px;;left:calc(50% - 160px + 10px);;width:300px;height:89px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"]{color:#192032;z-index:3;top:434px;;left:calc(50% - 600px + 638px);;width:214px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"]{display:table;top:513px;;left:calc(50% - 480px + 682px);;width:229px;height:auto;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"]{display:table;top:973px;;left:calc(50% - 320px + 42px);;width:229px;height:auto;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000006\"]{display:table;top:1258px;;left:calc(50% - 160px + 25px);;width:270px;height:auto;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"]{z-index:3;top:126px;;left:calc(50% - 600px + 906px);;width:274px;height:414px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"]{display:table;top:622px;;left:calc(50% - 480px + 330px);;width:300px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"]{display:table;top:612px;;left:calc(50% - 320px + 330px);;width:300px;height:457px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000008\"]{display:table;top:1362px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"]{z-index:3;top:438px;;left:calc(50% - 600px + 921px);;width:244px;height:87px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"]{display:table;top:944px;;left:calc(50% - 480px + 345px);;width:270px;height:120px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"]{display:table;top:934px;;left:calc(50% - 320px + 345px);;width:270px;height:120px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000010\"]{display:table;top:1674px;;left:calc(50% - 160px + 10px);;width:300px;height:68px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"]{color:#192032;z-index:3;top:453px;;left:calc(50% - 600px + 936px);;width:213px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"]{display:table;top:998px;;left:calc(50% - 480px + 362px);;width:237px;height:auto;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"]{display:table;top:988px;;left:calc(50% - 320px + 362px);;width:245px;height:auto;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000012\"]{display:table;top:1689px;;left:calc(50% - 160px + 25px);;width:270px;height:auto;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"]{z-index:3;top:126px;;left:calc(50% - 600px + 314px);;width:274px;height:414px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"]{display:table;top:147px;;left:calc(50% - 480px + 330px);;width:300px;height:457px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"]{display:table;top:135px;;left:calc(50% - 320px + 330px);;width:300px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000014\"]{display:table;top:542px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"]{z-index:3;top:454px;;left:calc(50% - 600px + 329px);;width:244px;height:71px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"]{display:table;top:469px;;left:calc(50% - 480px + 345px);;width:270px;height:120px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"]{display:table;top:457px;;left:calc(50% - 320px + 345px);;width:270px;height:120px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000016\"]{display:table;top:851px;;left:calc(50% - 160px + 10px);;width:300px;height:71px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"]{color:#192032;z-index:3;top:469px;;left:calc(50% - 600px + 344px);;width:218px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"]{display:table;top:523px;;left:calc(50% - 480px + 362px);;width:246px;height:auto;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"]{display:table;top:511px;;left:calc(50% - 320px + 360px);;width:236px;height:auto;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"]{display:table;top:866px;;left:calc(50% - 160px + 25px);;width:270px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000018\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"]{z-index:3;top:126px;;left:calc(50% - 600px + 20px);;width:274px;height:414px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"]{display:table;top:145px;;left:calc(50% - 480px + 10px);;width:300px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"]{display:table;top:135px;;left:calc(50% - 320px + 10px);;width:300px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000020\"]{display:table;top:132px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"]{z-index:3;top:438px;;left:calc(50% - 600px + 35px);;width:244px;height:87px;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"]{display:table;top:439px;;left:calc(50% - 480px + 25px);;width:270px;height:148px;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"]{display:table;top:429px;;left:calc(50% - 320px + 25px);;width:270px;height:148px;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"]{display:table;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000022\"]{display:table;top:441px;;left:calc(50% - 160px + 10px);;width:300px;height:71px;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"]{color:#192032;z-index:3;top:453px;;left:calc(50% - 600px + 50px);;width:218px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"]{display:table;top:522px;;left:calc(50% - 480px + 40px);;width:238px;height:auto;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"]{display:table;top:512px;;left:calc(50% - 320px + 40px);;width:233px;height:auto;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"]{display:table;top:456px;;left:calc(50% - 160px + 25px);;width:270px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613873780000023\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"]{color:#192032;text-align:center;z-index:3;top:0px;;left:calc(50% - 600px + 320px);;width:560px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"]{display:table;left:calc(50% - 160px + 0px);;width:320px;height:auto;}#rec1845725821 .tn-elem[data-elem-id=\"1769613814327\"] .tn-atom{font-size:28px;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845725821\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"620\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"1832\" data-artboard-height-res-480=\"620\" data-artboard-height-res-640=\"620\" data-artboard-height-res-960=\"620\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845725821\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845725821\"><\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000002' data-elem-id='1769613873780000002' data-elem-type='shape' data-field-top-value=\"126\" data-field-left-value=\"608\" data-field-height-value=\"414\" data-field-width-value=\"274\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"952\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"612\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"457\" data-field-width-res-640-value=\"300\" data-field-container-res-640-value=\"grid\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"152\" data-field-left-res-960-value=\"650\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3164-6362-4331-b539-366231623031\/Rectangle_17-2.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000004' data-elem-id='1769613873780000004' data-elem-type='shape' data-field-top-value=\"419\" data-field-left-value=\"623\" data-field-height-value=\"106\" data-field-width-value=\"244\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1243\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"89\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"919\" data-field-left-res-640-value=\"25\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"459\" data-field-left-res-960-value=\"665\" data-field-height-res-960-value=\"135\" data-field-width-res-960-value=\"270\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000006' data-elem-id='1769613873780000006' data-elem-type='text' data-field-top-value=\"434\" data-field-left-value=\"638\" data-field-height-value=\"76\" data-field-width-value=\"214\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1258\" data-field-left-res-320-value=\"25\" data-field-width-res-320-value=\"270\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"973\" data-field-left-res-640-value=\"42\" data-field-width-res-640-value=\"229\" data-field-top-res-960-value=\"513\" data-field-left-res-960-value=\"682\" data-field-width-res-960-value=\"229\"> <div class='tn-atom'field='tn_text_1769613873780000006'>\u0412\u0441\u0435 \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044b <span style=\"font-weight: 600;\">\u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043b\u0438 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0438 \u0441&nbsp;10-\u043b\u0435\u0442\u043d\u0435\u0439 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u043e\u0439<\/span>, \u0431\u0435\u0437 \u0443\u0447\u0430\u0441\u0442\u0438\u044f \u0418\u0418<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000008' data-elem-id='1769613873780000008' data-elem-type='shape' data-field-top-value=\"126\" data-field-left-value=\"906\" data-field-height-value=\"414\" data-field-width-value=\"274\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1362\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"612\" data-field-left-res-640-value=\"330\" data-field-height-res-640-value=\"457\" data-field-width-res-640-value=\"300\" data-field-container-res-640-value=\"grid\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"622\" data-field-left-res-960-value=\"330\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6635-6561-4137-a438-646634356264\/Rectangle_17-4.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000010' data-elem-id='1769613873780000010' data-elem-type='shape' data-field-top-value=\"438\" data-field-left-value=\"921\" data-field-height-value=\"87\" data-field-width-value=\"244\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1674\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"68\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"934\" data-field-left-res-640-value=\"345\" data-field-height-res-640-value=\"120\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-heightmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"944\" data-field-left-res-960-value=\"345\" data-field-height-res-960-value=\"120\" data-field-width-res-960-value=\"270\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000012' data-elem-id='1769613873780000012' data-elem-type='text' data-field-top-value=\"453\" data-field-left-value=\"936\" data-field-height-value=\"57\" data-field-width-value=\"213\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1689\" data-field-left-res-320-value=\"25\" data-field-width-res-320-value=\"270\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"988\" data-field-left-res-640-value=\"362\" data-field-height-res-640-value=\"51\" data-field-width-res-640-value=\"245\" data-field-top-res-960-value=\"998\" data-field-left-res-960-value=\"362\" data-field-width-res-960-value=\"237\"> <div class='tn-atom'field='tn_text_1769613873780000012'><span style=\"font-weight: 600;\">\u0422\u043e\u043b\u044c\u043a\u043e \u0441\u0430\u043c\u0430\u044f \u043d\u0443\u0436\u043d\u0430\u044f \u0438\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u044f<\/span>&nbsp;\u2014 \u0432\u0441\u0451 \u043a\u0440\u0430\u0442\u043a\u043e \u0438&nbsp;\u043f\u043e\u043d\u044f\u0442\u043d\u043e<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000014' data-elem-id='1769613873780000014' data-elem-type='shape' data-field-top-value=\"126\" data-field-left-value=\"314\" data-field-height-value=\"414\" data-field-width-value=\"274\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"542\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"135\" data-field-left-res-640-value=\"330\" data-field-width-res-640-value=\"300\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"147\" data-field-left-res-960-value=\"330\" data-field-height-res-960-value=\"457\" data-field-width-res-960-value=\"300\" data-field-container-res-960-value=\"grid\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6534-3463-4030-a336-633134633962\/Rectangle_17-1.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000016' data-elem-id='1769613873780000016' data-elem-type='shape' data-field-top-value=\"454\" data-field-left-value=\"329\" data-field-height-value=\"71\" data-field-width-value=\"244\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"851\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"71\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"457\" data-field-left-res-640-value=\"345\" data-field-height-res-640-value=\"120\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-heightmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"469\" data-field-left-res-960-value=\"345\" data-field-height-res-960-value=\"120\" data-field-width-res-960-value=\"270\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000018' data-elem-id='1769613873780000018' data-elem-type='text' data-field-top-value=\"469\" data-field-left-value=\"344\" data-field-height-value=\"38\" data-field-width-value=\"218\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"866\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"34\" data-field-width-res-320-value=\"270\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"511\" data-field-left-res-640-value=\"360\" data-field-height-res-640-value=\"51\" data-field-width-res-640-value=\"236\" data-field-top-res-960-value=\"523\" data-field-left-res-960-value=\"362\" data-field-width-res-960-value=\"246\"> <div class='tn-atom'field='tn_text_1769613873780000018'><span style=\"font-weight: 600;\">\u0424\u043e\u043a\u0443\u0441 \u043d\u0430 \u0442\u0435\u0431\u0435<\/span>, \u0430 \u043d\u0435 \u0441\u043b\u043e\u0436\u043d\u043e\u0441\u0442\u044f\u0445 \u0442\u0432\u043e\u0435\u0433\u043e \u043c\u0443\u0436\u0447\u0438\u043d\u044b<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000020' data-elem-id='1769613873780000020' data-elem-type='shape' data-field-top-value=\"126\" data-field-left-value=\"20\" data-field-height-value=\"414\" data-field-width-value=\"274\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"132\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"135\" data-field-left-res-640-value=\"10\" data-field-width-res-640-value=\"300\" data-field-top-res-960-value=\"145\" data-field-left-res-960-value=\"10\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6663-3536-4334-a238-626662613239\/Rectangle_17-5.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000022' data-elem-id='1769613873780000022' data-elem-type='shape' data-field-top-value=\"438\" data-field-left-value=\"35\" data-field-height-value=\"87\" data-field-width-value=\"244\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"441\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"71\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"429\" data-field-left-res-640-value=\"25\" data-field-height-res-640-value=\"148\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-heightmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"439\" data-field-left-res-960-value=\"25\" data-field-height-res-960-value=\"148\" data-field-width-res-960-value=\"270\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613873780000023' data-elem-id='1769613873780000023' data-elem-type='text' data-field-top-value=\"453\" data-field-left-value=\"50\" data-field-height-value=\"57\" data-field-width-value=\"218\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"456\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"34\" data-field-width-res-320-value=\"270\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"512\" data-field-left-res-640-value=\"40\" data-field-width-res-640-value=\"233\" data-field-top-res-960-value=\"522\" data-field-left-res-960-value=\"40\" data-field-width-res-960-value=\"238\"> <div class='tn-atom'field='tn_text_1769613873780000023'><span style=\"font-weight: 600;\">\u041f\u0440\u0430\u043a\u0442\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u044b<\/span> \u2014 \u0434\u0435\u043b\u0430\u0439 \u0438 \u0441\u0440\u0430\u0437\u0443 \u0437\u0430\u043c\u0435\u0447\u0430\u0439 \u044d\u0444\u0444\u0435\u043a\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457258211769613814327' data-elem-id='1769613814327' data-elem-type='text' data-field-top-value=\"0\" data-field-left-value=\"320\" data-field-height-value=\"86\" data-field-width-value=\"560\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"0\" data-field-width-res-320-value=\"320\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769613814327'>\u0412\u043e\u0442 \u0447\u0442\u043e \u043f\u043e\u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u043b\u0443\u0447\u0438\u0442\u044c \u0431\u044b\u0441\u0442\u0440\u044b\u0439 \u0440\u0435\u0437\u0443\u043b\u044c\u0442\u0430\u0442<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845725821');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845754881\" class=\"r t-rec t-screenmin-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-min=\"480px\"> <!-- T396 --> <style>#rec1845754881 .t396__artboard {height:717px;background-color:#ffffff;}#rec1845754881 .t396__filter {height:717px;}#rec1845754881 .t396__carrier{height:717px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845754881 .t396__artboard,#rec1845754881 .t396__filter,#rec1845754881 .t396__carrier {height:677px;}#rec1845754881 .t396__filter {}#rec1845754881 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845754881 .t396__artboard,#rec1845754881 .t396__filter,#rec1845754881 .t396__carrier {height:1090px;}#rec1845754881 .t396__filter {}#rec1845754881 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845754881 .t396__artboard,#rec1845754881 .t396__filter,#rec1845754881 .t396__carrier {height:1424px;}#rec1845754881 .t396__filter {}#rec1845754881 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845754881 .t396__artboard,#rec1845754881 .t396__filter,#rec1845754881 .t396__carrier {height:1661px;}#rec1845754881 .t396__filter {}#rec1845754881 .t396__carrier {background-attachment:scroll;}}#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"]{z-index:3;top:120px;;left:calc(50% - 600px + 20px);;width:360px;height:497px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#3f89c4;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:300px;height:517px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:120px;;left:calc(50% - 320px + 10px);;width:621px;height:378px;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:80px;;left:calc(50% - 160px + 0px);;width:320px;height:457px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"]{z-index:3;top:120px;;left:calc(50% - 600px + 20px);;width:360px;height:497px;}#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"] .tn-atom{border-radius:30px 30px 30px 30px;background-image:linear-gradient(0.133turn,rgba(255,255,255,0) 0%,rgba(255,255,255,0.7) 50%,rgba(255,255,255,0) 100%);border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:300px;height:517px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:120px;;left:calc(50% - 320px + 10px);;width:621px;height:378px;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:80px;;left:calc(50% - 160px + 0px);;width:320px;height:457px;}}#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"]{z-index:3;top:388px;;left:calc(50% - 600px + 29px);;width:342px;height:237px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:408px;;left:calc(50% - 480px + 24px);;width:279px;height:194px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{background-size:cover;opacity:1;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:257px;;left:calc(50% - 320px + 45px);;width:578px;height:241px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{background-position:center top;background-size:cover;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:331px;;left:calc(50% - 160px + 8px);;width:311px;height:216px;}}#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"]{z-index:3;top:295px;;left:calc(50% - 600px + 20px);;width:360px;height:322px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:275px;;left:calc(50% - 480px + -22px);;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:234px;;left:calc(50% - 320px + 186px);;width:278px;height:264px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"] .tn-atom{background-position:center top;background-size:cover;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:182px;;left:calc(50% - 160px + 29px);;width:271px;height:355px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"]{color:#ffffff;text-align:center;z-index:3;top:145px;;left:calc(50% - 600px + 32px);;width:338px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"] .tn-atom{vertical-align:middle;color:#ffffff;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:600;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:110px;;left:calc(50% - 480px + 10px);;width:300px;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:150px;;left:calc(50% - 320px + 78px);;width:487px;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:100px;;left:calc(50% - 160px + 26px);;width:269px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751655518565640\"] .tn-atom{font-size:26px;background-size:cover;}}#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"]{z-index:3;top:120px;;left:calc(50% - 600px + 400px);;width:780px;height:497px;}#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#f0f0f2;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:80px;;left:calc(50% - 480px + 330px);;width:620px;height:517px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:518px;;left:calc(50% - 320px + 10px);;height:492px;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:537px;;left:calc(50% - 160px + 0px);;width:320px;height:1124px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"]{z-index:3;top:364px;;left:calc(50% - 600px + 490px);;width:275px;height:160px;}#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751691219253000\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:295px;;left:calc(50% - 480px + 370px);;width:253px;height:177px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:752px;;left:calc(50% - 320px + 50px);;height:166px;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:799px;;left:calc(50% - 160px + 10px);;width:300px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"]{color:#192032;z-index:3;top:427px;;left:calc(50% - 600px + 505px);;width:243px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:358px;;left:calc(50% - 480px + 385px);;width:216px;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:815px;;left:calc(50% - 320px + 65px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:862px;;left:calc(50% - 160px + 25px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"]{z-index:3;top:379px;;left:calc(50% - 600px + 505px);;width:28px;height:28px;}#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751691220147420\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:310px;;left:calc(50% - 480px + 385px);;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:767px;;left:calc(50% - 320px + 65px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:814px;;left:calc(50% - 160px + 25px);;}}#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"]{color:#192032;z-index:3;top:384px;;left:calc(50% - 600px + 515px);;width:auto;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751691220483710\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:315px;;left:calc(50% - 480px + 395px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:772px;;left:calc(50% - 320px + 75px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:819px;;left:calc(50% - 160px + 35px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"]{z-index:3;top:419px;;left:calc(50% - 600px + 815px);;width:275px;height:138px;}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"1769614200841000002\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"]{display:table;top:367px;;left:calc(50% - 480px + 663px);;width:254px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"]{display:table;top:821px;;left:calc(50% - 320px + 343px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000002\"]{display:table;top:925px;;left:calc(50% - 160px + 10px);;width:300px;}}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"]{color:#192032;z-index:3;top:482px;;left:calc(50% - 600px + 830px);;width:243px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"]{display:table;top:430px;;left:calc(50% - 480px + 678px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"]{display:table;top:884px;;left:calc(50% - 320px + 358px);;width:232px;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000003\"]{display:table;top:988px;;left:calc(50% - 160px + 25px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"]{z-index:3;top:434px;;left:calc(50% - 600px + 830px);;width:28px;height:28px;}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"1769614200841000004\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"]{display:table;top:382px;;left:calc(50% - 480px + 678px);;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"]{display:table;top:836px;;left:calc(50% - 320px + 358px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000004\"]{display:table;top:940px;;left:calc(50% - 160px + 25px);;}}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"]{color:#192032;z-index:3;top:439px;;left:calc(50% - 600px + 840px);;width:auto;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"1769614200841000005\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"]{display:table;top:387px;;left:calc(50% - 480px + 688px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"]{display:table;top:841px;;left:calc(50% - 320px + 368px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"1769614200841000005\"]{display:table;top:945px;;left:calc(50% - 160px + 35px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"]{z-index:3;top:225px;;left:calc(50% - 600px + 815px);;width:275px;height:142px;}#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751695358654390\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:185px;;left:calc(50% - 480px + 663px);;width:254px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:643px;;left:calc(50% - 320px + 343px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:673px;;left:calc(50% - 160px + 10px);;width:300px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"]{color:#192032;z-index:3;top:288px;;left:calc(50% - 600px + 830px);;width:233px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:248px;;left:calc(50% - 480px + 678px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:706px;;left:calc(50% - 320px + 358px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:736px;;left:calc(50% - 160px + 25px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"]{z-index:3;top:240px;;left:calc(50% - 600px + 830px);;width:28px;height:28px;}#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751695359429400\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:200px;;left:calc(50% - 480px + 678px);;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:658px;;left:calc(50% - 320px + 358px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:688px;;left:calc(50% - 160px + 25px);;}}#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"]{color:#192032;z-index:3;top:245px;;left:calc(50% - 600px + 840px);;width:auto;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751695359729870\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:205px;;left:calc(50% - 480px + 688px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:663px;;left:calc(50% - 320px + 368px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:693px;;left:calc(50% - 160px + 35px);;height:auto;}}#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"]{z-index:3;top:170px;;left:calc(50% - 600px + 490px);;width:276px;height:154px;}#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751694202869190\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:120px;;left:calc(50% - 480px + 370px);;width:253px;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:558px;;left:calc(50% - 320px + 50px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:547px;;left:calc(50% - 160px + 10px);;width:300px;height:116px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"]{color:#192032;z-index:3;top:233px;;left:calc(50% - 600px + 505px);;width:233px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:183px;;left:calc(50% - 480px + 385px);;width:224px;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:621px;;left:calc(50% - 320px + 65px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:610px;;left:calc(50% - 160px + 25px);;width:233px;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751694203283420\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"]{z-index:3;top:185px;;left:calc(50% - 600px + 505px);;width:28px;height:28px;}#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751694203628460\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:135px;;left:calc(50% - 480px + 385px);;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:573px;;left:calc(50% - 320px + 65px);;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:562px;;left:calc(50% - 160px + 25px);;width:28px;height:28px;}}#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"]{color:#192032;z-index:3;top:190px;;left:calc(50% - 600px + 515px);;width:auto;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media (min-width:1200px){#rec1845754881 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"175751694203946750\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:140px;;left:calc(50% - 480px + 395px);;height:auto;}}@media screen and (max-width:959px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:578px;;left:calc(50% - 320px + 75px);;height:auto;}}@media screen and (max-width:639px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:567px;;left:calc(50% - 160px + 35px);;width:auto;height:auto;}#rec1845754881 .tn-elem[data-elem-id=\"175751694203946750\"] .tn-atom{vertical-align:middle;white-space:nowrap;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845754881\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"717\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"1661\" data-artboard-upscale-res-320=\"window\" data-artboard-height-res-480=\"1424\" data-artboard-height-res-640=\"1090\" data-artboard-height-res-960=\"677\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845754881\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845754881\"><\/div> <div class='t396__elem tn-elem tn-elem__18457548811757516404095' data-elem-id='1757516404095' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"20\" data-field-height-value=\"497\" data-field-width-value=\"360\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"457\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"120\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"378\" data-field-width-res-640-value=\"621\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-height-res-960-value=\"517\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751643549155230' data-elem-id='175751643549155230' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"20\" data-field-height-value=\"497\" data-field-width-value=\"360\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"457\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"120\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"378\" data-field-width-res-640-value=\"621\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-height-res-960-value=\"517\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811757516587255' data-elem-id='1757516587255' data-elem-type='shape' data-field-top-value=\"388\" data-field-left-value=\"29\" data-field-height-value=\"237\" data-field-width-value=\"342\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"331\" data-field-left-res-320-value=\"8\" data-field-height-res-320-value=\"216\" data-field-width-res-320-value=\"311\" data-field-top-res-640-value=\"257\" data-field-left-res-640-value=\"45\" data-field-height-res-640-value=\"241\" data-field-width-res-640-value=\"578\" data-field-top-res-960-value=\"408\" data-field-left-res-960-value=\"24\" data-field-height-res-960-value=\"194\" data-field-width-res-960-value=\"279\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3532-3437-4932-a630-643232373838\/photo.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811757516478159' data-elem-id='1757516478159' data-elem-type='shape' data-field-top-value=\"295\" data-field-left-value=\"20\" data-field-height-value=\"322\" data-field-width-value=\"360\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"182\" data-field-left-res-320-value=\"29\" data-field-height-res-320-value=\"355\" data-field-width-res-320-value=\"271\" data-field-top-res-640-value=\"234\" data-field-left-res-640-value=\"186\" data-field-height-res-640-value=\"264\" data-field-width-res-640-value=\"278\" data-field-top-res-960-value=\"275\" data-field-left-res-960-value=\"-22\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6365-3538-4938-b035-656535303734\/image_29.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751655518565640' data-elem-id='175751655518565640' data-elem-type='text' data-field-top-value=\"145\" data-field-left-value=\"32\" data-field-height-value=\"172\" data-field-width-value=\"338\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"100\" data-field-left-res-320-value=\"26\" data-field-width-res-320-value=\"269\" data-field-fontsize-res-320-value=\"26\" data-field-top-res-640-value=\"150\" data-field-left-res-640-value=\"78\" data-field-width-res-640-value=\"487\" data-field-top-res-960-value=\"110\" data-field-left-res-960-value=\"10\" data-field-width-res-960-value=\"300\"> <div class='tn-atom'field='tn_text_175751655518565640'>\u0427\u0442\u043e \u0433\u043e\u0432\u043e\u0440\u044f\u0442 \u0436\u0435\u043d\u0449\u0438\u043d\u044b, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u0432\u043e\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043b\u0438\u0441\u044c \u0433\u0430\u0439\u0434\u043e\u043c<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811757516630655' data-elem-id='1757516630655' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"400\" data-field-height-value=\"497\" data-field-width-value=\"780\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"537\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"1124\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"518\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"492\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"330\" data-field-height-res-960-value=\"517\" data-field-width-res-960-value=\"620\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751691219253000' data-elem-id='175751691219253000' data-elem-type='shape' data-field-top-value=\"364\" data-field-left-value=\"490\" data-field-height-value=\"160\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"799\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"752\" data-field-left-res-640-value=\"50\" data-field-height-res-640-value=\"166\" data-field-top-res-960-value=\"295\" data-field-left-res-960-value=\"370\" data-field-height-res-960-value=\"177\" data-field-width-res-960-value=\"253\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751691219794170' data-elem-id='175751691219794170' data-elem-type='text' data-field-top-value=\"427\" data-field-left-value=\"505\" data-field-height-value=\"76\" data-field-width-value=\"243\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"862\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"815\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"358\" data-field-left-res-960-value=\"385\" data-field-width-res-960-value=\"216\"> <div class='tn-atom'field='tn_text_175751691219794170'>\u0421\u043c\u043e\u0433\u043b\u0430 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430 \u201c\u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u0438\u043a\u201d \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u0438 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u0432\u0441\u0435 \u043d\u0430 \u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0434\u0438\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751691220147420' data-elem-id='175751691220147420' data-elem-type='shape' data-field-top-value=\"379\" data-field-left-value=\"505\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"814\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"767\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"310\" data-field-left-res-960-value=\"385\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751691220483710' data-elem-id='175751691220483710' data-elem-type='text' data-field-top-value=\"384\" data-field-left-value=\"515\" data-field-height-value=\"19\" data-field-width-value=\"8\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"819\" data-field-left-res-320-value=\"35\" data-field-top-res-640-value=\"772\" data-field-left-res-640-value=\"75\" data-field-top-res-960-value=\"315\" data-field-left-res-960-value=\"395\"> <div class='tn-atom'field='tn_text_175751691220483710'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">3<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811769614200841000002' data-elem-id='1769614200841000002' data-elem-type='shape' data-field-top-value=\"419\" data-field-left-value=\"815\" data-field-height-value=\"138\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"925\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"821\" data-field-left-res-640-value=\"343\" data-field-top-res-960-value=\"367\" data-field-left-res-960-value=\"663\" data-field-width-res-960-value=\"254\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811769614200841000003' data-elem-id='1769614200841000003' data-elem-type='text' data-field-top-value=\"482\" data-field-left-value=\"830\" data-field-height-value=\"57\" data-field-width-value=\"243\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"988\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"884\" data-field-left-res-640-value=\"358\" data-field-width-res-640-value=\"232\" data-field-top-res-960-value=\"430\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'field='tn_text_1769614200841000003'>\u041f\u0435\u0440\u0435\u0441\u0442\u0430\u043b\u0430 \u0438\u0434\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u043c\u0443\u0436\u0447\u0438\u043d\u0443 \u0438 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u043b\u0430 \u0440\u0435\u0430\u043b\u044c\u043d\u043e \u043d\u0430 \u0435\u0433\u043e \u043e\u0431\u0435\u0449\u0430\u043d\u0438\u044f<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811769614200841000004' data-elem-id='1769614200841000004' data-elem-type='shape' data-field-top-value=\"434\" data-field-left-value=\"830\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"940\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"836\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"382\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457548811769614200841000005' data-elem-id='1769614200841000005' data-elem-type='text' data-field-top-value=\"439\" data-field-left-value=\"840\" data-field-height-value=\"19\" data-field-width-value=\"9\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"945\" data-field-left-res-320-value=\"35\" data-field-top-res-640-value=\"841\" data-field-left-res-640-value=\"368\" data-field-top-res-960-value=\"387\" data-field-left-res-960-value=\"688\"> <div class='tn-atom'field='tn_text_1769614200841000005'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">4<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751695358654390' data-elem-id='175751695358654390' data-elem-type='shape' data-field-top-value=\"225\" data-field-left-value=\"815\" data-field-height-value=\"142\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"673\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"643\" data-field-left-res-640-value=\"343\" data-field-top-res-960-value=\"185\" data-field-left-res-960-value=\"663\" data-field-width-res-960-value=\"254\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751695359048590' data-elem-id='175751695359048590' data-elem-type='text' data-field-top-value=\"288\" data-field-left-value=\"830\" data-field-height-value=\"57\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"736\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"706\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"248\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'field='tn_text_175751695359048590'>\u041f\u0435\u0440\u0435\u0441\u0442\u0430\u043b\u0430 \u0441\u0442\u0440\u0430\u0434\u0430\u0442\u044c, \u043a\u043e\u0433\u0434\u0430 \u043e\u0441\u0442\u0430\u044e\u0441\u044c \u043d\u0430\u0435\u0434\u0438\u043d\u0435 \u0441 \u0441\u043e\u0431\u043e\u0439, \u043d\u0430\u0447\u0430\u043b\u0430 \u043d\u0430\u0441\u043b\u0430\u0436\u0434\u0430\u0442\u044c\u0441\u044f \u0436\u0438\u0437\u043d\u044c\u044e<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751695359429400' data-elem-id='175751695359429400' data-elem-type='shape' data-field-top-value=\"240\" data-field-left-value=\"830\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"688\" data-field-left-res-320-value=\"25\" data-field-top-res-640-value=\"658\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"200\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751695359729870' data-elem-id='175751695359729870' data-elem-type='text' data-field-top-value=\"245\" data-field-left-value=\"840\" data-field-height-value=\"19\" data-field-width-value=\"8\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"693\" data-field-left-res-320-value=\"35\" data-field-top-res-640-value=\"663\" data-field-left-res-640-value=\"368\" data-field-top-res-960-value=\"205\" data-field-left-res-960-value=\"688\"> <div class='tn-atom'field='tn_text_175751695359729870'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">2<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751694202869190' data-elem-id='175751694202869190' data-elem-type='shape' data-field-top-value=\"170\" data-field-left-value=\"490\" data-field-height-value=\"154\" data-field-width-value=\"276\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"547\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"116\" data-field-width-res-320-value=\"300\" data-field-container-res-320-value=\"grid\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"558\" data-field-left-res-640-value=\"50\" data-field-top-res-960-value=\"120\" data-field-left-res-960-value=\"370\" data-field-width-res-960-value=\"253\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751694203283420' data-elem-id='175751694203283420' data-elem-type='text' data-field-top-value=\"233\" data-field-left-value=\"505\" data-field-height-value=\"76\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"610\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"38\" data-field-width-res-320-value=\"233\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-top-res-640-value=\"621\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"183\" data-field-left-res-960-value=\"385\" data-field-width-res-960-value=\"224\"> <div class='tn-atom'field='tn_text_175751694203283420'>\u0421\u0430\u043c\u043e\u0435 \u0433\u043b\u0430\u0432\u043d\u043e\u0435 \u2014 \u044f \u0441\u043c\u043e\u0433\u043b\u0430 \u043f\u0440\u0438\u0432\u0435\u0441\u0442\u0438 \u043c\u044b\u0441\u043b\u0438 \u0432 \u043f\u043e\u0440\u044f\u0434\u043e\u043a \u0438 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u043e\u043a\u0430\u0437\u0430\u043b\u0430\u0441\u044c \u0432 \u044d\u0442\u0438\u0445 \u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u044b\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445...<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751694203628460' data-elem-id='175751694203628460' data-elem-type='shape' data-field-top-value=\"185\" data-field-left-value=\"505\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"562\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"28\" data-field-width-res-320-value=\"28\" data-field-container-res-320-value=\"grid\" data-field-top-res-640-value=\"573\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"135\" data-field-left-res-960-value=\"385\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845754881175751694203946750' data-elem-id='175751694203946750' data-elem-type='text' data-field-top-value=\"190\" data-field-left-value=\"515\" data-field-height-value=\"19\" data-field-width-value=\"5\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"hover\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'ti':0,'ea':'0','dt':0},{'mx':0,'my':0,'sx':1.06,'sy':1.06,'op':1,'ro':0,'ti':500,'ea':'0','dt':0}]\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"567\" data-field-left-res-320-value=\"35\" data-field-height-res-320-value=\"19\" data-field-width-res-320-value=\"5\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-widthunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autowidth\" data-field-top-res-640-value=\"578\" data-field-left-res-640-value=\"75\" data-field-top-res-960-value=\"140\" data-field-left-res-960-value=\"395\"> <div class='tn-atom'field='tn_text_175751694203946750'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">1<\/div><\/div> <\/div> <\/div> <\/div> <script>t_onFuncLoad('t396_initialScale',function() {t396_initialScale('1845754881');});t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845754881');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845767341\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-max=\"480px\"> <!-- T396 --> <style>#rec1845767341 .t396__artboard {height:625px;background-color:#ffffff;}#rec1845767341 .t396__filter {height:625px;}#rec1845767341 .t396__carrier{height:625px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845767341 .t396__artboard,#rec1845767341 .t396__filter,#rec1845767341 .t396__carrier {height:984px;}#rec1845767341 .t396__filter {}#rec1845767341 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845767341 .t396__artboard,#rec1845767341 .t396__filter,#rec1845767341 .t396__carrier {height:1424px;}#rec1845767341 .t396__filter {}#rec1845767341 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845767341 .t396__artboard,#rec1845767341 .t396__filter,#rec1845767341 .t396__carrier {}#rec1845767341 .t396__filter {}#rec1845767341 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845767341 .t396__artboard,#rec1845767341 .t396__filter,#rec1845767341 .t396__carrier {height:547px;}#rec1845767341 .t396__artboard {background-color:#ffffff;}#rec1845767341 .t396__filter {}#rec1845767341 .t396__carrier {background-attachment:scroll;}}#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"]{z-index:3;top:120px;;left:calc(50% - 600px + 20px);;width:360px;height:497px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#3f89c4;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:300px;height:517px;}}@media screen and (max-width:959px){#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:120px;;left:calc(50% - 320px + 10px);;width:621px;height:378px;}}@media screen and (max-width:639px){#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;}}@media screen and (max-width:479px){#rec1845767341 .tn-elem[data-elem-id=\"1757516404095\"]{display:table;top:80px;;left:calc(50% - 160px + 0px);;width:320px;height:457px;}}#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"]{z-index:3;top:120px;;left:calc(50% - 600px + 20px);;width:360px;height:497px;}#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"] .tn-atom{border-radius:30px 30px 30px 30px;background-image:linear-gradient(0.133turn,rgba(255,255,255,0) 0%,rgba(255,255,255,0.7) 50%,rgba(255,255,255,0) 100%);border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:300px;height:517px;}}@media screen and (max-width:959px){#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:120px;;left:calc(50% - 320px + 10px);;width:621px;height:378px;}}@media screen and (max-width:639px){#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;}}@media screen and (max-width:479px){#rec1845767341 .tn-elem[data-elem-id=\"175751643549155230\"]{display:table;top:80px;;left:calc(50% - 160px + 0px);;width:320px;height:457px;}}#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"]{z-index:3;top:388px;;left:calc(50% - 600px + 29px);;width:342px;height:237px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:408px;;left:calc(50% - 480px + 24px);;width:279px;height:194px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{background-size:cover;opacity:1;}}@media screen and (max-width:959px){#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:257px;;left:calc(50% - 320px + 45px);;width:578px;height:241px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"] .tn-atom{background-position:center top;background-size:cover;}}@media screen and (max-width:639px){#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;}}@media screen and (max-width:479px){#rec1845767341 .tn-elem[data-elem-id=\"1757516587255\"]{display:table;top:331px;;left:calc(50% - 160px + 8px);;width:311px;height:216px;}}#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"]{z-index:3;top:268px;;left:calc(50% - 600px + 68px);;width:266px;height:349px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:248px;;left:calc(50% - 480px + 18px);;}}@media screen and (max-width:959px){#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:234px;;left:calc(50% - 320px + 186px);;width:278px;height:264px;}#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"] .tn-atom{background-position:center top;background-size:cover;}}@media screen and (max-width:639px){#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;}}@media screen and (max-width:479px){#rec1845767341 .tn-elem[data-elem-id=\"1757516478159\"]{display:table;top:182px;;left:calc(50% - 160px + 1px);;width:319px;height:355px;}}#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"]{color:#ffffff;text-align:center;z-index:3;top:150px;;left:calc(50% - 600px + 82px);;width:294px;height:auto;}#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"] .tn-atom{vertical-align:middle;color:#ffffff;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:600;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:110px;;left:calc(50% - 480px + 43px);;height:auto;}}@media screen and (max-width:959px){#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:150px;;left:calc(50% - 320px + 78px);;width:487px;height:auto;}}@media screen and (max-width:639px){#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"]{display:table;top:100px;;left:calc(50% - 160px + 26px);;width:269px;height:auto;}#rec1845767341 .tn-elem[data-elem-id=\"175751655518565640\"] .tn-atom{font-size:26px;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845767341\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"625\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"547\" data-artboard-upscale-res-320=\"grid\" data-artboard-height-res-640=\"1424\" data-artboard-height-res-960=\"984\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845767341\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845767341\"><\/div> <div class='t396__elem tn-elem tn-elem__18457673411757516404095' data-elem-id='1757516404095' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"20\" data-field-height-value=\"497\" data-field-width-value=\"360\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"457\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"120\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"378\" data-field-width-res-640-value=\"621\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-height-res-960-value=\"517\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845767341175751643549155230' data-elem-id='175751643549155230' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"20\" data-field-height-value=\"497\" data-field-width-value=\"360\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"457\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"120\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"378\" data-field-width-res-640-value=\"621\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-height-res-960-value=\"517\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457673411757516587255' data-elem-id='1757516587255' data-elem-type='shape' data-field-top-value=\"388\" data-field-left-value=\"29\" data-field-height-value=\"237\" data-field-width-value=\"342\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"331\" data-field-left-res-320-value=\"8\" data-field-height-res-320-value=\"216\" data-field-width-res-320-value=\"311\" data-field-top-res-640-value=\"257\" data-field-left-res-640-value=\"45\" data-field-height-res-640-value=\"241\" data-field-width-res-640-value=\"578\" data-field-top-res-960-value=\"408\" data-field-left-res-960-value=\"24\" data-field-height-res-960-value=\"194\" data-field-width-res-960-value=\"279\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3532-3437-4932-a630-643232373838\/photo.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457673411757516478159' data-elem-id='1757516478159' data-elem-type='shape' data-field-top-value=\"268\" data-field-left-value=\"68\" data-field-height-value=\"349\" data-field-width-value=\"266\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"182\" data-field-left-res-320-value=\"1\" data-field-height-res-320-value=\"355\" data-field-width-res-320-value=\"319\" data-field-top-res-640-value=\"234\" data-field-left-res-640-value=\"186\" data-field-height-res-640-value=\"264\" data-field-width-res-640-value=\"278\" data-field-top-res-960-value=\"248\" data-field-left-res-960-value=\"18\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6339-6233-4634-b434-383835376662\/image_29.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845767341175751655518565640' data-elem-id='175751655518565640' data-elem-type='text' data-field-top-value=\"150\" data-field-left-value=\"82\" data-field-height-value=\"215\" data-field-width-value=\"294\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"100\" data-field-left-res-320-value=\"26\" data-field-height-res-320-value=\"124\" data-field-width-res-320-value=\"269\" data-field-fontsize-res-320-value=\"26\" data-field-top-res-640-value=\"150\" data-field-left-res-640-value=\"78\" data-field-width-res-640-value=\"487\" data-field-top-res-960-value=\"110\" data-field-left-res-960-value=\"43\"> <div class='tn-atom'field='tn_text_175751655518565640'>\u0427\u0442\u043e \u0433\u043e\u0432\u043e\u0440\u044f\u0442 \u0436\u0435\u043d\u0449\u0438\u043d\u044b, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u0432\u043e\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043b\u0438\u0441\u044c \u0433\u0430\u0439\u0434\u043e\u043c<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845767341');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845771801\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-max=\"480px\"> <!-- T396 --> <style>#rec1845771801 .t396__artboard {height:675px;background-color:#ffffff;}#rec1845771801 .t396__filter {height:675px;}#rec1845771801 .t396__carrier{height:675px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845771801 .t396__artboard,#rec1845771801 .t396__filter,#rec1845771801 .t396__carrier {height:984px;}#rec1845771801 .t396__filter {}#rec1845771801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845771801 .t396__artboard,#rec1845771801 .t396__filter,#rec1845771801 .t396__carrier {height:1424px;}#rec1845771801 .t396__filter {}#rec1845771801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845771801 .t396__artboard,#rec1845771801 .t396__filter,#rec1845771801 .t396__carrier {height:1424px;}#rec1845771801 .t396__filter {}#rec1845771801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845771801 .t396__artboard,#rec1845771801 .t396__filter,#rec1845771801 .t396__carrier {height:256px;}#rec1845771801 .t396__artboard {background-color:#ffffff;}#rec1845771801 .t396__filter {}#rec1845771801 .t396__carrier {background-attachment:scroll;}}#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"]{z-index:3;top:120px;;left:calc(50% - 600px + 400px);;width:780px;height:475px;}#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#f0f0f2;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:80px;;left:calc(50% - 480px + 330px);;width:620px;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:518px;;left:calc(50% - 320px + 10px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"1757516630655\"]{display:table;top:0px;;left:calc(50% - 160px + 0px);;width:1148px;height:176px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"]{z-index:3;top:336px;;left:calc(50% - 600px + 490px);;width:275px;height:116px;}#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:286px;;left:calc(50% - 480px + 370px);;width:253px;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:724px;;left:calc(50% - 320px + 50px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219253000\"]{display:table;top:10px;;left:calc(50% - 160px + 580px);;width:275px;height:155px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"]{color:#192032;z-index:3;top:399px;;left:calc(50% - 600px + 505px);;width:233px;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:349px;;left:calc(50% - 480px + 385px);;width:216px;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:787px;;left:calc(50% - 320px + 65px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751691219794170\"]{display:table;top:73px;;left:calc(50% - 160px + 595px);;width:216px;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"]{z-index:3;top:351px;;left:calc(50% - 600px + 505px);;width:28px;height:28px;}#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:301px;;left:calc(50% - 480px + 385px);;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:739px;;left:calc(50% - 320px + 65px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220147420\"]{display:table;top:25px;;left:calc(50% - 160px + 595px);;}}#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"]{color:#192032;z-index:3;top:356px;;left:calc(50% - 600px + 515px);;width:auto;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:306px;;left:calc(50% - 480px + 395px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:744px;;left:calc(50% - 320px + 75px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751691220483710\"]{display:table;top:30px;;left:calc(50% - 160px + 605px);;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"]{z-index:3;top:421px;;left:calc(50% - 600px + 815px);;width:275px;height:116px;}#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"]{display:table;top:371px;;left:calc(50% - 480px + 663px);;width:254px;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"]{display:table;top:809px;;left:calc(50% - 320px + 343px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751696120934010\"]{display:table;top:10px;;left:calc(50% - 160px + 865px);;width:275px;height:155px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"]{color:#192032;z-index:3;top:484px;;left:calc(50% - 600px + 830px);;width:233px;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"]{display:table;top:434px;;left:calc(50% - 480px + 678px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"]{display:table;top:872px;;left:calc(50% - 320px + 358px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121450100\"]{display:table;top:73px;;left:calc(50% - 160px + 880px);;width:233px;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"]{z-index:3;top:436px;;left:calc(50% - 600px + 830px);;width:28px;height:28px;}#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"]{display:table;top:386px;;left:calc(50% - 480px + 678px);;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"]{display:table;top:824px;;left:calc(50% - 320px + 358px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751696121883370\"]{display:table;top:25px;;left:calc(50% - 160px + 880px);;}}#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"]{color:#192032;z-index:3;top:441px;;left:calc(50% - 600px + 840px);;width:auto;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"]{display:table;top:391px;;left:calc(50% - 480px + 688px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"]{display:table;top:829px;;left:calc(50% - 320px + 368px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751696122152510\"]{display:table;top:30px;;left:calc(50% - 160px + 890px);;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"]{z-index:3;top:255px;;left:calc(50% - 600px + 815px);;width:275px;height:116px;}#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:205px;;left:calc(50% - 480px + 663px);;width:254px;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:643px;;left:calc(50% - 320px + 343px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751695358654390\"]{display:table;top:10px;;left:calc(50% - 160px + 295px);;width:275px;height:155px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"]{color:#192032;z-index:3;top:318px;;left:calc(50% - 600px + 830px);;width:233px;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:268px;;left:calc(50% - 480px + 678px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:706px;;left:calc(50% - 320px + 358px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359048590\"]{display:table;top:73px;;left:calc(50% - 160px + 310px);;width:233px;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"]{z-index:3;top:270px;;left:calc(50% - 600px + 830px);;width:28px;height:28px;}#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:220px;;left:calc(50% - 480px + 678px);;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:658px;;left:calc(50% - 320px + 358px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359429400\"]{display:table;top:25px;;left:calc(50% - 160px + 310px);;}}#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"]{color:#192032;z-index:3;top:275px;;left:calc(50% - 600px + 840px);;width:auto;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:225px;;left:calc(50% - 480px + 688px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:663px;;left:calc(50% - 320px + 368px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751695359729870\"]{display:table;top:30px;;left:calc(50% - 160px + 320px);;height:auto;}}#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"]{z-index:3;top:170px;;left:calc(50% - 600px + 490px);;width:275px;height:116px;}#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:120px;;left:calc(50% - 480px + 370px);;width:253px;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:558px;;left:calc(50% - 320px + 50px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751694202869190\"]{display:table;top:10px;;left:calc(50% - 160px + 10px);;width:275px;height:155px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"]{color:#192032;z-index:3;top:233px;;left:calc(50% - 600px + 505px);;width:233px;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:183px;;left:calc(50% - 480px + 385px);;width:224px;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:621px;;left:calc(50% - 320px + 65px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"]{display:table;top:73px;;left:calc(50% - 160px + 25px);;width:233px;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751694203283420\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"]{z-index:3;top:185px;;left:calc(50% - 600px + 505px);;width:28px;height:28px;}#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"] .tn-atom{border-radius:5px 5px 5px 5px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:135px;;left:calc(50% - 480px + 385px);;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:573px;;left:calc(50% - 320px + 65px);;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203628460\"]{display:table;top:25px;;left:calc(50% - 160px + 25px);;width:28px;height:28px;}}#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"]{color:#192032;z-index:3;top:190px;;left:calc(50% - 600px + 515px);;width:auto;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:140px;;left:calc(50% - 480px + 395px);;height:auto;}}@media screen and (max-width:959px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:578px;;left:calc(50% - 320px + 75px);;height:auto;}}@media screen and (max-width:639px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"]{display:table;top:30px;;left:calc(50% - 160px + 35px);;width:auto;height:auto;}#rec1845771801 .tn-elem[data-elem-id=\"175751694203946750\"] .tn-atom{vertical-align:middle;white-space:nowrap;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845771801\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"675\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"256\" data-artboard-upscale-res-320=\"grid\" data-artboard-height-res-480=\"1424\" data-artboard-height-res-640=\"1424\" data-artboard-height-res-960=\"984\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845771801\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845771801\"><\/div> <div class='t396__elem tn-elem tn-elem__18457718011757516630655' data-elem-id='1757516630655' data-elem-type='shape' data-field-top-value=\"120\" data-field-left-value=\"400\" data-field-height-value=\"475\" data-field-width-value=\"780\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"176\" data-field-width-res-320-value=\"1148\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"518\" data-field-left-res-640-value=\"10\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"330\" data-field-width-res-960-value=\"620\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751691219253000' data-elem-id='175751691219253000' data-elem-type='shape' data-field-top-value=\"336\" data-field-left-value=\"490\" data-field-height-value=\"116\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"10\" data-field-left-res-320-value=\"580\" data-field-height-res-320-value=\"155\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"724\" data-field-left-res-640-value=\"50\" data-field-top-res-960-value=\"286\" data-field-left-res-960-value=\"370\" data-field-width-res-960-value=\"253\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751691219794170' data-elem-id='175751691219794170' data-elem-type='text' data-field-top-value=\"399\" data-field-left-value=\"505\" data-field-height-value=\"76\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"73\" data-field-left-res-320-value=\"595\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"216\" data-field-top-res-640-value=\"787\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"349\" data-field-left-res-960-value=\"385\" data-field-width-res-960-value=\"216\"> <div class='tn-atom'field='tn_text_175751691219794170'>\u0421\u043c\u043e\u0433\u043b\u0430 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430 \u201c\u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u0438\u043a\u201d \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u0438 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u0432\u0441\u0435 \u043d\u0430 \u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0434\u0438\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751691220147420' data-elem-id='175751691220147420' data-elem-type='shape' data-field-top-value=\"351\" data-field-left-value=\"505\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"595\" data-field-top-res-640-value=\"739\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"301\" data-field-left-res-960-value=\"385\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751691220483710' data-elem-id='175751691220483710' data-elem-type='text' data-field-top-value=\"356\" data-field-left-value=\"515\" data-field-height-value=\"19\" data-field-width-value=\"8\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"30\" data-field-left-res-320-value=\"605\" data-field-top-res-640-value=\"744\" data-field-left-res-640-value=\"75\" data-field-top-res-960-value=\"306\" data-field-left-res-960-value=\"395\"> <div class='tn-atom'field='tn_text_175751691220483710'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">3<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751696120934010' data-elem-id='175751696120934010' data-elem-type='shape' data-field-top-value=\"421\" data-field-left-value=\"815\" data-field-height-value=\"116\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"10\" data-field-left-res-320-value=\"865\" data-field-height-res-320-value=\"155\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"809\" data-field-left-res-640-value=\"343\" data-field-top-res-960-value=\"371\" data-field-left-res-960-value=\"663\" data-field-width-res-960-value=\"254\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751696121450100' data-elem-id='175751696121450100' data-elem-type='text' data-field-top-value=\"484\" data-field-left-value=\"830\" data-field-height-value=\"57\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"73\" data-field-left-res-320-value=\"880\" data-field-height-res-320-value=\"57\" data-field-width-res-320-value=\"233\" data-field-top-res-640-value=\"872\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"434\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'field='tn_text_175751696121450100'>\u041f\u0435\u0440\u0435\u0441\u0442\u0430\u043b\u0430 \u0438\u0434\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u043c\u0443\u0436\u0447\u0438\u043d\u0443 \u0438 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u043b\u0430 \u0440\u0435\u0430\u043b\u044c\u043d\u043e \u043d\u0430 \u0435\u0433\u043e \u043e\u0431\u0435\u0449\u0430\u043d\u0438\u044f<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751696121883370' data-elem-id='175751696121883370' data-elem-type='shape' data-field-top-value=\"436\" data-field-left-value=\"830\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"880\" data-field-top-res-640-value=\"824\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"386\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751696122152510' data-elem-id='175751696122152510' data-elem-type='text' data-field-top-value=\"441\" data-field-left-value=\"840\" data-field-height-value=\"19\" data-field-width-value=\"9\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"30\" data-field-left-res-320-value=\"890\" data-field-top-res-640-value=\"829\" data-field-left-res-640-value=\"368\" data-field-top-res-960-value=\"391\" data-field-left-res-960-value=\"688\"> <div class='tn-atom'field='tn_text_175751696122152510'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">4<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751695358654390' data-elem-id='175751695358654390' data-elem-type='shape' data-field-top-value=\"255\" data-field-left-value=\"815\" data-field-height-value=\"116\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"10\" data-field-left-res-320-value=\"295\" data-field-height-res-320-value=\"155\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"643\" data-field-left-res-640-value=\"343\" data-field-top-res-960-value=\"205\" data-field-left-res-960-value=\"663\" data-field-width-res-960-value=\"254\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751695359048590' data-elem-id='175751695359048590' data-elem-type='text' data-field-top-value=\"318\" data-field-left-value=\"830\" data-field-height-value=\"57\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"73\" data-field-left-res-320-value=\"310\" data-field-height-res-320-value=\"57\" data-field-width-res-320-value=\"233\" data-field-top-res-640-value=\"706\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"268\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'field='tn_text_175751695359048590'>\u041f\u0435\u0440\u0435\u0441\u0442\u0430\u043b\u0430 \u0441\u0442\u0440\u0430\u0434\u0430\u0442\u044c, \u043a\u043e\u0433\u0434\u0430 \u043e\u0441\u0442\u0430\u044e\u0441\u044c \u043d\u0430\u0435\u0434\u0438\u043d\u0435 \u0441 \u0441\u043e\u0431\u043e\u0439, \u043d\u0430\u0447\u0430\u043b\u0430 \u043d\u0430\u0441\u043b\u0430\u0436\u0434\u0430\u0442\u044c\u0441\u044f \u0436\u0438\u0437\u043d\u044c\u044e<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751695359429400' data-elem-id='175751695359429400' data-elem-type='shape' data-field-top-value=\"270\" data-field-left-value=\"830\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"310\" data-field-top-res-640-value=\"658\" data-field-left-res-640-value=\"358\" data-field-top-res-960-value=\"220\" data-field-left-res-960-value=\"678\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751695359729870' data-elem-id='175751695359729870' data-elem-type='text' data-field-top-value=\"275\" data-field-left-value=\"840\" data-field-height-value=\"19\" data-field-width-value=\"8\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"30\" data-field-left-res-320-value=\"320\" data-field-top-res-640-value=\"663\" data-field-left-res-640-value=\"368\" data-field-top-res-960-value=\"225\" data-field-left-res-960-value=\"688\"> <div class='tn-atom'field='tn_text_175751695359729870'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">2<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751694202869190' data-elem-id='175751694202869190' data-elem-type='shape' data-field-top-value=\"170\" data-field-left-value=\"490\" data-field-height-value=\"116\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"10\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"155\" data-field-width-res-320-value=\"275\" data-field-container-res-320-value=\"grid\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"558\" data-field-left-res-640-value=\"50\" data-field-top-res-960-value=\"120\" data-field-left-res-960-value=\"370\" data-field-width-res-960-value=\"253\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751694203283420' data-elem-id='175751694203283420' data-elem-type='text' data-field-top-value=\"233\" data-field-left-value=\"505\" data-field-height-value=\"76\" data-field-width-value=\"233\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"73\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"233\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-top-res-640-value=\"621\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"183\" data-field-left-res-960-value=\"385\" data-field-width-res-960-value=\"224\"> <div class='tn-atom'field='tn_text_175751694203283420'>\u0421\u0430\u043c\u043e\u0435 \u0433\u043b\u0430\u0432\u043d\u043e\u0435 \u2014 \u044f \u0441\u043c\u043e\u0433\u043b\u0430 \u043f\u0440\u0438\u0432\u0435\u0441\u0442\u0438 \u043c\u044b\u0441\u043b\u0438 \u0432 \u043f\u043e\u0440\u044f\u0434\u043e\u043a \u0438 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u043e\u043a\u0430\u0437\u0430\u043b\u0430\u0441\u044c \u0432 \u044d\u0442\u0438\u0445 \u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u044b\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445...<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751694203628460' data-elem-id='175751694203628460' data-elem-type='shape' data-field-top-value=\"185\" data-field-left-value=\"505\" data-field-height-value=\"28\" data-field-width-value=\"28\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"25\" data-field-left-res-320-value=\"25\" data-field-height-res-320-value=\"28\" data-field-width-res-320-value=\"28\" data-field-container-res-320-value=\"grid\" data-field-top-res-640-value=\"573\" data-field-left-res-640-value=\"65\" data-field-top-res-960-value=\"135\" data-field-left-res-960-value=\"385\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845771801175751694203946750' data-elem-id='175751694203946750' data-elem-type='text' data-field-top-value=\"190\" data-field-left-value=\"515\" data-field-height-value=\"19\" data-field-width-value=\"5\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"30\" data-field-left-res-320-value=\"35\" data-field-height-res-320-value=\"19\" data-field-width-res-320-value=\"5\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-widthunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autowidth\" data-field-top-res-640-value=\"578\" data-field-left-res-640-value=\"75\" data-field-top-res-960-value=\"140\" data-field-left-res-960-value=\"395\"> <div class='tn-atom'field='tn_text_175751694203946750'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">1<\/div><\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845771801');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845784371\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"131\"> <!-- T123 --> <div class=\"t123\"> <div class=\"t-container_100\"> <div class=\"t-width t-width_100\"> <!-- nominify begin --> <script>\ndocument.addEventListener('DOMContentLoaded', function () {\n    \n    let pos = { top: 0, left: 0, x: 0, y: 0 };\n    let blocks = ['#rec1845771801'];\n    \n    blocks.forEach((elem) => {\n        elem = document.querySelector(elem + \" .t396__artboard\");\n        if (elem.querySelector(\"img\") !== null) {\n            elem.querySelector(\"img\").ondragstart = function() { return false; };\n        };\n        elem.style.overflowX = 'auto';\n        elem.style.overflowY = 'hidden';\n        elem.querySelector('.t396__carrier').style.position = 'sticky';\n        elem.style.cursor = 'grab';\n        const mouseDownHandler = function (e) {\n            elem.style.cursor = 'grabbing';\n            elem.style.userSelect = 'none';\n            pos = {\n                left: elem.scrollLeft,\n                x: e.clientX,\n            };\n            document.addEventListener('mousemove', mouseMoveHandler);\n            document.addEventListener('mouseup', mouseUpHandler);\n        };\n        const mouseMoveHandler = function (e) {\n            const dx = e.clientX - pos.x;\n            elem.scrollLeft = pos.left - dx;\n        };\n        const mouseUpHandler = function () {\n            elem.style.cursor = 'grab';\n            elem.style.removeProperty('user-select');\n    \n            document.removeEventListener('mousemove', mouseMoveHandler);\n            document.removeEventListener('mouseup', mouseUpHandler);\n        };\n        elem.addEventListener('mousedown', mouseDownHandler);\n        \n    function scrollHorizontally(e) {\n      e = window.event;\n      var delta = Math.max(-1, Math.min(1, (-(e.deltaY) || 0)));\n      elem.scrollLeft -= (delta * 40);\n    if((delta > 0 && elem.scrollLeft > 0) || (delta < 0 && elem.offsetWidth+elem.scrollLeft < elem.scrollWidth)) {\n        e.preventDefault();\n    };\n  };\n  elem.addEventListener('wheel', scrollHorizontally, false);\n    });\n    \n});\n<\/script> <style>\n   #rec1845771801 .t396__artboard::-webkit-scrollbar {\n      display: none;\n  }\n  #rec1845771801 .t396__artboard {\n      scrollbar-width: none;\n  }\n<\/style> <!-- nominify end --> <\/div> <\/div> <\/div> <\/div> <div id=\"rec1845792891\" class=\"r t-rec t-screenmin-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-min=\"480px\"> <!-- T396 --> <style>#rec1845792891 .t396__artboard {height:138px;background-color:#ffffff;}#rec1845792891 .t396__filter {height:138px;}#rec1845792891 .t396__carrier{height:138px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845792891 .t396__artboard,#rec1845792891 .t396__filter,#rec1845792891 .t396__carrier {height:138px;}#rec1845792891 .t396__filter {}#rec1845792891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845792891 .t396__artboard,#rec1845792891 .t396__filter,#rec1845792891 .t396__carrier {height:138px;}#rec1845792891 .t396__filter {}#rec1845792891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845792891 .t396__artboard,#rec1845792891 .t396__filter,#rec1845792891 .t396__carrier {height:138px;}#rec1845792891 .t396__filter {}#rec1845792891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845792891 .t396__artboard,#rec1845792891 .t396__filter,#rec1845792891 .t396__carrier {height:138px;}#rec1845792891 .t396__filter {}#rec1845792891 .t396__carrier {background-attachment:scroll;}}#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"]{z-index:3;top:0px;;left:calc(50% - 600px + 20px);;width:1160px;height:237px;}#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#f0f0f2;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:959px){#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:639px){#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:479px){#rec1845792891 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;left:calc(50% - 160px + 0px);;width:320px;height:238px;}}#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"]{color:#192032;text-align:center;z-index:3;top:50px;;left:calc(50% - 600px + 537px);;width:auto;height:auto;}#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845792891 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;left:calc(50% - 160px + 98px);;width:125px;height:auto;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845792891\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"138\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"138\" data-artboard-height-res-480=\"138\" data-artboard-height-res-640=\"138\" data-artboard-height-res-960=\"138\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845792891\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845792891\"><\/div> <div class='t396__elem tn-elem tn-elem__18457928911769614652543' data-elem-id='1769614652543' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"20\" data-field-height-value=\"237\" data-field-width-value=\"1160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"238\" data-field-width-res-320-value=\"320\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18457928911769614683111' data-elem-id='1769614683111' data-elem-type='text' data-field-top-value=\"50\" data-field-left-value=\"537\" data-field-height-value=\"43\" data-field-width-value=\"126\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"98\" data-field-width-res-320-value=\"125\"> <div class='tn-atom'field='tn_text_1769614683111'>\u041e\u0442\u0437\u044b\u0432\u044b<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845792891');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845812441\" class=\"r t-rec t-screenmin-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-min=\"480px\"> <!-- T396 --> <style>#rec1845812441 .t396__artboard {height:363px;background-color:#ffffff;}#rec1845812441 .t396__filter {height:363px;}#rec1845812441 .t396__carrier{height:363px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845812441 .t396__artboard,#rec1845812441 .t396__filter,#rec1845812441 .t396__carrier {height:138px;}#rec1845812441 .t396__filter {}#rec1845812441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845812441 .t396__artboard,#rec1845812441 .t396__filter,#rec1845812441 .t396__carrier {height:138px;}#rec1845812441 .t396__filter {}#rec1845812441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845812441 .t396__artboard,#rec1845812441 .t396__filter,#rec1845812441 .t396__carrier {height:138px;}#rec1845812441 .t396__filter {}#rec1845812441 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845812441 .t396__artboard,#rec1845812441 .t396__filter,#rec1845812441 .t396__carrier {height:138px;}#rec1845812441 .t396__filter {}#rec1845812441 .t396__carrier {background-attachment:scroll;}}#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"]{z-index:3;top:-53px;;left:calc(50% - 600px + 20px);;width:1160px;height:416px;}#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#f0f0f2;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:959px){#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:639px){#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;}}@media screen and (max-width:479px){#rec1845812441 .tn-elem[data-elem-id=\"1769614652543\"]{display:table;left:calc(50% - 160px + 0px);;width:320px;height:238px;}}#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"]{z-index:3;top:0px;;left:calc(50% - 600px + 437px);;width:326px;height:298px;}#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:959px){#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:639px){#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:479px){#rec1845812441 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"]{z-index:3;top:15px;;left:calc(50% - 600px + 806px);;width:322px;height:267px;}#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:959px){#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:639px){#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:479px){#rec1845812441 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"]{z-index:3;top:24px;;left:calc(50% - 600px + 80px);;width:314px;height:249px;}#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:959px){#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:639px){#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845812441 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845812441\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"363\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"138\" data-artboard-height-res-480=\"138\" data-artboard-height-res-640=\"138\" data-artboard-height-res-960=\"138\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845812441\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845812441\"><\/div> <div class='t396__elem tn-elem tn-elem__18458124411769614652543' data-elem-id='1769614652543' data-elem-type='shape' data-field-top-value=\"-53\" data-field-left-value=\"20\" data-field-height-value=\"416\" data-field-width-value=\"1160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"238\" data-field-width-res-320-value=\"320\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458124411769614800862' data-elem-id='1769614800862' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"437\" data-field-height-value=\"298\" data-field-width-value=\"326\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6163-3935-4534-a338-656233646166\/image_32.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458124411769614840829000001' data-elem-id='1769614840829000001' data-elem-type='shape' data-field-top-value=\"15\" data-field-left-value=\"806\" data-field-height-value=\"267\" data-field-width-value=\"322\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6265-3238-4164-b263-303130396431\/image_33.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458124411769614863423000002' data-elem-id='1769614863423000002' data-elem-type='shape' data-field-top-value=\"24\" data-field-left-value=\"80\" data-field-height-value=\"249\" data-field-width-value=\"314\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6233-3831-4761-b739-633134396238\/image_31.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845812441');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845827251\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-max=\"480px\"> <!-- T396 --> <style>#rec1845827251 .t396__artboard {height:138px;background-color:#f0f0f2;}#rec1845827251 .t396__filter {height:138px;}#rec1845827251 .t396__carrier{height:138px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845827251 .t396__artboard,#rec1845827251 .t396__filter,#rec1845827251 .t396__carrier {height:138px;}#rec1845827251 .t396__filter {}#rec1845827251 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845827251 .t396__artboard,#rec1845827251 .t396__filter,#rec1845827251 .t396__carrier {height:138px;}#rec1845827251 .t396__filter {}#rec1845827251 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845827251 .t396__artboard,#rec1845827251 .t396__filter,#rec1845827251 .t396__carrier {height:138px;}#rec1845827251 .t396__filter {}#rec1845827251 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845827251 .t396__artboard,#rec1845827251 .t396__filter,#rec1845827251 .t396__carrier {height:123px;}#rec1845827251 .t396__filter {}#rec1845827251 .t396__carrier {background-attachment:scroll;}}#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"]{color:#192032;text-align:center;z-index:3;top:50px;;left:calc(50% - 600px + 537px);;width:auto;height:auto;}#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845827251 .tn-elem[data-elem-id=\"1769614683111\"]{display:table;left:calc(50% - 160px + 98px);;width:125px;height:auto;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845827251\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"138\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"123\" data-artboard-height-res-480=\"138\" data-artboard-height-res-640=\"138\" data-artboard-height-res-960=\"138\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845827251\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845827251\"><\/div> <div class='t396__elem tn-elem tn-elem__18458272511769614683111' data-elem-id='1769614683111' data-elem-type='text' data-field-top-value=\"50\" data-field-left-value=\"537\" data-field-height-value=\"43\" data-field-width-value=\"125\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"98\" data-field-width-res-320-value=\"125\"> <div class='tn-atom'field='tn_text_1769614683111'>\u041e\u0442\u0437\u044b\u0432\u044b<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845827251');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845830191\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\" data-screen-max=\"480px\"> <!-- T396 --> <style>#rec1845830191 .t396__artboard {height:363px;background-color:#f0f0f2;}#rec1845830191 .t396__filter {height:363px;}#rec1845830191 .t396__carrier{height:363px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845830191 .t396__artboard,#rec1845830191 .t396__filter,#rec1845830191 .t396__carrier {height:138px;}#rec1845830191 .t396__filter {}#rec1845830191 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845830191 .t396__artboard,#rec1845830191 .t396__filter,#rec1845830191 .t396__carrier {height:138px;}#rec1845830191 .t396__filter {}#rec1845830191 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845830191 .t396__artboard,#rec1845830191 .t396__filter,#rec1845830191 .t396__carrier {height:138px;}#rec1845830191 .t396__filter {}#rec1845830191 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845830191 .t396__artboard,#rec1845830191 .t396__filter,#rec1845830191 .t396__carrier {height:288px;}#rec1845830191 .t396__filter {}#rec1845830191 .t396__carrier {background-attachment:scroll;}}#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"]{z-index:3;top:0px;;left:calc(50% - 600px + 437px);;width:326px;height:298px;}#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:959px){#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:639px){#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;}}@media screen and (max-width:479px){#rec1845830191 .tn-elem[data-elem-id=\"1769614800862\"]{display:table;top:0px;;left:calc(50% - 160px + 10px);;width:259px;height:237px;}}#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"]{z-index:3;top:15px;;left:calc(50% - 600px + 806px);;width:322px;height:267px;}#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:959px){#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:639px){#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;}}@media screen and (max-width:479px){#rec1845830191 .tn-elem[data-elem-id=\"1769614840829000001\"]{display:table;top:0px;;left:calc(50% - 160px + 588px);;width:280px;height:233px;}}#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"]{z-index:3;top:24px;;left:calc(50% - 600px + 80px);;width:314px;height:249px;}#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:959px){#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:639px){#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845830191 .tn-elem[data-elem-id=\"1769614863423000002\"]{display:table;top:0px;;left:calc(50% - 160px + 279px);;width:298px;height:236px;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845830191\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"363\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"288\" data-artboard-height-res-480=\"138\" data-artboard-height-res-640=\"138\" data-artboard-height-res-960=\"138\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845830191\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845830191\"><\/div> <div class='t396__elem tn-elem tn-elem__18458301911769614800862' data-elem-id='1769614800862' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"437\" data-field-height-value=\"298\" data-field-width-value=\"326\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"237\" data-field-width-res-320-value=\"259\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6163-3935-4534-a338-656233646166\/image_32.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458301911769614840829000001' data-elem-id='1769614840829000001' data-elem-type='shape' data-field-top-value=\"15\" data-field-left-value=\"806\" data-field-height-value=\"267\" data-field-width-value=\"322\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"588\" data-field-height-res-320-value=\"233\" data-field-width-res-320-value=\"280\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6265-3238-4164-b263-303130396431\/image_33.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458301911769614863423000002' data-elem-id='1769614863423000002' data-elem-type='shape' data-field-top-value=\"24\" data-field-left-value=\"80\" data-field-height-value=\"249\" data-field-width-value=\"314\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"279\" data-field-height-res-320-value=\"236\" data-field-width-res-320-value=\"298\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6638-6539-4632-a333-343838343539\/image_31.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845830191');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845838261\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"131\" data-screen-max=\"480px\"> <!-- T123 --> <div class=\"t123\"> <div class=\"t-container_100\"> <div class=\"t-width t-width_100\"> <!-- nominify begin --> <script>\ndocument.addEventListener('DOMContentLoaded', function () {\n    \n    let pos = { top: 0, left: 0, x: 0, y: 0 };\n    let blocks = ['#rec1845830191'];\n    \n    blocks.forEach((elem) => {\n        elem = document.querySelector(elem + \" .t396__artboard\");\n        if (elem.querySelector(\"img\") !== null) {\n            elem.querySelector(\"img\").ondragstart = function() { return false; };\n        };\n        elem.style.overflowX = 'auto';\n        elem.style.overflowY = 'hidden';\n        elem.querySelector('.t396__carrier').style.position = 'sticky';\n        elem.style.cursor = 'grab';\n        const mouseDownHandler = function (e) {\n            elem.style.cursor = 'grabbing';\n            elem.style.userSelect = 'none';\n            pos = {\n                left: elem.scrollLeft,\n                x: e.clientX,\n            };\n            document.addEventListener('mousemove', mouseMoveHandler);\n            document.addEventListener('mouseup', mouseUpHandler);\n        };\n        const mouseMoveHandler = function (e) {\n            const dx = e.clientX - pos.x;\n            elem.scrollLeft = pos.left - dx;\n        };\n        const mouseUpHandler = function () {\n            elem.style.cursor = 'grab';\n            elem.style.removeProperty('user-select');\n    \n            document.removeEventListener('mousemove', mouseMoveHandler);\n            document.removeEventListener('mouseup', mouseUpHandler);\n        };\n        elem.addEventListener('mousedown', mouseDownHandler);\n        \n    function scrollHorizontally(e) {\n      e = window.event;\n      var delta = Math.max(-1, Math.min(1, (-(e.deltaY) || 0)));\n      elem.scrollLeft -= (delta * 40);\n    if((delta > 0 && elem.scrollLeft > 0) || (delta < 0 && elem.offsetWidth+elem.scrollLeft < elem.scrollWidth)) {\n        e.preventDefault();\n    };\n  };\n  elem.addEventListener('wheel', scrollHorizontally, false);\n    });\n    \n});\n<\/script> <style>\n   #rec1845830191 .t396__artboard::-webkit-scrollbar {\n      display: none;\n  }\n  #rec1845830191 .t396__artboard {\n      scrollbar-width: none;\n  }\n<\/style> <!-- nominify end --> <\/div> <\/div> <\/div> <\/div> <div id=\"rec1845843891\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845843891 .t396__artboard {height:2356px;background-color:#ffffff;}#rec1845843891 .t396__filter {height:2356px;}#rec1845843891 .t396__carrier{height:2356px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845843891 .t396__artboard,#rec1845843891 .t396__filter,#rec1845843891 .t396__carrier {height:2276px;}#rec1845843891 .t396__filter {}#rec1845843891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845843891 .t396__artboard,#rec1845843891 .t396__filter,#rec1845843891 .t396__carrier {height:2276px;}#rec1845843891 .t396__filter {}#rec1845843891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845843891 .t396__artboard,#rec1845843891 .t396__filter,#rec1845843891 .t396__carrier {height:2276px;}#rec1845843891 .t396__filter {}#rec1845843891 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845843891 .t396__artboard,#rec1845843891 .t396__filter,#rec1845843891 .t396__carrier {height:2372px;}#rec1845843891 .t396__filter {}#rec1845843891 .t396__carrier {background-attachment:scroll;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"]{color:#192032;text-align:center;z-index:3;top:100px;;left:calc(50% - 600px + 240px);;width:720px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"]{display:table;left:calc(50% - 160px + 2px);;width:317px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615204294\"] .tn-atom{font-size:28px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"]{z-index:3;top:244px;;left:calc(50% - 600px + 60px);;width:433px;height:650px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media (min-width:1200px){#rec1845843891 .tn-elem.t396__elem--anim-hidden[data-elem-id=\"1769615244894\"]{opacity:0;}}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615244894\"]{display:table;top:262px;;left:calc(50% - 160px + 43px);;width:245px;height:368px;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"]{z-index:3;top:302px;;left:calc(50% - 600px + 600px);;width:1px;height:1818px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"] .tn-atom{border-radius:0px 0px 0px 0px;background-color:#a8a8a8;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615318646\"]{display:table;top:656px;;left:calc(50% - 160px + -630px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"]{z-index:3;top:2079px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615309470\"]{display:table;top:2433px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"]{z-index:3;top:1802px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615439216000031\"]{display:table;top:2156px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"]{z-index:3;top:1544px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615426354000030\"]{display:table;top:1898px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"]{z-index:3;top:1270px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615416471000029\"]{display:table;top:1624px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"]{z-index:3;top:1009px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615405452000028\"]{display:table;top:1363px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"]{z-index:3;top:748px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615391408000027\"]{display:table;top:1102px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"]{z-index:3;top:512px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615376241000026\"]{display:table;top:866px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"]{z-index:3;top:276px;;left:calc(50% - 600px + 580px);;width:40px;height:40px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"]{display:table;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"]{display:table;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"]{display:table;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615362446000025\"]{display:table;top:630px;;left:calc(50% - 160px + -650px);;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"]{color:#192032;z-index:3;top:2237px;;left:calc(50% - 600px + 680px);;width:445px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615466950\"]{display:table;top:2254px;;left:calc(50% - 160px + 10px);;width:294px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"]{color:#192032;z-index:3;top:2146px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"]{display:table;top:2181px;;left:calc(50% - 160px + 10px);;width:283px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615520090000033\"] .tn-atom{vertical-align:middle;white-space:normal;font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"]{color:#192032;z-index:3;top:2087px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615506642000032\"]{display:table;top:2142px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"]{color:#192032;z-index:3;top:1960px;;left:calc(50% - 600px + 680px);;width:408px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000060\"]{display:table;top:2026px;;left:calc(50% - 160px + 10px);;width:303px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"]{color:#192032;z-index:3;top:1869px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"]{display:table;top:1944px;;left:calc(50% - 160px + 10px);;width:301px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000061\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"]{color:#192032;z-index:3;top:1810px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615751861000062\"]{display:table;top:1905px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"]{color:#192032;z-index:3;top:1702px;;left:calc(50% - 600px + 680px);;width:408px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000056\"]{display:table;top:1827px;;left:calc(50% - 160px + 10px);;width:304px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"]{color:#192032;z-index:3;top:1611px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"]{display:table;top:1745px;;left:calc(50% - 160px + 10px);;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000057\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"]{color:#192032;z-index:3;top:1552px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615730464000058\"]{display:table;top:1706px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"]{color:#192032;z-index:3;top:1425px;;left:calc(50% - 600px + 680px);;width:408px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000052\"]{display:table;top:1590px;;left:calc(50% - 160px + 10px);;width:301px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"]{color:#192032;z-index:3;top:1334px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"]{display:table;top:1508px;;left:calc(50% - 160px + 10px);;width:295px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000053\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"]{color:#192032;z-index:3;top:1275px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615701749000054\"]{display:table;top:1469px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"]{color:#192032;z-index:3;top:1167px;;left:calc(50% - 600px + 680px);;width:408px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000048\"]{display:table;top:1372px;;left:calc(50% - 160px + 10px);;width:300px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"]{color:#192032;z-index:3;top:1076px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"]{display:table;top:1290px;;left:calc(50% - 160px + 10px);;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000049\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"]{color:#192032;z-index:3;top:1017px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615680382000050\"]{display:table;top:1251px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"]{color:#192032;z-index:3;top:909px;;left:calc(50% - 600px + 680px);;width:408px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000044\"]{display:table;top:1154px;;left:calc(50% - 160px + 10px);;width:310px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"]{color:#192032;z-index:3;top:818px;;left:calc(50% - 600px + 680px);;width:330px;height:76px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"] .tn-atom{vertical-align:middle;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"]{display:table;top:1072px;;left:calc(50% - 160px + 10px);;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000045\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"]{color:#192032;z-index:3;top:759px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615648384000046\"]{display:table;top:1033px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"]{color:#192032;z-index:3;top:632px;;left:calc(50% - 600px + 680px);;width:408px;height:57px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000040\"]{display:table;top:917px;;left:calc(50% - 160px + 10px);;width:304px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"]{color:#192032;z-index:3;top:579px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"]{display:table;top:873px;;left:calc(50% - 160px + 10px);;width:236px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000041\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"]{color:#192032;z-index:3;top:520px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615582593000042\"]{display:table;top:834px;;left:calc(50% - 160px + 10px);;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"]{color:#192032;z-index:3;top:393px;;left:calc(50% - 600px + 680px);;width:408px;height:57px;}#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"] .tn-atom{vertical-align:middle;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557655000036\"]{display:table;top:718px;;left:calc(50% - 160px + 10px);;width:304px;height:auto;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"]{color:#192032;z-index:3;top:340px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:32px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"]{display:table;top:674px;;left:calc(50% - 160px + 10px);;width:191px;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000037\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"]{color:#192032;z-index:3;top:281px;;left:calc(50% - 600px + 680px);;width:auto;height:auto;}#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845843891 .tn-elem[data-elem-id=\"1769615557656000038\"]{display:table;top:635px;;left:calc(50% - 160px + 10px);;height:auto;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845843891\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"2356\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"2372\" data-artboard-height-res-480=\"2276\" data-artboard-height-res-640=\"2276\" data-artboard-height-res-960=\"2276\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845843891\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845843891\"><\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615204294' data-elem-id='1769615204294' data-elem-type='text' data-field-top-value=\"100\" data-field-left-value=\"240\" data-field-height-value=\"129\" data-field-width-value=\"720\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"2\" data-field-width-res-320-value=\"317\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769615204294'>\u041f\u043e\u0448\u0430\u0433\u043e\u0432\u0430\u044f \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u0430 \u0432\u0435\u0434\u0451\u0442 \u0442\u0435\u0431\u044f \u0437\u0430&nbsp;\u0440\u0443\u043a\u0443 \u0438&nbsp;\u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u0440\u0430\u0437\u043e\u0431\u0440\u0430\u0442\u044c\u0441\u044f \u0432&nbsp;\u0441\u0432\u043e\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615244894' data-elem-id='1769615244894' data-elem-type='shape' data-field-top-value=\"244\" data-field-left-value=\"60\" data-field-height-value=\"650\" data-field-width-value=\"433\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-animate-sbs-event=\"scroll\" data-animate-sbs-trg=\"0\" data-animate-sbs-trgofst=\"40\" data-animate-sbs-opts=\"[{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'di':'0','dd':'0','fi':'0'},{'mx':0,'my':0,'sx':1,'sy':1,'op':1,'ro':0,'di':1362,'dd':'0','fi':'fixed'}]\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"262\" data-field-left-res-320-value=\"43\" data-field-height-res-320-value=\"368\" data-field-width-res-320-value=\"245\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3961-6531-4161-b166-393566386666\/image_36.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615318646' data-elem-id='1769615318646' data-elem-type='shape' data-field-top-value=\"302\" data-field-left-value=\"600\" data-field-height-value=\"1818\" data-field-width-value=\"1\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"656\" data-field-left-res-320-value=\"-630\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615309470' data-elem-id='1769615309470' data-elem-type='shape' data-field-top-value=\"2079\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"2433\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615439216000031' data-elem-id='1769615439216000031' data-elem-type='shape' data-field-top-value=\"1802\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"2156\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615426354000030' data-elem-id='1769615426354000030' data-elem-type='shape' data-field-top-value=\"1544\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1898\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615416471000029' data-elem-id='1769615416471000029' data-elem-type='shape' data-field-top-value=\"1270\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1624\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615405452000028' data-elem-id='1769615405452000028' data-elem-type='shape' data-field-top-value=\"1009\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1363\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615391408000027' data-elem-id='1769615391408000027' data-elem-type='shape' data-field-top-value=\"748\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"1102\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615376241000026' data-elem-id='1769615376241000026' data-elem-type='shape' data-field-top-value=\"512\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"866\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615362446000025' data-elem-id='1769615362446000025' data-elem-type='shape' data-field-top-value=\"276\" data-field-left-value=\"580\" data-field-height-value=\"40\" data-field-width-value=\"40\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"630\" data-field-left-res-320-value=\"-650\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6465-3263-4632-b561-376264336430\/Frame_278.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615466950' data-elem-id='1769615466950' data-elem-type='text' data-field-top-value=\"2237\" data-field-left-value=\"680\" data-field-height-value=\"19\" data-field-width-value=\"445\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"2254\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"294\"> <div class='tn-atom'field='tn_text_1769615466950'>\u041f\u043e\u0434\u0432\u0435\u0434\u0435\u043d\u0438\u0435 \u0438\u0442\u043e\u0433\u043e\u0432 \u0438 \u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438 \u043f\u043e \u0434\u0430\u043b\u044c\u043d\u0435\u0439\u0448\u0435\u043c\u0443 \u043f\u0443\u0442\u0438.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615520090000033' data-elem-id='1769615520090000033' data-elem-type='text' data-field-top-value=\"2146\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"2181\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"283\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615520090000033'>\u00ab\u0427\u0442\u043e \u0442\u0435\u0431\u0435 \u0434\u0435\u043b\u0430\u0442\u044c \u0434\u0430\u043b\u044c\u0448\u0435?\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615506642000032' data-elem-id='1769615506642000032' data-elem-type='text' data-field-top-value=\"2087\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"70\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"2142\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615506642000032'>\u0427\u0430\u0441\u0442\u044c 8<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615751861000060' data-elem-id='1769615751861000060' data-elem-type='text' data-field-top-value=\"1960\" data-field-left-value=\"680\" data-field-height-value=\"57\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"2026\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"303\"> <div class='tn-atom'field='tn_text_1769615751861000060'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u0443\u0432\u0438\u0434\u0435\u0442\u044c \u0446\u0435\u043d\u043d\u043e\u0441\u0442\u0438, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0442\u044b&nbsp;\u043f\u0440\u0438\u0432\u043d\u043e\u0441\u0438\u0448\u044c \u0432&nbsp;\u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f, \u0437\u0430&nbsp;\u0441\u0447\u0435\u0442 \u044d\u0442\u043e\u0433\u043e&nbsp;\u2014 \u043f\u043e\u0434\u043d\u044f\u0442\u044c \u0441\u0430\u043c\u043e\u043e\u0446\u0435\u043d\u043a\u0443 \u0438&nbsp;\u043e\u0449\u0443\u0449\u0435\u043d\u0438\u0435 \u0441\u0430\u043c\u043e\u0446\u0435\u043d\u043d\u043e\u0441\u0442\u0438.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615751861000061' data-elem-id='1769615751861000061' data-elem-type='text' data-field-top-value=\"1869\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"1944\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"301\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615751861000061'>\u00ab\u041a\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u0442\u044b \u0434\u043e\u0441\u0442\u043e\u0439\u043d\u0430\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615751861000062' data-elem-id='1769615751861000062' data-elem-type='text' data-field-top-value=\"1810\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"69\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1905\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615751861000062'>\u0427\u0430\u0441\u0442\u044c 7<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615730464000056' data-elem-id='1769615730464000056' data-elem-type='text' data-field-top-value=\"1702\" data-field-left-value=\"680\" data-field-height-value=\"38\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1827\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"304\"> <div class='tn-atom'field='tn_text_1769615730464000056'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u0442\u044b \u0432\u044b\u0431\u0440\u0430\u043b\u0430 \u0434\u043b\u044f \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u043d\u043e\u0433\u043e \u043c\u0443\u0436\u0447\u0438\u043d\u0443.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615730464000057' data-elem-id='1769615730464000057' data-elem-type='text' data-field-top-value=\"1611\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"1745\" data-field-left-res-320-value=\"10\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615730464000057'>\u00ab\u041f\u043e\u0447\u0435\u043c\u0443 \u0442\u044b \u0432 \u044d\u0442\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615730464000058' data-elem-id='1769615730464000058' data-elem-type='text' data-field-top-value=\"1552\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"70\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1706\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615730464000058'>\u0427\u0430\u0441\u0442\u044c 6<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615701749000052' data-elem-id='1769615701749000052' data-elem-type='text' data-field-top-value=\"1425\" data-field-left-value=\"680\" data-field-height-value=\"57\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1590\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"301\"> <div class='tn-atom'field='tn_text_1769615701749000052'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u0440\u0430\u0437\u043e\u0431\u0440\u0430\u0442\u044c\u0441\u044f, \u043a\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u043d\u0430&nbsp;\u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u0442\u044b&nbsp;\u0445\u043e\u0447\u0435\u0448\u044c \u0438&nbsp;\u043f\u043e\u0434\u0445\u043e\u0434\u044f\u0442&nbsp;\u043b\u0438 \u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0438\u0435 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u043f\u043e\u0434 \u0436\u0435\u043b\u0430\u0435\u043c\u044b\u0439 \u043e\u0431\u0440\u0430\u0437.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615701749000053' data-elem-id='1769615701749000053' data-elem-type='text' data-field-top-value=\"1334\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"1508\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"295\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615701749000053'>\u00ab\u041a\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u0442\u044b \u0445\u043e\u0447\u0435\u0448\u044c\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615701749000054' data-elem-id='1769615701749000054' data-elem-type='text' data-field-top-value=\"1275\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"70\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1469\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615701749000054'>\u0427\u0430\u0441\u0442\u044c 5<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615680382000048' data-elem-id='1769615680382000048' data-elem-type='text' data-field-top-value=\"1167\" data-field-left-value=\"680\" data-field-height-value=\"38\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1372\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\"> <div class='tn-atom'field='tn_text_1769615680382000048'>\u041f\u043e\u043c\u043e\u0449\u044c \u0441&nbsp;\u0442\u0435\u043c, \u0447\u0442\u043e\u0431\u044b \u043f\u0435\u0440\u0435\u0441\u0442\u0430\u0442\u044c \u0438\u0434\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c (\u0438&nbsp;\u0434\u0435\u043c\u043e\u043d\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c) \u043c\u0443\u0436\u0447\u0438\u043d\u0443.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615680382000049' data-elem-id='1769615680382000049' data-elem-type='text' data-field-top-value=\"1076\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"1290\" data-field-left-res-320-value=\"10\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615680382000049'>\u00ab\u200e\u0420\u0435\u0430\u043b\u044c\u043d\u044b\u0439 \u0432\u0437\u0433\u043b\u044f\u0434 \u043d\u0430&nbsp;\u043f\u0430\u0440\u0442\u043d\u0451\u0440\u0430\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615680382000050' data-elem-id='1769615680382000050' data-elem-type='text' data-field-top-value=\"1017\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"71\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1251\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615680382000050'>\u0427\u0430\u0441\u0442\u044c 4<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615648384000044' data-elem-id='1769615648384000044' data-elem-type='text' data-field-top-value=\"909\" data-field-left-value=\"680\" data-field-height-value=\"38\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"1154\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"310\"> <div class='tn-atom'field='tn_text_1769615648384000044'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u043c\u044f\u0433\u043a\u043e \u043f\u0435\u0440\u0435\u0440\u0430\u0431\u043e\u0442\u0430\u0442\u044c \u043d\u0430\u043a\u043e\u043f\u0438\u0432\u0448\u0438\u0439\u0441\u044f \u043d\u0435\u0433\u0430\u0442\u0438\u0432 \u0438 \u0432\u0435\u0440\u043d\u0443\u0442\u044c \u0432\u043d\u0443\u0442\u0440\u0435\u043d\u043d\u0435\u0435 \u0440\u0430\u0432\u043d\u043e\u0432\u0435\u0441\u0438\u0435.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615648384000045' data-elem-id='1769615648384000045' data-elem-type='text' data-field-top-value=\"818\" data-field-left-value=\"680\" data-field-height-value=\"76\" data-field-width-value=\"330\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"1072\" data-field-left-res-320-value=\"10\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615648384000045'>\u00ab\u200e\u042d\u043c\u043e\u0446\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u0430\u044f \u0441\u0442\u0430\u0431\u0438\u043b\u0438\u0437\u0430\u0446\u0438\u044f\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615648384000046' data-elem-id='1769615648384000046' data-elem-type='text' data-field-top-value=\"759\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"70\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"1033\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615648384000046'>\u0427\u0430\u0441\u0442\u044c 3<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615582593000040' data-elem-id='1769615582593000040' data-elem-type='text' data-field-top-value=\"632\" data-field-left-value=\"680\" data-field-height-value=\"57\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"917\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"304\"> <div class='tn-atom'field='tn_text_1769615582593000040'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u0443\u0437\u043d\u0430\u0442\u044c \u0441\u0432\u043e\u0435 \u043d\u0430\u0441\u0442\u043e\u044f\u0449\u0435\u0435 \u044d\u043c\u043e\u0446\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u043e\u0435 \u0441\u043e\u0441\u0442\u043e\u044f\u043d\u0438\u0435 \u0438 \u0447\u0435\u0433\u043e \u0432 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f\u0445 \u0441\u0435\u0439\u0447\u0430\u0441 \u0431\u043e\u043b\u044c\u0448\u0435: \u0445\u043e\u0440\u043e\u0448\u0435\u0433\u043e \u0438\u043b\u0438 \u043f\u043b\u043e\u0445\u043e\u0433\u043e.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615582593000041' data-elem-id='1769615582593000041' data-elem-type='text' data-field-top-value=\"579\" data-field-left-value=\"680\" data-field-height-value=\"38\" data-field-width-value=\"314\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"873\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"236\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615582593000041'>\u00ab\u0422\u0440\u0435\u043a\u0435\u0440 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615582593000042' data-elem-id='1769615582593000042' data-elem-type='text' data-field-top-value=\"520\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"70\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"834\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615582593000042'>\u0427\u0430\u0441\u0442\u044c 2<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615557655000036' data-elem-id='1769615557655000036' data-elem-type='text' data-field-top-value=\"393\" data-field-left-value=\"680\" data-field-height-value=\"57\" data-field-width-value=\"408\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"718\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"76\" data-field-width-res-320-value=\"304\"> <div class='tn-atom'field='tn_text_1769615557655000036'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430&nbsp;\u0441\u0432\u043e\u0438 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441\u043e&nbsp;\u0441\u0442\u043e\u0440\u043e\u043d\u044b \u0438&nbsp;\u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a \u043d\u0430&nbsp;\u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u043e\u043d\u0438 \u0432\u044b\u0433\u043b\u044f\u0434\u044f\u0442, \u0447\u0442\u043e \u0432&nbsp;\u043d\u0438\u0445 \u0435\u0441\u0442\u044c, \u0430&nbsp;\u0447\u0435\u0433\u043e \u043d\u0435&nbsp;\u0434\u043e\u0441\u0442\u0430\u0435\u0442.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615557656000037' data-elem-id='1769615557656000037' data-elem-type='text' data-field-top-value=\"340\" data-field-left-value=\"680\" data-field-height-value=\"38\" data-field-width-value=\"255\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"32\" data-field-top-res-320-value=\"674\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"191\" data-field-fontsize-res-320-value=\"24\"> <div class='tn-atom'field='tn_text_1769615557656000037'>\u00ab\u200e\u0413\u0434\u0435 \u0442\u044b \u0441\u0435\u0439\u0447\u0430\u0441?\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458438911769615557656000038' data-elem-id='1769615557656000038' data-elem-type='text' data-field-top-value=\"281\" data-field-left-value=\"680\" data-field-height-value=\"24\" data-field-width-value=\"66\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"635\" data-field-left-res-320-value=\"10\"> <div class='tn-atom'field='tn_text_1769615557656000038'>\u0427\u0430\u0441\u0442\u044c 1<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845843891');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845894861\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845894861 .t396__artboard {height:457px;background-color:#ffffff;}#rec1845894861 .t396__filter {height:457px;}#rec1845894861 .t396__carrier{height:457px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845894861 .t396__artboard,#rec1845894861 .t396__filter,#rec1845894861 .t396__carrier {height:457px;}#rec1845894861 .t396__filter {}#rec1845894861 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845894861 .t396__artboard,#rec1845894861 .t396__filter,#rec1845894861 .t396__carrier {height:457px;}#rec1845894861 .t396__filter {}#rec1845894861 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845894861 .t396__artboard,#rec1845894861 .t396__filter,#rec1845894861 .t396__carrier {height:457px;}#rec1845894861 .t396__filter {}#rec1845894861 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845894861 .t396__artboard,#rec1845894861 .t396__filter,#rec1845894861 .t396__carrier {height:979px;}#rec1845894861 .t396__filter {}#rec1845894861 .t396__carrier {background-attachment:scroll;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"]{z-index:3;top:0px;;left:calc(50% - 600px + 420px);;width:373px;height:457px;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"]{display:table;top:145px;;left:calc(50% - 480px + 330px);;width:300px;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"]{display:table;top:156px;;left:calc(50% - 320px + 330px);;width:300px;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"]{display:table;top:156px;;left:calc(50% - 240px + 330px);;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000004\"]{display:table;top:179px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"]{z-index:3;top:339px;;left:calc(50% - 600px + 435px);;width:343px;height:103px;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"]{display:table;top:439px;;left:calc(50% - 480px + 345px);;width:266px;height:148px;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"]{display:table;top:450px;;left:calc(50% - 320px + 345px);;width:270px;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"]{display:table;top:450px;;left:calc(50% - 240px + 345px);;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034706000006\"]{display:table;top:442px;;left:calc(50% - 160px + 10px);;width:300px;height:117px;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"]{color:#192032;z-index:3;top:354px;;left:calc(50% - 600px + 450px);;width:300px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"]{display:table;top:454px;;left:calc(50% - 480px + 360px);;width:222px;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"]{display:table;top:465px;;left:calc(50% - 320px + 360px);;width:219px;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"]{display:table;top:465px;;left:calc(50% - 240px + 360px);;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"]{display:table;top:455px;;left:calc(50% - 160px + 25px);;width:295px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000007\"] .tn-atom{font-size:23px;background-size:cover;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"]{color:#192032;z-index:3;top:393px;;left:calc(50% - 600px + 450px);;width:311px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"]{display:table;top:522px;;left:calc(50% - 480px + 362px);;width:257px;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"]{display:table;top:533px;;left:calc(50% - 320px + 362px);;width:253px;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"]{display:table;top:533px;;left:calc(50% - 240px + 362px);;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000008\"]{display:table;top:493px;;left:calc(50% - 160px + 27px);;width:270px;height:auto;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"]{z-index:3;top:0px;;left:calc(50% - 600px + 807px);;width:373px;height:457px;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"] .tn-atom{border-radius:30px 30px 30px 30px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"]{display:table;top:145px;;left:calc(50% - 480px + 650px);;width:300px;height:457px;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"]{display:table;top:633px;;left:calc(50% - 320px + 10px);;width:300px;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"]{display:table;top:633px;;left:calc(50% - 240px + 10px);;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000010\"]{display:table;top:589px;;left:calc(50% - 160px + 0px);;width:320px;height:390px;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"]{z-index:3;top:333px;;left:calc(50% - 600px + 822px);;width:343px;height:103px;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"]{display:table;top:467px;;left:calc(50% - 480px + 665px);;width:270px;height:120px;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"]{display:table;top:955px;;left:calc(50% - 320px + 25px);;width:270px;height:120px;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"]{display:table;top:955px;;left:calc(50% - 240px + 25px);;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000012\"]{display:table;top:843px;;left:calc(50% - 160px + 10px);;width:300px;height:121px;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"]{color:#192032;z-index:3;top:348px;;left:calc(50% - 600px + 837px);;width:auto;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"]{display:table;top:482px;;left:calc(50% - 480px + 680px);;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"]{display:table;top:970px;;left:calc(50% - 320px + 40px);;width:128px;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"]{display:table;top:970px;;left:calc(50% - 240px + 40px);;width:266px;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000013\"]{display:table;top:858px;;left:calc(50% - 160px + 25px);;width:266px;height:auto;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"]{color:#192032;z-index:3;top:387px;;left:calc(50% - 600px + 839px);;width:315px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"]{display:table;top:521px;;left:calc(50% - 480px + 682px);;width:246px;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"]{display:table;top:1009px;;left:calc(50% - 320px + 40px);;width:236px;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"]{display:table;top:1009px;;left:calc(50% - 240px + 40px);;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"]{display:table;top:897px;;left:calc(50% - 160px + 27px);;width:270px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616034707000014\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"]{color:#192032;z-index:3;top:106px;;left:calc(50% - 600px + 20px);;width:343px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"] .tn-atom{vertical-align:middle;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"]{display:table;top:83px;;left:calc(50% - 160px + 10px);;width:300px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769615986669000001\"] .tn-atom{font-size:18px;background-size:cover;}}#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"]{color:#192032;z-index:3;top:0px;;left:calc(50% - 600px + 20px);;width:343px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"]{display:table;height:auto;}}@media screen and (max-width:959px){#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"]{display:table;height:auto;}}@media screen and (max-width:639px){#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"]{display:table;left:calc(50% - 160px + 10px);;width:267px;height:auto;}#rec1845894861 .tn-elem[data-elem-id=\"1769616001271000002\"] .tn-atom{font-size:28px;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845894861\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"457\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"979\" data-artboard-height-res-480=\"457\" data-artboard-height-res-640=\"457\" data-artboard-height-res-960=\"457\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845894861\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845894861\"><\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034706000004' data-elem-id='1769616034706000004' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"420\" data-field-height-value=\"457\" data-field-width-value=\"373\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"179\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"156\" data-field-left-res-480-value=\"330\" data-field-top-res-640-value=\"156\" data-field-left-res-640-value=\"330\" data-field-width-res-640-value=\"300\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"145\" data-field-left-res-960-value=\"330\" data-field-width-res-960-value=\"300\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3932-3037-4337-b866-653666326161\/Rectangle_18.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034706000006' data-elem-id='1769616034706000006' data-elem-type='shape' data-field-top-value=\"339\" data-field-left-value=\"435\" data-field-height-value=\"103\" data-field-width-value=\"343\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"442\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"117\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"450\" data-field-left-res-480-value=\"345\" data-field-top-res-640-value=\"450\" data-field-left-res-640-value=\"345\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"439\" data-field-left-res-960-value=\"345\" data-field-height-res-960-value=\"148\" data-field-width-res-960-value=\"266\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000007' data-elem-id='1769616034707000007' data-elem-type='text' data-field-top-value=\"354\" data-field-left-value=\"450\" data-field-height-value=\"29\" data-field-width-value=\"300\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"455\" data-field-left-res-320-value=\"25\" data-field-width-res-320-value=\"295\" data-field-fontsize-res-320-value=\"23\" data-field-top-res-480-value=\"465\" data-field-left-res-480-value=\"360\" data-field-top-res-640-value=\"465\" data-field-left-res-640-value=\"360\" data-field-height-res-640-value=\"59\" data-field-width-res-640-value=\"219\" data-field-top-res-960-value=\"454\" data-field-left-res-960-value=\"360\" data-field-height-res-960-value=\"58\" data-field-width-res-960-value=\"222\"> <div class='tn-atom'field='tn_text_1769616034707000007'>\u00ab\u0411\u0435\u0437\u0443\u0441\u043b\u043e\u0432\u043d\u0430\u044f \u0446\u0435\u043d\u043d\u043e\u0441\u0442\u044c\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000008' data-elem-id='1769616034707000008' data-elem-type='text' data-field-top-value=\"393\" data-field-left-value=\"450\" data-field-height-value=\"34\" data-field-width-value=\"311\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"493\" data-field-left-res-320-value=\"27\" data-field-width-res-320-value=\"270\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"533\" data-field-left-res-480-value=\"362\" data-field-top-res-640-value=\"533\" data-field-left-res-640-value=\"362\" data-field-width-res-640-value=\"253\" data-field-top-res-960-value=\"522\" data-field-left-res-960-value=\"362\" data-field-width-res-960-value=\"257\"> <div class='tn-atom'field='tn_text_1769616034707000008'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u043d\u044f\u0442\u044c, \u0447\u0442\u043e&nbsp;\u0441&nbsp;\u0442\u043e\u0431\u043e\u0439 \u0432\u0441\u0451&nbsp;\u0432&nbsp;\u043f\u043e\u0440\u044f\u0434\u043a\u0435 \u0438&nbsp;\u0431\u043e\u043b\u044c\u0448\u0435 \u043d\u0435&nbsp;\u0437\u0430\u0432\u0438\u0441\u0435\u0442\u044c \u043e\u0442&nbsp;\u0447\u0443\u0436\u043e\u0433\u043e \u043e\u0434\u043e\u0431\u0440\u0435\u043d\u0438\u044f.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000010' data-elem-id='1769616034707000010' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"807\" data-field-height-value=\"457\" data-field-width-value=\"373\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"589\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"390\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"633\" data-field-left-res-480-value=\"10\" data-field-top-res-640-value=\"633\" data-field-left-res-640-value=\"10\" data-field-width-res-640-value=\"300\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"145\" data-field-left-res-960-value=\"650\" data-field-height-res-960-value=\"457\" data-field-width-res-960-value=\"300\" data-field-container-res-960-value=\"grid\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3764-3430-4565-b533-353535333961\/Rectangle_19.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000012' data-elem-id='1769616034707000012' data-elem-type='shape' data-field-top-value=\"333\" data-field-left-value=\"822\" data-field-height-value=\"103\" data-field-width-value=\"343\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"843\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"121\" data-field-width-res-320-value=\"300\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"955\" data-field-left-res-480-value=\"25\" data-field-top-res-640-value=\"955\" data-field-left-res-640-value=\"25\" data-field-height-res-640-value=\"120\" data-field-width-res-640-value=\"270\" data-field-widthmode-res-640-value=\"fixed\" data-field-heightmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"467\" data-field-left-res-960-value=\"665\" data-field-height-res-960-value=\"120\" data-field-width-res-960-value=\"270\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000013' data-elem-id='1769616034707000013' data-elem-type='text' data-field-top-value=\"348\" data-field-left-value=\"837\" data-field-height-value=\"29\" data-field-width-value=\"266\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"858\" data-field-left-res-320-value=\"25\" data-field-width-res-320-value=\"266\" data-field-top-res-480-value=\"970\" data-field-left-res-480-value=\"40\" data-field-width-res-480-value=\"266\" data-field-top-res-640-value=\"970\" data-field-left-res-640-value=\"40\" data-field-height-res-640-value=\"29\" data-field-width-res-640-value=\"128\" data-field-top-res-960-value=\"482\" data-field-left-res-960-value=\"680\"> <div class='tn-atom'field='tn_text_1769616034707000013'>\u00ab\u0423\u0441\u0442\u0440\u0430\u043d\u0435\u043d\u0438\u0435 \u043d\u0435\u0433\u0430\u0442\u0438\u0432\u0430\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616034707000014' data-elem-id='1769616034707000014' data-elem-type='text' data-field-top-value=\"387\" data-field-left-value=\"839\" data-field-height-value=\"34\" data-field-width-value=\"315\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"897\" data-field-left-res-320-value=\"27\" data-field-height-res-320-value=\"34\" data-field-width-res-320-value=\"270\" data-field-container-res-320-value=\"grid\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-widthmode-res-320-value=\"fixed\" data-field-top-res-480-value=\"1009\" data-field-left-res-480-value=\"40\" data-field-top-res-640-value=\"1009\" data-field-left-res-640-value=\"40\" data-field-height-res-640-value=\"51\" data-field-width-res-640-value=\"236\" data-field-top-res-960-value=\"521\" data-field-left-res-960-value=\"682\" data-field-width-res-960-value=\"246\"> <div class='tn-atom'field='tn_text_1769616034707000014'>\u041f\u043e\u043c\u043e\u0436\u0435\u0442 \u043e\u0442\u043f\u0443\u0441\u0442\u0438\u0442\u044c \u043b\u0438\u0448\u043d\u0438\u0435 \u044d\u043c\u043e\u0446\u0438\u0438 \u0438 \u043c\u044f\u0433\u043a\u043e \u043f\u0435\u0440\u0435\u043a\u043b\u044e\u0447\u0438\u0442\u044c\u0441\u044f \u0441 \u043f\u043b\u043e\u0445\u043e\u0433\u043e \u043d\u0430 \u0445\u043e\u0440\u043e\u0448\u0435\u0435.<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769615986669000001' data-elem-id='1769615986669000001' data-elem-type='text' data-field-top-value=\"106\" data-field-left-value=\"20\" data-field-height-value=\"87\" data-field-width-value=\"343\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"83\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"300\" data-field-fontsize-res-320-value=\"18\"> <div class='tn-atom'field='tn_text_1769615986669000001'>\u0427\u0442\u043e\u0431\u044b&nbsp;\u043f\u043e\u043c\u043e\u0447\u044c \u0442\u0435\u0431\u0435 \u0441\u0442\u0430\u0431\u0438\u043b\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u044d\u043c\u043e\u0446\u0438\u0438 \u0438&nbsp;\u043f\u043e\u0432\u044b\u0441\u0438\u0442\u044c \u0441\u0430\u043c\u043e\u043e\u0446\u0435\u043d\u043a\u0443<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18458948611769616001271000002' data-elem-id='1769616001271000002' data-elem-type='text' data-field-top-value=\"0\" data-field-left-value=\"20\" data-field-height-value=\"86\" data-field-width-value=\"343\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-left-res-320-value=\"10\" data-field-width-res-320-value=\"267\" data-field-fontsize-res-320-value=\"28\"> <div class='tn-atom'field='tn_text_1769616001271000002'>\u0411\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u0439 \u0431\u043e\u043d\u0443\u0441: 2 \u043c\u0435\u0434\u0438\u0442\u0430\u0446\u0438\u0438<\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845894861');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1846447811\" class=\"r t-rec\" style=\" \" data-record-type=\"215\"> <a name=\"kupit\" style=\"font-size:0;\"><\/a> <\/div> <div id=\"rec1845904801\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845904801 .t396__artboard {height:642px;background-color:#ffffff;}#rec1845904801 .t396__filter {height:642px;}#rec1845904801 .t396__carrier{height:642px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845904801 .t396__artboard,#rec1845904801 .t396__filter,#rec1845904801 .t396__carrier {height:702px;}#rec1845904801 .t396__filter {}#rec1845904801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845904801 .t396__artboard,#rec1845904801 .t396__filter,#rec1845904801 .t396__carrier {height:1031px;}#rec1845904801 .t396__filter {}#rec1845904801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845904801 .t396__artboard,#rec1845904801 .t396__filter,#rec1845904801 .t396__carrier {height:1031px;}#rec1845904801 .t396__filter {}#rec1845904801 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845904801 .t396__artboard,#rec1845904801 .t396__filter,#rec1845904801 .t396__carrier {height:722px;}#rec1845904801 .t396__filter {}#rec1845904801 .t396__carrier {background-attachment:scroll;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"]{z-index:3;top:100px;;left:calc(50% - 600px + 20px);;width:1160px;height:542px;}#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"] .tn-atom{border-radius:30px 30px 30px 30px;background-color:#ddecff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:940px;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"]{display:table;top:80px;;left:calc(50% - 320px + 10px);;width:620px;height:871px;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"]{display:table;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539253160\"]{display:table;top:50px;;left:calc(50% - 160px + 0px);;width:320px;height:672px;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"]{z-index:3;top:100px;;left:calc(50% - 600px + 20px);;width:1160px;height:542px;}#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"] .tn-atom{border-radius:30px 30px 30px 30px;background-image:linear-gradient(0.06turn,rgba(255,255,255,0) 0%,rgba(255,255,255,1) 49%,rgba(255,255,255,0) 100%);border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"]{display:table;top:80px;;left:calc(50% - 480px + 10px);;width:940px;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"]{display:table;top:80px;;left:calc(50% - 320px + 10px);;width:620px;height:871px;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"]{display:table;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539670550\"]{display:table;top:50px;;left:calc(50% - 160px + 0px);;width:320px;height:672px;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"]{color:#192032;z-index:3;top:289px;;left:calc(50% - 600px + 63px);;width:357px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"] .tn-atom{vertical-align:middle;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:600;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"]{display:table;top:221px;;left:calc(50% - 480px + 50px);;width:378px;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"]{display:table;top:221px;;left:calc(50% - 320px + 50px);;width:521px;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"]{display:table;top:240px;;left:calc(50% - 160px + 30px);;width:270px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542539894590\"] .tn-atom{font-size:16px;background-size:cover;}}#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"]{color:#192032;z-index:3;top:328px;;left:calc(50% - 600px + 63px);;width:357px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"] .tn-atom{vertical-align:middle;color:#192032;font-size:20px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"]{display:table;top:221px;;left:calc(50% - 480px + 50px);;width:378px;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"]{display:table;top:221px;;left:calc(50% - 320px + 50px);;width:521px;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"]{display:table;top:279px;;left:calc(50% - 160px + 30px);;width:270px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"1769616232148000001\"] .tn-atom{font-size:16px;background-size:cover;}}#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"]{color:#838383;z-index:3;top:431px;;left:calc(50% - 600px + 193px);;width:auto;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#838383;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"]{display:table;top:425px;;left:calc(50% - 480px + 206px);;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"]{display:table;top:377px;;left:calc(50% - 320px + 206px);;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"]{display:table;top:394px;;left:calc(50% - 160px + 106px);;width:40px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"1769616293208000002\"] .tn-atom{font-size:16px;background-size:cover;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"]{color:#3f89c4;z-index:3;top:425px;;left:calc(50% - 600px + 60px);;width:auto;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#3f89c4;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"]{display:table;top:419px;;left:calc(50% - 480px + 50px);;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"]{display:table;top:371px;;left:calc(50% - 320px + 50px);;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"]{display:table;top:388px;;left:calc(50% - 160px + 30px);;width:66px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540550980\"] .tn-atom{font-size:26px;background-size:cover;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"]{color:#192032;z-index:3;top:140px;;left:calc(50% - 600px + 60px);;width:574px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"]{display:table;top:120px;;left:calc(50% - 480px + 50px);;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"]{display:table;top:120px;;left:calc(50% - 320px + 50px);;width:480px;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"]{display:table;top:80px;;left:calc(50% - 160px + 30px);;width:264px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540850890\"] .tn-atom{font-size:24px;background-size:cover;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"]{color:#ffffff;text-align:center;z-index:3;top:498px;;left:calc(50% - 600px + 58px);;width:283px;height:68px;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom{color:#ffffff;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.55;font-weight:600;border-radius:10px 10px 10px 10px;background-position:center center;--t396-speedhover:0.2s;transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-bgcolor-color:#3f89c4;--t396-bgcolor-image:none;--t396-bgcolor-hover-color:#2161af;--t396-bgcolor-hover-image:none;background-color:var(--t396-bgcolor-color,transparent);-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom::after{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-content{column-gap:10px;padding:0px 0px 0px 0px;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-text{transition:color var(--t396-speedhover,0s) ease-in-out;color:#ffffff;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover::after{opacity:0;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{color:#ffffff;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover .tn-atom__button-text{color:#ffffff;}}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"]{display:block;top:492px;;left:calc(50% - 480px + 48px);;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom::after{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover::after{opacity:0;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"]{display:block;top:444px;;left:calc(50% - 320px + 48px);;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom::after{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover::after{opacity:0;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"]{display:block;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom{background-color:var(--t396-bgcolor-color,transparent);}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom::after{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover::after{opacity:0;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"]{display:block;top:439px;;left:calc(50% - 160px + 30px);;width:261px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom{font-size:14px;background-size:cover;background-color:var(--t396-bgcolor-color,transparent);}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom::after{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::before{display:none;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom .tn-atom__button-border::after{display:none;}@media (hover),(min-width:0\u0000){#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover::after{opacity:0;}#rec1845904801 .tn-elem[data-elem-id=\"175757542541476330\"] .tn-atom:hover{animation-name:none;background-color:var(--t396-bgcolor-hover-color,var(--t396-bgcolor-color,transparent));}}}#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"]{z-index:3;top:128px;;left:calc(50% - 600px + 634px);;width:531px;height:514px;}#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:0.000% 0.000%;background-size:100.000%;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"]{display:table;top:151px;;left:calc(50% - 480px + 410px);;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"]{display:table;top:548px;;left:calc(50% - 320px + 23px);;width:607px;height:403px;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"]{display:table;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"1769425751843000001\"]{display:table;top:525px;;left:calc(50% - 160px + 10px);;width:297px;height:197px;}}#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"]{z-index:3;top:429px;;left:calc(50% - 600px + 280px);;width:123px;height:39px;}#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"] .tn-atom{border-radius:10px 10px 10px 10px;background-color:#ffffff;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"]{display:table;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"]{display:table;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"]{display:table;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"1769616306815\"]{display:table;top:384px;;left:calc(50% - 160px + 170px);;}}#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"]{color:#192032;z-index:3;top:439px;;left:calc(50% - 600px + 290px);;width:auto;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:16px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"]{display:table;top:425px;;left:calc(50% - 480px + 206px);;height:auto;}}@media screen and (max-width:959px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"]{display:table;top:377px;;left:calc(50% - 320px + 206px);;height:auto;}}@media screen and (max-width:639px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"]{display:table;top:393px;;left:calc(50% - 160px + 182px);;width:102px;height:auto;}#rec1845904801 .tn-elem[data-elem-id=\"175757542540249580\"] .tn-atom{font-size:16px;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845904801\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"642\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"722\" data-artboard-upscale-res-320=\"grid\" data-artboard-height-res-480=\"1031\" data-artboard-height-res-640=\"1031\" data-artboard-upscale-res-640=\"window\" data-artboard-height-res-960=\"702\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845904801\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845904801\"><\/div> <div class='t396__elem tn-elem tn-elem__1845904801175757542539253160' data-elem-id='175757542539253160' data-elem-type='shape' data-field-top-value=\"100\" data-field-left-value=\"20\" data-field-height-value=\"542\" data-field-width-value=\"1160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"50\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"672\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"80\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"871\" data-field-width-res-640-value=\"620\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-width-res-960-value=\"940\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845904801175757542539670550' data-elem-id='175757542539670550' data-elem-type='shape' data-field-top-value=\"100\" data-field-left-value=\"20\" data-field-height-value=\"542\" data-field-width-value=\"1160\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"50\" data-field-left-res-320-value=\"0\" data-field-height-res-320-value=\"672\" data-field-width-res-320-value=\"320\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"80\" data-field-left-res-640-value=\"10\" data-field-height-res-640-value=\"871\" data-field-width-res-640-value=\"620\" data-field-widthmode-res-640-value=\"fixed\" data-field-top-res-960-value=\"80\" data-field-left-res-960-value=\"10\" data-field-width-res-960-value=\"940\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845904801175757542539894590' data-elem-id='175757542539894590' data-elem-type='text' data-field-top-value=\"289\" data-field-left-value=\"63\" data-field-height-value=\"24\" data-field-width-value=\"357\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"240\" data-field-left-res-320-value=\"30\" data-field-width-res-320-value=\"270\" data-field-widthmode-res-320-value=\"fixed\" data-field-fontsize-res-320-value=\"16\" data-field-top-res-640-value=\"221\" data-field-left-res-640-value=\"50\" data-field-width-res-640-value=\"521\" data-field-top-res-960-value=\"221\" data-field-left-res-960-value=\"50\" data-field-width-res-960-value=\"378\"> <div class='tn-atom'field='tn_text_175757542539894590'>\u0422\u044b \u043f\u043e\u043b\u0443\u0447\u0430\u0435\u0448\u044c:<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459048011769616232148000001' data-elem-id='1769616232148000001' data-elem-type='text' data-field-top-value=\"328\" data-field-left-value=\"63\" data-field-height-value=\"96\" data-field-width-value=\"357\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"20\" data-field-top-res-320-value=\"279\" data-field-left-res-320-value=\"30\" data-field-width-res-320-value=\"270\" data-field-widthmode-res-320-value=\"fixed\" data-field-fontsize-res-320-value=\"16\" data-field-top-res-640-value=\"221\" data-field-left-res-640-value=\"50\" data-field-width-res-640-value=\"521\" data-field-top-res-960-value=\"221\" data-field-left-res-960-value=\"50\" data-field-width-res-960-value=\"378\"> <div class='tn-atom'field='tn_text_1769616232148000001'>\u2022 \u0413\u0430\u0439\u0434 \u00ab\u0416\u0435\u043d\u0430\u0442\u0438\u043a\u00bb<br>\u2022 \u041c\u0435\u0434\u0438\u0442\u0430\u0446\u0438\u044e \u00ab\u0411\u0435\u0437\u0443\u0441\u043b\u043e\u0432\u043d\u0430\u044f \u0446\u0435\u043d\u043d\u043e\u0441\u0442\u044c\u00bb<br>\u2022 \u041c\u0435\u0434\u0438\u0442\u0430\u0446\u0438\u044f \u00ab\u0423\u0441\u0442\u0440\u0430\u043d\u0435\u043d\u0438\u0435 \u043d\u0435\u0433\u0430\u0442\u0438\u0432\u0430\u00bb<\/div> <\/div> <div class='t396__elem tn-elem js-price2 tn-elem__18459048011769616293208000002' data-elem-id='1769616293208000002' data-elem-type='text' data-field-top-value=\"431\" data-field-left-value=\"193\" data-field-height-value=\"29\" data-field-width-value=\"60\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"394\" data-field-left-res-320-value=\"106\" data-field-width-res-320-value=\"40\" data-field-fontsize-res-320-value=\"16\" data-field-top-res-640-value=\"377\" data-field-left-res-640-value=\"206\" data-field-top-res-960-value=\"425\" data-field-left-res-960-value=\"206\"> <div class='tn-atom'field='tn_text_1769616293208000002'><s>2199\u20bd<\/s><\/div> <\/div> <div class='t396__elem tn-elem js-price tn-elem__1845904801175757542540550980' data-elem-id='175757542540550980' data-elem-type='text' data-field-top-value=\"425\" data-field-left-value=\"60\" data-field-height-value=\"43\" data-field-width-value=\"92\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"388\" data-field-left-res-320-value=\"30\" data-field-height-res-320-value=\"31\" data-field-width-res-320-value=\"66\" data-field-fontsize-res-320-value=\"26\" data-field-top-res-640-value=\"371\" data-field-left-res-640-value=\"50\" data-field-top-res-960-value=\"419\" data-field-left-res-960-value=\"50\"> <div class='tn-atom'field='tn_text_175757542540550980'>1499\u20bd<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845904801175757542540850890' data-elem-id='175757542540850890' data-elem-type='text' data-field-top-value=\"140\" data-field-left-value=\"60\" data-field-height-value=\"129\" data-field-width-value=\"574\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"80\" data-field-left-res-320-value=\"30\" data-field-height-res-320-value=\"136\" data-field-width-res-320-value=\"264\" data-field-fontsize-res-320-value=\"24\" data-field-top-res-640-value=\"120\" data-field-left-res-640-value=\"50\" data-field-width-res-640-value=\"480\" data-field-top-res-960-value=\"120\" data-field-left-res-960-value=\"50\"> <div class='tn-atom'field='tn_text_175757542540850890'>\u041a\u0443\u043f\u0438 \u0433\u0430\u0439\u0434 \u00ab\u0416\u0435\u043d\u0430\u0442\u0438\u043a: \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c, \u0435\u0441\u043b\u0438 \u0442\u0432\u043e\u0439 \u043b\u044e\u0431\u0438\u043c\u044b\u0439 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u0435\u043d\u00bb \u0441\u0435\u0439\u0447\u0430\u0441 \u043f\u043e \u0441\u0430\u043c\u043e\u0439 \u0432\u044b\u0433\u043e\u0434\u043d\u043e\u0439 \u0446\u0435\u043d\u0435<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845904801175757542541476330' data-elem-id='175757542541476330' data-elem-type='button' data-field-top-value=\"498\" data-field-left-value=\"58\" data-field-height-value=\"68\" data-field-width-value=\"283\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"439\" data-field-left-res-320-value=\"30\" data-field-height-res-320-value=\"48\" data-field-width-res-320-value=\"261\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-fontsize-res-320-value=\"14\" data-field-top-res-640-value=\"444\" data-field-left-res-640-value=\"48\" data-field-top-res-960-value=\"492\" data-field-left-res-960-value=\"48\"> <a class='tn-atom' href=\"https:\/\/sbsite.pro\/\/married_man_1\" target=\"_blank\"> <div class='tn-atom__button-content'> <span class=\"tn-atom__button-text\">\u0417\u0430\u0431\u0440\u0430\u0442\u044c \u0433\u0430\u0439\u0434<\/span> <\/div> <span class=\"tn-atom__button-border\"><\/span> <\/a> <\/div> <div class='t396__elem tn-elem tn-elem__18459048011769425751843000001' data-elem-id='1769425751843000001' data-elem-type='shape' data-field-top-value=\"128\" data-field-left-value=\"634\" data-field-height-value=\"514\" data-field-width-value=\"531\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"525\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"197\" data-field-width-res-320-value=\"297\" data-field-top-res-640-value=\"548\" data-field-left-res-640-value=\"23\" data-field-height-res-640-value=\"403\" data-field-width-res-640-value=\"607\" data-field-top-res-960-value=\"151\" data-field-left-res-960-value=\"410\"> <div class='tn-atom t-bgimg' style=\"background-image:url('https:\/\/static.tildacdn.com\/tild3631-3934-4737-a463-393163663463\/Rectangle.png');\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459048011769616306815' data-elem-id='1769616306815' data-elem-type='shape' data-field-top-value=\"429\" data-field-left-value=\"280\" data-field-height-value=\"39\" data-field-width-value=\"123\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"384\" data-field-left-res-320-value=\"170\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem js-price2 tn-elem__1845904801175757542540249580' data-elem-id='175757542540249580' data-elem-type='text' data-field-top-value=\"439\" data-field-left-value=\"290\" data-field-height-value=\"19\" data-field-width-value=\"102\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"16\" data-field-top-res-320-value=\"393\" data-field-left-res-320-value=\"182\" data-field-width-res-320-value=\"102\" data-field-fontsize-res-320-value=\"16\" data-field-top-res-640-value=\"377\" data-field-left-res-640-value=\"206\" data-field-top-res-960-value=\"425\" data-field-left-res-960-value=\"206\"> <div class='tn-atom'field='tn_text_175757542540249580'>\u0414\u043e 3 \u0444\u0435\u0432\u0440\u0430\u043b\u044f<\/div> <\/div> <\/div> <\/div> <script>t_onFuncLoad('t396_initialScale',function() {t396_initialScale('1845904801');});t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845904801');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845919331\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845919331 .t396__artboard {height:206px;background-color:#ffffff;}#rec1845919331 .t396__filter {height:206px;}#rec1845919331 .t396__carrier{height:206px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845919331 .t396__artboard,#rec1845919331 .t396__filter,#rec1845919331 .t396__carrier {height:206px;}#rec1845919331 .t396__filter {}#rec1845919331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845919331 .t396__artboard,#rec1845919331 .t396__filter,#rec1845919331 .t396__carrier {height:206px;}#rec1845919331 .t396__filter {}#rec1845919331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845919331 .t396__artboard,#rec1845919331 .t396__filter,#rec1845919331 .t396__carrier {height:206px;}#rec1845919331 .t396__filter {}#rec1845919331 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845919331 .t396__artboard,#rec1845919331 .t396__filter,#rec1845919331 .t396__carrier {height:171px;}#rec1845919331 .t396__filter {}#rec1845919331 .t396__carrier {background-attachment:scroll;}}#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"]{color:#192032;text-align:center;z-index:3;top:80px;;left:calc(50% - 600px + 336px);;width:528px;height:86px;}#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"] .tn-atom{vertical-align:middle;color:#192032;font-size:36px;font-family:var(--t-text-font,Arial);line-height:1.2;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"]{display:table;left:calc(50% - 480px + 318px);;height:auto;}}@media screen and (max-width:959px){#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"]{display:table;left:calc(50% - 320px + 158px);;height:auto;}}@media screen and (max-width:639px){#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"]{display:table;top:50px;;left:calc(50% - 160px + 43px);;width:243px;height:auto;}#rec1845919331 .tn-elem[data-elem-id=\"175752054412513130\"] .tn-atom{font-size:26px;background-size:cover;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845919331\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"206\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"171\" data-artboard-upscale-res-320=\"window\" data-artboard-height-res-480=\"206\" data-artboard-height-res-640=\"206\" data-artboard-upscale-res-640=\"window\" data-artboard-height-res-960=\"206\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845919331\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845919331\"><\/div> <div class='t396__elem tn-elem tn-elem__1845919331175752054412513130' data-elem-id='175752054412513130' data-elem-type='text' data-field-top-value=\"80\" data-field-left-value=\"336\" data-field-height-value=\"86\" data-field-width-value=\"528\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-fontsize-value=\"36\" data-field-top-res-320-value=\"50\" data-field-left-res-320-value=\"43\" data-field-height-res-320-value=\"93\" data-field-width-res-320-value=\"243\" data-field-fontsize-res-320-value=\"26\" data-field-left-res-640-value=\"158\" data-field-left-res-960-value=\"318\"> <div class='tn-atom'field='tn_text_175752054412513130'>\u0413\u0430\u0439\u0434 \u0441\u043e\u0437\u0434\u0430\u043b\u0438 \u043f\u0440\u043e\u0444\u0435\u0441\u0441\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0438<\/div> <\/div> <\/div> <\/div> <script>t_onFuncLoad('t396_initialScale',function() {t396_initialScale('1845919331');});t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845919331');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1845919561\" class=\"r t-rec\" style=\" \" data-animationappear=\"off\" data-record-type=\"396\"> <!-- T396 --> <style>#rec1845919561 .t396__artboard {height:573px;background-color:#ffffff;}#rec1845919561 .t396__filter {height:573px;}#rec1845919561 .t396__carrier{height:573px;background-position:center center;background-attachment:scroll;background-size:cover;background-repeat:no-repeat;}@media screen and (max-width:1199px) {#rec1845919561 .t396__artboard,#rec1845919561 .t396__filter,#rec1845919561 .t396__carrier {height:350px;}#rec1845919561 .t396__filter {}#rec1845919561 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:959px) {#rec1845919561 .t396__artboard,#rec1845919561 .t396__filter,#rec1845919561 .t396__carrier {height:350px;}#rec1845919561 .t396__filter {}#rec1845919561 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:639px) {#rec1845919561 .t396__artboard,#rec1845919561 .t396__filter,#rec1845919561 .t396__carrier {height:350px;}#rec1845919561 .t396__filter {}#rec1845919561 .t396__carrier {background-attachment:scroll;}}@media screen and (max-width:479px) {#rec1845919561 .t396__artboard,#rec1845919561 .t396__filter,#rec1845919561 .t396__carrier {height:334px;}#rec1845919561 .t396__filter {}#rec1845919561 .t396__carrier {background-attachment:scroll;}}#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"]{z-index:3;top:0px;;left:calc(50% - 600px + 20px);;width:275px;height:250px;}#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"]{display:table;top:0px;;left:calc(50% - 480px + 730px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"]{display:table;top:0px;;left:calc(50% - 320px + 700px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1757520560469\"]{display:table;top:0px;;left:calc(50% - 160px + 10px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"]{z-index:3;top:20px;;left:calc(50% - 600px + 40px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"]{display:table;top:20px;;left:calc(50% - 480px + 750px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"]{display:table;top:20px;;left:calc(50% - 320px + 720px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1757520601301\"]{display:table;top:20px;;left:calc(50% - 160px + 30px);;}}#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"]{color:#192032;z-index:3;top:154px;;left:calc(50% - 600px + 40px);;width:246px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"]{display:table;top:154px;;left:calc(50% - 480px + 750px);;width:200px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"]{display:table;top:154px;;left:calc(50% - 320px + 720px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1757520615622\"]{display:table;top:154px;;left:calc(50% - 160px + 30px);;width:246px;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"]{color:#192032;z-index:3;top:115px;;left:calc(50% - 600px + 40px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"]{display:table;top:115px;;left:calc(50% - 480px + 750px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"]{display:table;top:115px;;left:calc(50% - 320px + 720px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752064323315520\"]{display:table;top:115px;;left:calc(50% - 160px + 30px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"]{z-index:3;top:270px;;left:calc(50% - 600px + 610px);;width:275px;height:195px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"]{display:table;top:0px;;left:calc(50% - 480px + 490px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"]{display:table;top:0px;;left:calc(50% - 320px + 470px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076592560\"]{display:table;top:0px;;left:calc(50% - 160px + 1436px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"]{z-index:3;top:290px;;left:calc(50% - 600px + 630px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"]{display:table;top:20px;;left:calc(50% - 480px + 510px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"]{display:table;top:20px;;left:calc(50% - 320px + 490px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084076836210\"]{display:table;top:20px;;left:calc(50% - 160px + 1456px);;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"]{color:#192032;z-index:3;top:424px;;left:calc(50% - 600px + 630px);;width:235px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"]{display:table;top:154px;;left:calc(50% - 480px + 510px);;width:177px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"]{display:table;top:154px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077185550\"]{display:table;top:154px;;left:calc(50% - 160px + 1456px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"]{color:#192032;z-index:3;top:385px;;left:calc(50% - 600px + 630px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"]{display:table;top:115px;;left:calc(50% - 480px + 510px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"]{display:table;top:115px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084077488090\"]{display:table;top:115px;;left:calc(50% - 160px + 1456px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"]{z-index:3;top:268px;;left:calc(50% - 600px + 315px);;width:275px;height:195px;}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"]{display:table;top:0px;;left:calc(50% - 480px + 490px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"]{display:table;top:0px;;left:calc(50% - 320px + 470px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000007\"]{display:table;top:0px;;left:calc(50% - 160px + 1151px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"]{z-index:3;top:288px;;left:calc(50% - 600px + 335px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"]{display:table;top:20px;;left:calc(50% - 480px + 510px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"]{display:table;top:20px;;left:calc(50% - 320px + 490px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000008\"]{display:table;top:20px;;left:calc(50% - 160px + 1171px);;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"]{color:#192032;z-index:3;top:422px;;left:calc(50% - 600px + 335px);;width:235px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"]{display:table;top:154px;;left:calc(50% - 480px + 510px);;width:177px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"]{display:table;top:154px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000009\"]{display:table;top:154px;;left:calc(50% - 160px + 1171px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"]{color:#192032;z-index:3;top:383px;;left:calc(50% - 600px + 335px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"]{display:table;top:115px;;left:calc(50% - 480px + 510px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"]{display:table;top:115px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616546335000010\"]{display:table;top:115px;;left:calc(50% - 160px + 1171px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"]{z-index:3;top:0px;;left:calc(50% - 600px + 610px);;width:275px;height:250px;}#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"]{display:table;top:0px;;left:calc(50% - 480px + 490px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"]{display:table;top:0px;;left:calc(50% - 320px + 470px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000002\"]{display:table;top:0px;;left:calc(50% - 160px + 581px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"]{z-index:3;top:20px;;left:calc(50% - 600px + 630px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"]{display:table;top:20px;;left:calc(50% - 480px + 510px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"]{display:table;top:20px;;left:calc(50% - 320px + 490px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512964000003\"]{display:table;top:20px;;left:calc(50% - 160px + 601px);;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"]{color:#192032;z-index:3;top:154px;;left:calc(50% - 600px + 630px);;width:235px;height:40px;}#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"]{display:table;top:154px;;left:calc(50% - 480px + 510px);;width:177px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"]{display:table;top:154px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000004\"]{display:table;top:154px;;left:calc(50% - 160px + 601px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"]{color:#192032;z-index:3;top:115px;;left:calc(50% - 600px + 630px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"]{display:table;top:115px;;left:calc(50% - 480px + 510px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"]{display:table;top:115px;;left:calc(50% - 320px + 490px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"1769616512965000005\"]{display:table;top:115px;;left:calc(50% - 160px + 601px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"]{z-index:3;top:0px;;left:calc(50% - 600px + 315px);;width:275px;height:250px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"]{display:table;top:0px;;left:calc(50% - 480px + 250px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"]{display:table;top:0px;;left:calc(50% - 320px + 240px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872457210\"]{display:table;top:0px;;left:calc(50% - 160px + 295px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"]{z-index:3;top:20px;;left:calc(50% - 600px + 335px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"]{display:table;top:20px;;left:calc(50% - 480px + 270px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"]{display:table;top:20px;;left:calc(50% - 320px + 260px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084872977420\"]{display:table;top:20px;;left:calc(50% - 160px + 315px);;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"]{color:#192032;z-index:3;top:154px;;left:calc(50% - 600px + 335px);;width:255px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"]{display:table;top:154px;;left:calc(50% - 480px + 270px);;width:190px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"]{display:table;top:154px;;left:calc(50% - 320px + 260px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873395770\"]{display:table;top:154px;;left:calc(50% - 160px + 315px);;width:255px;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"]{color:#192032;z-index:3;top:115px;;left:calc(50% - 600px + 335px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"]{display:table;top:115px;;left:calc(50% - 480px + 270px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"]{display:table;top:115px;;left:calc(50% - 320px + 260px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084873651970\"]{display:table;top:115px;;left:calc(50% - 160px + 315px);;height:auto;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"]{z-index:3;top:0px;;left:calc(50% - 600px + 905px);;width:275px;height:250px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"] .tn-atom{border-radius:20px 20px 20px 20px;background-color:#f7f7f7;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"]{display:table;top:0px;;left:calc(50% - 480px + 10px);;width:220px;height:270px;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"]{display:table;top:0px;;left:calc(50% - 320px + 10px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875088940\"]{display:table;top:0px;;left:calc(50% - 160px + 866px);;width:275px;height:254px;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"]{z-index:3;top:20px;;left:calc(50% - 600px + 925px);;width:75px;height:75px;}#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"] .tn-atom{border-radius:0px 0px 0px 0px;background-position:center center;background-size:cover;background-repeat:no-repeat;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"]{display:table;top:20px;;left:calc(50% - 480px + 30px);;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"]{display:table;top:20px;;left:calc(50% - 320px + 30px);;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"]{display:table;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875213350\"]{display:table;top:20px;;left:calc(50% - 160px + 886px);;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"]{color:#192032;z-index:3;top:154px;;left:calc(50% - 600px + 925px);;width:235px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"] .tn-atom{vertical-align:middle;color:#192032;font-size:14px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"]{display:table;top:154px;;left:calc(50% - 480px + 30px);;width:174px;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"]{display:table;top:154px;;left:calc(50% - 320px + 30px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"]{display:table;top:154px;;left:calc(50% - 160px + 886px);;width:223px;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084875668360\"] .tn-atom{vertical-align:middle;white-space:normal;background-size:cover;}}#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"]{color:#192032;z-index:3;top:115px;;left:calc(50% - 600px + 925px);;width:auto;height:auto;}#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"] .tn-atom{vertical-align:middle;white-space:nowrap;color:#192032;font-size:24px;font-family:var(--t-text-font,Arial);line-height:1.4;font-weight:400;background-position:center center;border-width:var(--t396-borderwidth,0);border-style:var(--t396-borderstyle,solid);border-color:var(--t396-bordercolor,transparent);transition:background-color var(--t396-speedhover,0s) ease-in-out,color var(--t396-speedhover,0s) ease-in-out,border-color var(--t396-speedhover,0s) ease-in-out,box-shadow var(--t396-shadowshoverspeed,0.2s) ease-in-out;--t396-shadow-text-opacity:100%;text-shadow:var(--t396-shadow-text-x,0px) var(--t396-shadow-text-y,0px) var(--t396-shadow-text-blur,0px) rgba(var(--t396-shadow-text-color),var(--t396-shadow-text-opacity,100%));}@media screen and (max-width:1199px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"]{display:table;top:115px;;left:calc(50% - 480px + 30px);;height:auto;}}@media screen and (max-width:959px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"]{display:table;top:115px;;left:calc(50% - 320px + 30px);;height:auto;}}@media screen and (max-width:639px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"]{display:table;height:auto;}}@media screen and (max-width:479px){#rec1845919561 .tn-elem[data-elem-id=\"175752084875879950\"]{display:table;top:115px;;left:calc(50% - 160px + 886px);;height:auto;}}<\/style> <div class='t396'> <div class=\"t396__artboard\" data-artboard-recid=\"1845919561\" data-artboard-screens=\"320,480,640,960,1200\" data-artboard-height=\"573\" data-artboard-valign=\"center\" data-artboard-upscale=\"grid\" data-artboard-height-res-320=\"334\" data-artboard-upscale-res-320=\"window\" data-artboard-height-res-480=\"350\" data-artboard-height-res-640=\"350\" data-artboard-upscale-res-640=\"window\" data-artboard-height-res-960=\"350\"> <div class=\"t396__carrier\" data-artboard-recid=\"1845919561\"><\/div> <div class=\"t396__filter\" data-artboard-recid=\"1845919561\"><\/div> <div class='t396__elem tn-elem tn-elem__18459195611757520560469' data-elem-id='1757520560469' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"20\" data-field-height-value=\"250\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"10\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"700\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"730\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611757520601301' data-elem-id='1757520601301' data-elem-type='shape' data-field-top-value=\"20\" data-field-left-value=\"40\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"30\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"720\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"750\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3635-6566-4331-a466-383164623031\/Ellipse_13.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611757520615622' data-elem-id='1757520615622' data-elem-type='text' data-field-top-value=\"154\" data-field-left-value=\"40\" data-field-height-value=\"80\" data-field-width-value=\"246\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"30\" data-field-width-res-320-value=\"246\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"720\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"750\" data-field-width-res-960-value=\"200\"> <div class='tn-atom'field='tn_text_1757520615622'>\u043e\u0441\u043d\u043e\u0432\u0430\u0442\u0435\u043b\u044c \u0438&nbsp;CEO Mindspa, \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u0430\u0432\u0442\u043e\u0440 9 \u0431\u0435\u0441\u0442\u0441\u0435\u043b\u043b\u0435\u0440\u043e\u0432 \u0432&nbsp;\u0436\u0430\u043d\u0440\u0435 \u00ab\u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0430\u044f \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0438\u044f\u00bb \u0438&nbsp;\u043a\u043d\u0438\u0433\u0438 \u00ab\u0412&nbsp;\u043f\u043e\u0441\u0442\u0435\u043b\u0438 \u0441&nbsp;\u0442\u0432\u043e\u0438\u043c \u043c\u0443\u0436\u0435\u043c\u00bb<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752064323315520' data-elem-id='175752064323315520' data-elem-type='text' data-field-top-value=\"115\" data-field-left-value=\"40\" data-field-height-value=\"34\" data-field-width-value=\"174\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"30\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"720\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"750\"> <div class='tn-atom'field='tn_text_175752064323315520'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">\u041d\u0438\u043a\u0430 \u041d\u0430\u0431\u043e\u043a\u043e\u0432\u0430<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084076592560' data-elem-id='175752084076592560' data-elem-type='shape' data-field-top-value=\"270\" data-field-left-value=\"610\" data-field-height-value=\"195\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"1436\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"470\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"490\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084076836210' data-elem-id='175752084076836210' data-elem-type='shape' data-field-top-value=\"290\" data-field-left-value=\"630\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"1456\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"510\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3739-3635-4134-b231-653163393236\/Ellipse_10.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084077185550' data-elem-id='175752084077185550' data-elem-type='text' data-field-top-value=\"424\" data-field-left-value=\"630\" data-field-height-value=\"20\" data-field-width-value=\"235\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"1456\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"510\" data-field-width-res-960-value=\"177\"> <div class='tn-atom'field='tn_text_175752084077185550'>\u0438\u043d\u0442\u0435\u0433\u0440\u0430\u0442\u0438\u0432\u043d\u044b\u0439 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084077488090' data-elem-id='175752084077488090' data-elem-type='text' data-field-top-value=\"385\" data-field-left-value=\"630\" data-field-height-value=\"34\" data-field-width-value=\"188\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"1456\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"510\"> <div class='tn-atom'field='tn_text_175752084077488090'>\u0414\u0438\u0430\u043d\u0430 \u041f\u0438\u043d\u0435\u0433\u0438\u043d\u0430<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616546335000007' data-elem-id='1769616546335000007' data-elem-type='shape' data-field-top-value=\"268\" data-field-left-value=\"315\" data-field-height-value=\"195\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"1151\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"470\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"490\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616546335000008' data-elem-id='1769616546335000008' data-elem-type='shape' data-field-top-value=\"288\" data-field-left-value=\"335\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"1171\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"510\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6533-3433-4061-b638-633663303432\/Ellipse_12-1.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616546335000009' data-elem-id='1769616546335000009' data-elem-type='text' data-field-top-value=\"422\" data-field-left-value=\"335\" data-field-height-value=\"20\" data-field-width-value=\"235\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"1171\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"510\" data-field-width-res-960-value=\"177\"> <div class='tn-atom'field='tn_text_1769616546335000009'>\u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u043a\u0440\u0438\u0437\u0438\u0441\u043d\u044b\u0439 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u043a\u043e\u0443\u0447<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616546335000010' data-elem-id='1769616546335000010' data-elem-type='text' data-field-top-value=\"383\" data-field-left-value=\"335\" data-field-height-value=\"34\" data-field-width-value=\"206\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"1171\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"510\"> <div class='tn-atom'field='tn_text_1769616546335000010'>\u041e\u043b\u044c\u0433\u0430 \u0410\u043b\u0435\u043a\u0441\u0435\u0435\u043d\u043a\u043e<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616512964000002' data-elem-id='1769616512964000002' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"610\" data-field-height-value=\"250\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"581\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"470\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"490\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616512964000003' data-elem-id='1769616512964000003' data-elem-type='shape' data-field-top-value=\"20\" data-field-left-value=\"630\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"601\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"510\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3635-6239-4736-b036-623166336162\/Ellipse_12.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616512965000004' data-elem-id='1769616512965000004' data-elem-type='text' data-field-top-value=\"154\" data-field-left-value=\"630\" data-field-height-value=\"40\" data-field-width-value=\"235\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"fixedsize\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"601\" data-field-height-res-320-value=\"60\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"510\" data-field-width-res-960-value=\"177\"> <div class='tn-atom'field='tn_text_1769616512965000004'>\u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0443\u044e\u0449\u0438\u0439 \u043a\u043b\u0438\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u0433\u0435\u0448\u0442\u0430\u043b\u044c\u0442\u2013\u0442\u0435\u0440\u0430\u043f\u0435\u0432\u0442<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__18459195611769616512965000005' data-elem-id='1769616512965000005' data-elem-type='text' data-field-top-value=\"115\" data-field-left-value=\"630\" data-field-height-value=\"34\" data-field-width-value=\"194\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"601\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"490\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"510\"> <div class='tn-atom'field='tn_text_1769616512965000005'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">\u0421\u043e\u0444\u0438\u044f \u0410\u0432\u0434\u044e\u0445\u0438\u043d\u0430<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084872457210' data-elem-id='175752084872457210' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"315\" data-field-height-value=\"250\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"295\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"240\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"250\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084872977420' data-elem-id='175752084872977420' data-elem-type='shape' data-field-top-value=\"20\" data-field-left-value=\"335\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"315\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"260\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"270\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild6134-3932-4732-b238-363433366534\/Ellipse_11.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084873395770' data-elem-id='175752084873395770' data-elem-type='text' data-field-top-value=\"154\" data-field-left-value=\"335\" data-field-height-value=\"60\" data-field-width-value=\"255\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"315\" data-field-width-res-320-value=\"255\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"260\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"270\" data-field-width-res-960-value=\"190\"> <div class='tn-atom'field='tn_text_175752084873395770'>\u043c\u0430\u0433\u0438\u0441\u0442\u0440 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0438\u0438, \u043f\u0441\u0438\u0445\u043e\u0434\u0440\u0430\u043c\u0430\u0442\u0435\u0440\u0430\u043f\u0435\u0432\u0442, \u0441\u0445\u0435\u043c\u0430-\u0442\u0435\u0440\u0430\u043f\u0435\u0432\u0442, \u0437\u0430\u0432\u0435\u0434\u0443\u044e\u0449\u0430\u044f \u043a\u0430\u0444\u0435\u0434\u0440\u043e\u0439 \u041c\u0410\u0413<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084873651970' data-elem-id='175752084873651970' data-elem-type='text' data-field-top-value=\"115\" data-field-left-value=\"335\" data-field-height-value=\"34\" data-field-width-value=\"190\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"315\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"260\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"270\"> <div class='tn-atom'field='tn_text_175752084873651970'><div style=\"white-space: nowrap;\" data-customstyle=\"yes\">\u041e\u043b\u044c\u0433\u0430 \u041c\u0430\u043b\u0438\u043d\u0438\u043d\u0430<\/div><\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084875088940' data-elem-id='175752084875088940' data-elem-type='shape' data-field-top-value=\"0\" data-field-left-value=\"905\" data-field-height-value=\"250\" data-field-width-value=\"275\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"0\" data-field-left-res-320-value=\"866\" data-field-height-res-320-value=\"254\" data-field-width-res-320-value=\"275\" data-field-widthmode-res-320-value=\"fixed\" data-field-heightmode-res-320-value=\"fixed\" data-field-top-res-640-value=\"0\" data-field-left-res-640-value=\"10\" data-field-top-res-960-value=\"0\" data-field-left-res-960-value=\"10\" data-field-height-res-960-value=\"270\" data-field-width-res-960-value=\"220\" data-field-widthmode-res-960-value=\"fixed\" data-field-heightmode-res-960-value=\"fixed\"> <div class='tn-atom'> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084875213350' data-elem-id='175752084875213350' data-elem-type='shape' data-field-top-value=\"20\" data-field-left-value=\"925\" data-field-height-value=\"75\" data-field-width-value=\"75\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-widthmode-value=\"fixed\" data-field-heightmode-value=\"fixed\" data-field-top-res-320-value=\"20\" data-field-left-res-320-value=\"886\" data-field-top-res-640-value=\"20\" data-field-left-res-640-value=\"30\" data-field-top-res-960-value=\"20\" data-field-left-res-960-value=\"30\"> <div class='tn-atom t-bgimg' data-original=\"https:\/\/static.tildacdn.com\/tild3563-3065-4661-b437-356462333839\/Ellipse_10.png\"\naria-label='' role=\"img\"> <\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084875668360' data-elem-id='175752084875668360' data-elem-type='text' data-field-top-value=\"154\" data-field-left-value=\"925\" data-field-height-value=\"40\" data-field-width-value=\"235\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autoheight\" data-field-widthmode-value=\"fixed\" data-field-fontsize-value=\"14\" data-field-top-res-320-value=\"154\" data-field-left-res-320-value=\"886\" data-field-width-res-320-value=\"223\" data-field-heightunits-res-320-value=\"px\" data-field-textfit-res-320-value=\"autoheight\" data-field-top-res-640-value=\"154\" data-field-left-res-640-value=\"30\" data-field-top-res-960-value=\"154\" data-field-left-res-960-value=\"30\" data-field-height-res-960-value=\"80\" data-field-width-res-960-value=\"174\"> <div class='tn-atom'field='tn_text_175752084875668360'>\u043a\u043b\u0438\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u043a\u0440\u0438\u0437\u0438\u0441\u043d\u044b\u0439 \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433, \u0441\u0443\u043f\u0435\u0440\u0432\u0438\u0437\u043e\u0440<\/div> <\/div> <div class='t396__elem tn-elem tn-elem__1845919561175752084875879950' data-elem-id='175752084875879950' data-elem-type='text' data-field-top-value=\"115\" data-field-left-value=\"925\" data-field-height-value=\"34\" data-field-width-value=\"164\" data-field-axisy-value=\"top\" data-field-axisx-value=\"left\" data-field-container-value=\"grid\" data-field-topunits-value=\"px\" data-field-leftunits-value=\"px\" data-field-heightunits-value=\"px\" data-field-widthunits-value=\"px\" data-field-textfit-value=\"autowidth\" data-field-fontsize-value=\"24\" data-field-top-res-320-value=\"115\" data-field-left-res-320-value=\"886\" data-field-top-res-640-value=\"115\" data-field-left-res-640-value=\"30\" data-field-top-res-960-value=\"115\" data-field-left-res-960-value=\"30\"> <div class='tn-atom'field='tn_text_175752084875879950'>\u0415\u043b\u0435\u043d\u0430 \u0415\u0440\u0448\u043e\u0432\u0430<\/div> <\/div> <\/div> <\/div> <script>t_onFuncLoad('t396_initialScale',function() {t396_initialScale('1845919561');});t_onReady(function() {t_onFuncLoad('t396_init',function() {t396_init('1845919561');});});<\/script> <!-- \/T396 --> <\/div> <div id=\"rec1846326451\" class=\"r t-rec t-screenmax-480px\" style=\" \" data-animationappear=\"off\" data-record-type=\"131\" data-screen-max=\"480px\"> <!-- T123 --> <div class=\"t123\"> <div class=\"t-container_100\"> <div class=\"t-width t-width_100\"> <!-- nominify begin --> <script>\ndocument.addEventListener('DOMContentLoaded', function () {\n    \n    let pos = { top: 0, left: 0, x: 0, y: 0 };\n    let blocks = ['#rec1845919561'];\n    \n    blocks.forEach((elem) => {\n        elem = document.querySelector(elem + \" .t396__artboard\");\n        if (elem.querySelector(\"img\") !== null) {\n            elem.querySelector(\"img\").ondragstart = function() { return false; };\n        };\n        elem.style.overflowX = 'auto';\n        elem.style.overflowY = 'hidden';\n        elem.querySelector('.t396__carrier').style.position = 'sticky';\n        elem.style.cursor = 'grab';\n        const mouseDownHandler = function (e) {\n            elem.style.cursor = 'grabbing';\n            elem.style.userSelect = 'none';\n            pos = {\n                left: elem.scrollLeft,\n                x: e.clientX,\n            };\n            document.addEventListener('mousemove', mouseMoveHandler);\n            document.addEventListener('mouseup', mouseUpHandler);\n        };\n        const mouseMoveHandler = function (e) {\n            const dx = e.clientX - pos.x;\n            elem.scrollLeft = pos.left - dx;\n        };\n        const mouseUpHandler = function () {\n            elem.style.cursor = 'grab';\n            elem.style.removeProperty('user-select');\n    \n            document.removeEventListener('mousemove', mouseMoveHandler);\n            document.removeEventListener('mouseup', mouseUpHandler);\n        };\n        elem.addEventListener('mousedown', mouseDownHandler);\n        \n    function scrollHorizontally(e) {\n      e = window.event;\n      var delta = Math.max(-1, Math.min(1, (-(e.deltaY) || 0)));\n      elem.scrollLeft -= (delta * 40);\n    if((delta > 0 && elem.scrollLeft > 0) || (delta < 0 && elem.offsetWidth+elem.scrollLeft < elem.scrollWidth)) {\n        e.preventDefault();\n    };\n  };\n  elem.addEventListener('wheel', scrollHorizontally, false);\n    });\n    \n});\n<\/script> <style>\n   #rec1845919561 .t396__artboard::-webkit-scrollbar {\n      display: none;\n  }\n  #rec1845919561 .t396__artboard {\n      scrollbar-width: none;\n  }\n<\/style> <!-- nominify end --> <\/div> <\/div> <\/div> <\/div> <div id=\"rec1845950711\" class=\"r t-rec t-rec_pt_0 t-rec_pb_90\" style=\"padding-top:0px;padding-bottom:90px;background-color:#ffffff; \" data-animationappear=\"off\" data-record-type=\"668\" data-bg-color=\"#ffffff\"> <!-- T668 --> <div class=\"t668\"> <div class=\"t-section__container t-container t-container_flex\"> <div class=\"t-col t-col_12\"> <div\nclass=\"t-section__title t-title t-title_xs t-align_center t-margin_auto\"\nfield=\"btitle\">\nFAQ\n<\/div> <\/div> <\/div> <style><\/style> <style> #rec1845950711 .t-section__title{color:#192032;font-family:var(--t-text-font,Arial);font-weight:400;padding-bottom:30px;padding-top:0px;}@media screen and (min-width:900px){#rec1845950711 .t-section__title{font-size:36px;}}#rec1845950711 .t-section__descr{font-size:16px;color:#192032;font-family:var(--t-text-font,Arial);}<\/style> <div class=\"t-container\"> <div class=\"t668__col t-col t-col_12\" style=\"margin-bottom:2px;\"> <div class=\"t668__accordion\" data-accordion=\"true\" data-scroll-to-expanded=\"false\"> <div class=\"t668__wrapper\" style=\"background-color: #f7f7f7;\"> <div class=\"t668__header\"> <button type=\"button\"\nclass=\"t668__trigger-button\"\naria-controls=\"accordion1_1845950711\"\naria-expanded=\"false\"> <span class=\"t668__title t-name t-name_xl\" field=\"li_title__5698223929570\" style=\"color: #192032;\">\u041a\u0430\u043a \u044f \u043f\u043e\u043b\u0443\u0447\u0443 \u0433\u0430\u0439\u0434 \u0438 \u0431\u043e\u043d\u0443\u0441\u043d\u044b\u0435 \u043c\u0435\u0434\u0438\u0442\u0430\u0446\u0438\u0438?<\/span> <span class=\"t668__icon\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #3f89c4\"><\/span> <\/span> <span class=\"t668__icon t668__icon-hover\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #1f659c\"><\/span> <\/span> <\/button> <\/div> <div class=\"t668__content\"\nid=\"accordion1_1845950711\"\nhidden> <div class=\"t668__textwrapper\"> <div class=\"t668__text t-descr t-descr_xs\" field=\"li_descr__5698223929570\" style=\"color: #192032;\">\u041f\u043e\u0441\u043b\u0435 \u043e\u043f\u043b\u0430\u0442\u044b \u0442\u044b \u0430\u0432\u0442\u043e\u043c\u0430\u0442\u0438\u0447\u0435\u0441\u043a\u0438 \u043f\u043e\u043f\u0430\u0434\u0451\u0448\u044c \u0432 Telegram-\u0431\u043e\u0442\u0430 \u2014 \u0438\u043c\u0435\u043d\u043d\u043e \u0442\u0430\u043c \u0431\u0443\u0434\u0435\u0442 \u0434\u043e\u0441\u0442\u0443\u043f\u0435\u043d \u0433\u0430\u0439\u0434 \u0438 \u0432\u0441\u0435 \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044b.<\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"t668__col t-col t-col_12\" style=\"margin-bottom:2px;\"> <div class=\"t668__accordion\" data-accordion=\"true\" data-scroll-to-expanded=\"false\"> <div class=\"t668__wrapper\" style=\"background-color: #f7f7f7;\"> <div class=\"t668__header\"> <button type=\"button\"\nclass=\"t668__trigger-button\"\naria-controls=\"accordion2_1845950711\"\naria-expanded=\"false\"> <span class=\"t668__title t-name t-name_xl\" field=\"li_title__9698223929571\" style=\"color: #192032;\">\u041a\u0430\u043a \u044f \u043c\u043e\u0433\u0443 \u043e\u043f\u043b\u0430\u0442\u0438\u0442\u044c \u0433\u0430\u0439\u0434?<\/span> <span class=\"t668__icon\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #3f89c4\"><\/span> <\/span> <span class=\"t668__icon t668__icon-hover\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #1f659c\"><\/span> <\/span> <\/button> <\/div> <div class=\"t668__content\"\nid=\"accordion2_1845950711\"\nhidden> <div class=\"t668__textwrapper\"> <div class=\"t668__text t-descr t-descr_xs\" field=\"li_descr__9698223929571\" style=\"color: #192032;\">\u0422\u044b \u043c\u043e\u0436\u0435\u0448\u044c \u043e\u043f\u043b\u0430\u0442\u0438\u0442\u044c \u0433\u0430\u0439\u0434 \u0431\u0430\u043d\u043a\u043e\u0432\u0441\u043a\u043e\u0439 \u043a\u0430\u0440\u0442\u043e\u0439. \u041e\u043f\u043b\u0430\u0442\u0430 \u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0442 \u043e\u043d\u043b\u0430\u0439\u043d \u0432 Telegram-\u0431\u043e\u0442\u0435 \u2014 \u0431\u044b\u0441\u0442\u0440\u043e \u0438 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e.<\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"t668__col t-col t-col_12\" style=\"margin-bottom:2px;\"> <div class=\"t668__accordion\" data-accordion=\"true\" data-scroll-to-expanded=\"false\"> <div class=\"t668__wrapper\" style=\"background-color: #f7f7f7;\"> <div class=\"t668__header\"> <button type=\"button\"\nclass=\"t668__trigger-button\"\naria-controls=\"accordion3_1845950711\"\naria-expanded=\"false\"> <span class=\"t668__title t-name t-name_xl\" field=\"li_title__9698223929572\" style=\"color: #192032;\">\u0427\u0435\u043c \u0433\u0430\u0439\u0434 \u043e\u0442\u043b\u0438\u0447\u0430\u0435\u0442\u0441\u044f \u043e\u0442 \u043a\u0443\u0440\u0441\u043e\u0432? <\/span> <span class=\"t668__icon\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #3f89c4\"><\/span> <\/span> <span class=\"t668__icon t668__icon-hover\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #1f659c\"><\/span> <\/span> <\/button> <\/div> <div class=\"t668__content\"\nid=\"accordion3_1845950711\"\nhidden> <div class=\"t668__textwrapper\"> <div class=\"t668__text t-descr t-descr_xs\" field=\"li_descr__9698223929572\" style=\"color: #192032;\">\u0413\u0430\u0439\u0434 \u00ab\u0416\u0435\u043d\u0430\u0442\u0438\u043a: \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c, \u0435\u0441\u043b\u0438 \u0442\u0432\u043e\u0439 \u043b\u044e\u0431\u0438\u043c\u044b\u0439 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u0435\u043d?\u00bb \u2014 \u0431\u043e\u043b\u0435\u0435 \u0442\u043e\u0447\u0435\u0447\u043d\u044b\u0439 \u0444\u043e\u0440\u043c\u0430\u0442. \u041e\u043d \u043e\u0440\u0438\u0435\u043d\u0442\u0438\u0440\u043e\u0432\u0430\u043d \u043d\u0430 \u043a\u043e\u043d\u043a\u0440\u0435\u0442\u043d\u044b\u0439 \u0442\u0438\u043f \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u2014 \u0441 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u043d\u044b\u043c\u0438 \u043c\u0443\u0436\u0447\u0438\u043d\u0430\u043c\u0438. \u0413\u0430\u0439\u0434 \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u043f\u043e\u043d\u044f\u0442\u044c, \u043a\u0430\u043a\u0438\u0445 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439 \u0442\u044b \u0445\u043e\u0447\u0435\u0448\u044c \u0438 \u043a\u0430\u043a \u043a \u043d\u0438\u043c \u043f\u0440\u0438\u0439\u0442\u0438. \u0412\u043d\u0443\u0442\u0440\u0438 \u2014 \u0441\u0436\u0430\u0442\u0430\u044f \u0442\u0435\u043e\u0440\u0438\u044f \u0438 \u0430\u043a\u0446\u0435\u043d\u0442 \u043d\u0430 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0438, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u044e\u0442 \u00ab\u0437\u0434\u0435\u0441\u044c \u0438 \u0441\u0435\u0439\u0447\u0430\u0441\u00bb \u0438 \u043f\u043e\u043c\u043e\u0433\u0430\u044e\u0442 \u0440\u0430\u0431\u043e\u0442\u0430\u0442\u044c \u0441 \u043a\u043e\u043d\u043a\u0440\u0435\u0442\u043d\u044b\u043c \u0441\u0438\u043c\u043f\u0442\u043e\u043c\u043e\u043c.<\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"t668__col t-col t-col_12\" style=\"margin-bottom:2px;\"> <div class=\"t668__accordion\" data-accordion=\"true\" data-scroll-to-expanded=\"false\"> <div class=\"t668__wrapper\" style=\"background-color: #f7f7f7;\"> <div class=\"t668__header\"> <button type=\"button\"\nclass=\"t668__trigger-button\"\naria-controls=\"accordion4_1845950711\"\naria-expanded=\"false\"> <span class=\"t668__title t-name t-name_xl\" field=\"li_title__1769617008035\" style=\"color: #192032;\">\u041c\u043e\u0436\u043d\u043e \u043b\u0438 \u0432\u0435\u0440\u043d\u0443\u0442\u044c \u0434\u0435\u043d\u044c\u0433\u0438, \u0435\u0441\u043b\u0438 \u0433\u0430\u0439\u0434 \u043d\u0435 \u043f\u043e\u043d\u0440\u0430\u0432\u0438\u0442\u0441\u044f?<\/span> <span class=\"t668__icon\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #3f89c4\"><\/span> <\/span> <span class=\"t668__icon t668__icon-hover\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #1f659c\"><\/span> <\/span> <\/button> <\/div> <div class=\"t668__content\"\nid=\"accordion4_1845950711\"\nhidden> <div class=\"t668__textwrapper\"> <div class=\"t668__text t-descr t-descr_xs\" field=\"li_descr__1769617008035\" style=\"color: #192032;\">\u0413\u0430\u0439\u0434 \u2014 \u0446\u0438\u0444\u0440\u043e\u0432\u043e\u0439 \u043f\u0440\u043e\u0434\u0443\u043a\u0442 \u0441 \u043c\u0433\u043d\u043e\u0432\u0435\u043d\u043d\u044b\u043c \u0434\u043e\u0441\u0442\u0443\u043f\u043e\u043c, \u043f\u043e\u044d\u0442\u043e\u043c\u0443 \u0432\u043e\u0437\u0432\u0440\u0430\u0442 \u0441\u0440\u0435\u0434\u0441\u0442\u0432 \u043d\u0435 \u043f\u0440\u0435\u0434\u0443\u0441\u043c\u043e\u0442\u0440\u0435\u043d.<\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"t668__col t-col t-col_12\" style=\"margin-bottom:2px;\"> <div class=\"t668__accordion\" data-accordion=\"true\" data-scroll-to-expanded=\"false\"> <div class=\"t668__wrapper\" style=\"background-color: #f7f7f7;\"> <div class=\"t668__header\"> <button type=\"button\"\nclass=\"t668__trigger-button\"\naria-controls=\"accordion5_1845950711\"\naria-expanded=\"false\"> <span class=\"t668__title t-name t-name_xl\" field=\"li_title__1769617030170\" style=\"color: #192032;\">\u0423 \u043c\u0435\u043d\u044f \u043e\u0441\u0442\u0430\u043b\u0438\u0441\u044c \u0432\u043e\u043f\u0440\u043e\u0441\u044b<\/span> <span class=\"t668__icon\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #3f89c4\"><\/span> <\/span> <span class=\"t668__icon t668__icon-hover\"> <span class=\"t668__lines\"> <svg role=\"presentation\" focusable=\"false\" width=\"24px\" height=\"24px\" viewbox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"> <g stroke=\"none\" stroke-width=\"1px\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"square\"> <g transform=\"translate(1.000000, 1.000000)\" stroke=\"#ffffff\"> <path d=\"M0,11 L22,11\"><\/path> <path d=\"M11,0 L11,22\"><\/path> <\/g> <\/g> <\/svg> <\/span> <span class=\"t668__circle\" style=\"background-color: #1f659c\"><\/span> <\/span> <\/button> <\/div> <div class=\"t668__content\"\nid=\"accordion5_1845950711\"\nhidden> <div class=\"t668__textwrapper\"> <div class=\"t668__text t-descr t-descr_xs\" field=\"li_descr__1769617030170\" style=\"color: #192032;\">\u041d\u0430\u043f\u0438\u0448\u0438 \u043d\u0430\u043c \u0432 <a href=\"https:\/\/t.me\/mindspa_support_bot\" style=\"color: rgb(63, 137, 196); box-shadow: none; text-decoration: none; border-bottom: 1px solid rgb(63, 137, 196);\">\u043f\u043e\u0434\u0434\u0435\u0440\u0436\u043a\u0443<\/a>\u2014 \u043c\u044b \u0441 \u0440\u0430\u0434\u043e\u0441\u0442\u044c\u044e \u043f\u043e\u043c\u043e\u0436\u0435\u043c \u0438 \u0432\u0441\u0451 \u043e\u0431\u044a\u044f\u0441\u043d\u0438\u043c \ud83e\udd0d<\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <script>t_onReady(function() {t_onFuncLoad('t668_init',function() {t668_init('1845950711');});});<\/script> <style> #rec1845950711 .t668__title{font-size:20px;color:#192032;font-family:var(--t-text-font,Arial);font-weight:400;}#rec1845950711 .t668__text{font-size:16px;color:#192032;font-family:var(--t-text-font,Arial);font-weight:400;}<\/style> <style> #rec1845950711 .t668__wrapper{border-radius:20px;}<\/style> <\/div> <div id=\"rec1846448491\" class=\"r t-rec\" style=\" \" data-record-type=\"270\"> <div class=\"t270\"><\/div> <script>t_onReady(function() {var hash=window.location.hash;t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,-3);});setTimeout(function() {var curPath=window.location.pathname;var curFullPath=window.location.origin + curPath;var recs=document.querySelectorAll('.r');Array.prototype.forEach.call(recs,function(rec) {var selects='a[href^=\"#\"]:not([href=\"#\"]):not(.carousel-control):not(.t-carousel__control):not([href^=\"#price\"]):not([href^=\"#submenu\"]):not([href^=\"#popup\"]):not([href*=\"#zeropopup\"]):not([href*=\"#closepopup\"]):not([href*=\"#closeallpopup\"]):not([href^=\"#prodpopup\"]):not([href^=\"#order\"]):not([href^=\"#!\"]):not([target=\"_blank\"]),' +\n'a[href^=\"' + curPath + '#\"]:not([href*=\"#!\/tfeeds\/\"]):not([href*=\"#!\/tproduct\/\"]):not([href*=\"#!\/tab\/\"]):not([href*=\"#popup\"]):not([href*=\"#zeropopup\"]):not([href*=\"#closepopup\"]):not([href*=\"#closeallpopup\"]):not([target=\"_blank\"]),' +\n'a[href^=\"' + curFullPath + '#\"]:not([href*=\"#!\/tfeeds\/\"]):not([href*=\"#!\/tproduct\/\"]):not([href*=\"#!\/tab\/\"]):not([href*=\"#popup\"]):not([href*=\"#zeropopup\"]):not([href*=\"#closepopup\"]):not([href*=\"#closeallpopup\"]):not([target=\"_blank\"])';var elements=rec.querySelectorAll(selects);Array.prototype.forEach.call(elements,function(element) {element.addEventListener('click',function(event) {event.preventDefault();var hash=this.hash.trim();t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,-3);});});});});if(document.querySelectorAll('.js-store').length>0||document.querySelectorAll('.js-feed').length>0) {t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,-3,1);});}},500);setTimeout(function() {var hash=window.location.hash;if(hash&&document.querySelectorAll('a[name=\"' + hash.slice(1) + '\"], div[id=\"' + hash.slice(1) + '\"]').length>0) {if(window.isMobile) {t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,0);});} else {t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,0);});}}},1000);window.addEventListener('popstate',function() {var hash=window.location.hash;if(hash&&document.querySelectorAll('a[name=\"' + hash.slice(1) + '\"], div[id=\"' + hash.slice(1) + '\"]').length>0) {if(window.isMobile) {t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,0);});} else {t_onFuncLoad('t270_scroll',function() {t270_scroll(hash,0);});}}});});<\/script> <\/div> <\/div> <!--\/allrecords-->","protected":false},"excerpt":{"rendered":"\u0416\u0435\u043d\u0430\u0442\u0438\u043a: \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c, \u0435\u0441\u043b\u0438 \u0442\u0432\u043e\u0439 \u043b\u044e\u0431\u0438\u043c\u044b\u0439 \u043d\u0435\u0441\u0432\u043e\u0431\u043e\u0434\u0435\u043d \u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u043f\u0441\u0438\u0445\u043e\u043b\u043e\u0433\u0430\u043c\u0438, \u0447\u0442\u043e\u0431\u044b \u0442\u044b: \u041f\u043e\u043c\u043e\u0436\u0435\u0442, \u0435\u0441\u043b\u0438 \u0442\u044b&nbsp;\u043f\u043e\u043f\u0430\u043b\u0430 \u0432&nbsp;\u043b\u044e\u0431\u043e\u0432\u043d\u044b\u0439 \u0442\u0440\u0435\u0443\u0433\u043e\u043b\u044c\u043d\u0438\u043a \u0438&nbsp;\u0441\u043e\u0432\u0441\u0435\u043c \u0437\u0430\u043f\u0443\u0442\u0430\u043b\u0430\u0441\u044c \u0420\u0430\u0437\u043e\u0431\u0440\u0430\u043b\u0430\u0441\u044c, \u0447\u0442\u043e \u0434\u0435\u043b\u0430\u0442\u044c \u0434\u0430\u043b\u044c\u0448\u0435 \u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u043b\u0430 \u043d\u0430 \u0441\u0432\u043e\u0438 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u0418\u0437\u0431\u0430\u0432\u0438\u043b\u0430\u0441\u044c \u043e\u0442 \u0441\u043b\u0430\u0434\u043a\u0438\u0445 \u0438\u043b\u043b\u044e\u0437\u0438\u0439 \u0417\u0430\u0431\u0440\u0430\u0442\u044c \u0433\u0430\u0439\u0434 \u041f\u0440\u0438\u0432\u0435\u0442. \u0422\u044b&nbsp;\u0437\u0434\u0435\u0441\u044c, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043f\u043e\u043f\u0430\u043b\u0430 \u0432&nbsp;\u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u044f \u0441&nbsp;\u0436\u0435\u043d\u0430\u0442\u044b\u043c \u043c\u0443\u0436\u0447\u0438\u043d\u043e\u0439 \u0418\u043d\u043e\u0433\u0434\u0430 \u043e\u043d&nbsp;\u0433\u043e\u0432\u043e\u0440\u0438\u0442: \u00ab\u041f\u043e\u0442\u0435\u0440\u043f\u0438 \u0435\u0449\u0451 \u0447\u0443\u0442\u044c-\u0447\u0443\u0442\u044c, \u0441\u043a\u043e\u0440\u043e \u0443&nbsp;\u043d\u0430\u0441 \u0432\u0441\u0451 \u043d\u0430\u043b\u0430\u0434\u0438\u0442\u0441\u044f\u00bb, \u043d\u043e&nbsp;\u0432\u0441\u0451 \u043e\u0441\u0442\u0430\u0435\u0442\u0441\u044f \u043f\u043e&nbsp;\u043f\u0440\u0435\u0436\u043d\u0435\u043c\u0443: 06&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/es\/genatik\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">\u0416\u0435\u043d\u0430\u0442\u0438\u043a<\/span><\/a>","protected":false},"author":18,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-1003814","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/pages\/1003814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/comments?post=1003814"}],"version-history":[{"count":13,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/pages\/1003814\/revisions"}],"predecessor-version":[{"id":1003856,"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/pages\/1003814\/revisions\/1003856"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/es\/wp-json\/wp\/v2\/media?parent=1003814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}