



{"id":987542,"date":"2025-04-14T16:21:32","date_gmt":"2025-04-14T16:21:32","guid":{"rendered":"https:\/\/mindspa.me\/?p=987542"},"modified":"2025-04-14T16:21:35","modified_gmt":"2025-04-14T16:21:35","slug":"donde-termina-el-cuidado-y-comienza-el-control","status":"publish","type":"post","link":"https:\/\/mindspa.me\/en\/donde-termina-el-cuidado-y-comienza-el-control\/","title":{"rendered":"Donde termina el cuidado y comienza el control"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-1024x683.webp\" alt=\"\" class=\"wp-image-987534\" style=\"width:233px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-1024x683.webp 1024w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-300x200.webp 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-768x512.webp 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-1536x1024.webp 1536w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-2048x1366.webp 2048w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-18x12.webp 18w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-930x620.webp 930w, https:\/\/mindspa.me\/wp-content\/uploads\/2025\/04\/pexels-a-darmel-6642995-600x400.webp 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Es natural que una persona cuide a su pareja y quiera que la cuiden. Pero a veces hay demasiada atenci\u00f3n: ya no da placer, pero te hace sentir inc\u00f3moda. A veces incluso culpable. \u00bfSuena familiar? En este art\u00edculo, intentaremos descubrir d\u00f3nde termina el cuidado placentero y comienza el control inc\u00f3modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Llamo para preguntarte c\u00f3mo est\u00e1s porque not\u00e9 que has estado un poco molesta \u00faltimamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Quiero saber cada detalle de tu vida, porque me siento ansioso y quiero controlar lo que haces y a qui\u00e9n ves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Estoy listo para escucharte y tratar de comprender tus sentimientos sin juzgar ni sesgar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Debes contarme todo lo que sucede en tu vida, de lo contrario sospechar\u00e9 que me est\u00e1s ocultando algo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Estar\u00e9 all\u00ed para ti si necesitas mi ayuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Resolver\u00e9 tus problemas yo mismo, porque creo que no puedes arregl\u00e1rtelas sola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Estoy orgulloso de ti y de tus logros. Realmente mereces reconocimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Tienes que alcanzar ciertas metas para cumplir con mis expectativas y obtener mi aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Respeto tu independencia, tus l\u00edmites y tu espacio personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Espero que est\u00e9s disponible 24\/7. No necesitas espacio personal cuando estamos juntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Eres libre de elegir y tomar decisiones que satisfagan tus necesidades y deseos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: No deber\u00edas hacer nada sin mi permiso. S\u00e9 lo que es mejor para ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Estoy dispuesto a apoyarte en cualquier situaci\u00f3n y ayudarte a alcanzar tus metas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: No puedes confiar en nadie m\u00e1s que en m\u00ed. Solo yo puedo resolver todos tus problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: quiero que seas feliz, incluso si eso significa que tenemos que tomar decisiones diferentes.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><ul class=\"products columns-2\">\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 961407 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/987542?add-to-cart=961407\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Add to cart: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u201cLudopat\u00eda\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_961407\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a56ff346fbd6\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 11403 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/987542?add-to-cart=11403\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Add to cart: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u201cSuperar una separaci\u00f3n (para mujer)\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_11403\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a56ff34702ca\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Si est\u00e1s conmigo, tendr\u00e1s que hacer lo que yo quiera. Incluso si te hace infeliz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Te apoyo en tus decisiones y acciones porque creo en tus ideas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: Tienes que hacer lo que digo, porque yo s\u00e9 lo que es mejor y siempre tengo la raz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cari\u00f1oso: Me alegro de que te mantengas en contacto con otras personas y tengas tus propios amigos. Agradezco la confianza y el respeto entre nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Control: No debes ver a tus amigos ni mantenerte en contacto con nadie sin mi conocimiento. \u00bfMe est\u00e1s enga\u00f1ando? \u00a1Tengo que controlar tus contactos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprender la diferencia entre cuidar y controlar te ayudar\u00e1 a construir una relaci\u00f3n s\u00f3lida con tu pareja, aprender a escuchar tus propias necesidades y las de los dem\u00e1s.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Es natural que una persona cuide a su pareja y quiera que la cuiden. Pero a veces hay demasiada atenci\u00f3n: ya no da placer, pero te hace sentir inc\u00f3moda. A veces incluso culpable. \u00bfSuena familiar? En este art\u00edculo, intentaremos descubrir d\u00f3nde termina el cuidado placentero y comienza el control inc\u00f3modo. Cari\u00f1oso: Llamo para preguntarte c\u00f3mo&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/en\/donde-termina-el-cuidado-y-comienza-el-control\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Donde termina el cuidado y comienza el control<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":987534,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[83,136,2775,883,989,2686,1164,2774],"class_list":["post-987542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-amar","tag-autocontrol","tag-cuidado","tag-mindspa","tag-pareja","tag-posesividad","tag-relacion","tag-toxicidad"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/987542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/comments?post=987542"}],"version-history":[{"count":1,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/987542\/revisions"}],"predecessor-version":[{"id":987543,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/987542\/revisions\/987543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media\/987534"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media?parent=987542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/categories?post=987542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/tags?post=987542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}