



{"id":979080,"date":"2024-12-28T18:14:53","date_gmt":"2024-12-28T18:14:53","guid":{"rendered":"https:\/\/mindspa.me\/?p=979080"},"modified":"2024-12-28T18:14:56","modified_gmt":"2024-12-28T18:14:56","slug":"las-principales-manipulaciones-de-los-padres-y-como-resistirlas","status":"publish","type":"post","link":"https:\/\/mindspa.me\/en\/las-principales-manipulaciones-de-los-padres-y-como-resistirlas\/","title":{"rendered":"Las principales manipulaciones de los padres y c\u00f3mo resistirlas"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-1024x683.jpg\" alt=\"\" class=\"wp-image-979076\" style=\"width:237px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-1024x683.jpg 1024w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-300x200.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-768x512.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-cottonbro-6603350-1-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La manipulaci\u00f3n es un problema com\u00fan en las relaciones entre los hijos adultos y tus padres. Las manipulaciones a menudo se disfrazan de cari\u00f1o o \u201ccr\u00edtica razonable\u201d cuando en realidad no lo son. Hemos recopilado las formas m\u00e1s comunes de manipulaci\u00f3n para que te resulte m\u00e1s f\u00e1cil identificar d\u00f3nde se pueden violar tus l\u00edmites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cEstoy muerto de miedo por ti\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los padres muestran una ansiedad que literalmente paraliza la actividad de sus hijos adultos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de las veces los padres dicen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00a1Estoy preocupado por ti! \u00a1Hago esto porque te quiero mucho!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00a1Hago todo por ti, y me pagas as\u00ed!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00a1Cuando no me llamas por la noche, me preocupo mucho!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Si haces eso, me matar\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ni\u00f1os se contaminan con la ansiedad de los padres o experimentan una irritaci\u00f3n mal contenida que no se les permite mostrar. Cuando te sientes preocupado por tus padres y asumes la responsabilidad por tu condici\u00f3n, permites que te manipulen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ansiedad de tus padres es tu \u00e1rea de responsabilidad, no la tuya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201c\u00a1Esc\u00fachame!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los padres a menudo interfieren en la vida de sus hijos adultos queriendo ayudar, compartir una opini\u00f3n y dar consejos. Al mismo tiempo, a menudo exigen gratitud por su atenci\u00f3n. Dichos padres suelen decir algo como:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Si yo fuera t\u00fa\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Deber\u00edas haberlo hecho as\u00ed\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb No, lo est\u00e1s haciendo mal\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Te dir\u00e9 c\u00f3mo\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00a1No bebas en la fiesta de la oficina, es malo para ti! \u00a1No comas dulces, engordar\u00e1s!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Deber\u00edas comer\/tomar esto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Deber\u00edas hacer conexiones con&#8230; y no deber\u00edas hacer conexiones con&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Ya hice los arreglos. \u00bfY qu\u00e9 si no me lo pediste?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos consejos son molestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los que te dan consejos quieren ayudarte e instruirte sobre c\u00f3mo vivir \u201ccorrectamente\u201d. El problema es que lo \u201ccorrecto\u201d es lo que te conviene, no solo lo bueno en general, y nadie sabe c\u00f3mo lograrlo excepto t\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cQuiero saberlo todo\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichos padres quieren un informe sobre todo lo que sucede en tu vida. Suelen decir cosas como:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00a1Tienes que dec\u00edrmelo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00bfPor qu\u00e9 no quieres mostrarme esto si no tienes nada que ocultar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Tengo derecho a saber, d\u00edmelo para no tener que preocuparme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Soy tu padre, debes escucharme\/hablarme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00bfPregunt\u00e9 algo malo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Soy una persona sensible, \u00bfrealmente te cuesta tanto visitarme m\u00e1s a menudo\/hacer lo que quiero\/satisfacer mis peticiones?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00bfC\u00f3mo estuvo la fiesta? \u00bfQu\u00e9 comiste all\u00ed? \u00bfY qui\u00e9n m\u00e1s estaba all\u00ed?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb \u00bfCu\u00e1ndo te casar\u00e1s?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichos padres quieren controlar la vida de su hijo adulto e involucrarse demasiado en ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero puedes manejar tu vida por tu cuenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cTodo es tu culpa\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El padre transfiere la responsabilidad de sus propias acciones, elecciones y sentimientos al ni\u00f1o. Suena as\u00ed:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Arruinaste mi vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Gracias a ti, yo\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Si no fuera por ti\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Fuiste t\u00fa quien me llev\u00f3 a esto&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Hago todo por ti, y me lo pagas as\u00ed\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerda que t\u00fa no eres responsable de los fracasos de tus padres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cDej\u00e9 todo por ti&#8230;\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los padres sacrificados dicen que tuvieron que renunciar a mucho por ti:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Dej\u00e9 la universidad por ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Tuve que vivir con un hombre al que no amaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Sacrifiqu\u00e9 mi carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Todos se divirtieron y disfrutaron de sus vidas, mientras yo ya te ten\u00eda a ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El prop\u00f3sito del mensaje de los padres es obtener acceso ilimitado a tus recursos: tiempo, atenci\u00f3n, cuidado; e involucrarse en tu vida como \u00fanico sentido de su existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tienes tu propia vida. Tienes que establecer los l\u00edmites de tu participaci\u00f3n en la vida de tus padres y la participaci\u00f3n de ellos en tu vida, para que su \u201csacrificio\u201d no sea en vano y tengas la oportunidad de vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cDebes cumplir mis expectativas\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un padre puede tener cierta idea sobre su hijo, cierta imagen perfecta: quiero que seas as\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb El pelo largo no te queda bien, c\u00f3rtate el pelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Siempre usamos traje y corbata cuando salimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb No obtendr\u00e1s una educaci\u00f3n decente en esta universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Tus amigos son malos para ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este caso, el ni\u00f1o forma parte de una imagen de felicidad bastante r\u00edgida y espec\u00edfica. La meta de los padres con esta actitud es la autorrealizaci\u00f3n a trav\u00e9s de sus hijos, a trav\u00e9s de sus \u00e9xitos y logros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no eres una imagen fija en el \u00e1lbum de fotos de im\u00e1genes felices de tus padres. Tu imagen de felicidad puede ser diferente a la de tus padres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manipulaci\u00f3n: \u201cNo puedes ser mejor que yo\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los padres que transmiten este mensaje quieren validaci\u00f3n. Influyen en el ni\u00f1o a trav\u00e9s del miedo y la verg\u00fcenza:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Yo fui un excelente estudiante en la escuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb 3er lugar otra vez, yo hubiera obtenido el 1er lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Cierto, sab\u00eda que no ser\u00edas capaz de hacerlo, no eres muy ingenioso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb Me veo m\u00e1s atractivo incluso ahora.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><ul class=\"products columns-2\">\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 961407 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/979080?add-to-cart=961407\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Add to cart: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u201cLudopat\u00eda\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_961407\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a56eb0e690e4\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 11403 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/979080?add-to-cart=11403\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Add to cart: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u201cSuperar una separaci\u00f3n (para mujer)\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_11403\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a56eb0e697bd\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta forma de comportamiento de los padres oculta su miedo a ser peor que su propio hijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no tienes que competir con tus padres. Dirige tu atenci\u00f3n a algo que sea realmente importante para ti y trabaja en ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo resistir la manipulaci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El propio mecanismo de manipulaci\u00f3n implica que ser\u00e1 resistido. As\u00ed que no intentes presentar una pelea abierta y no te involucres en discusiones largas. Carece de sentido. Lo que realmente ayuda es nombrar abiertamente lo que est\u00e1 pasando, por ejemplo: \u201cLo que est\u00e1s haciendo es manipulaci\u00f3n, quieres&#8230; y por eso est\u00e1s diciendo&#8230; y haciendo&#8230; Mientras tanto, siento&#8230; y evita que tome acci\u00f3n. As\u00ed que ahora me voy a ir\/salir\/colgar el tel\u00e9fono para lidiar con mis sentimientos. Hablaremos\/nos encontraremos m\u00e1s tarde\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una herramienta importante para resistir la manipulaci\u00f3n es retrasar las reacciones inconscientes. Es posible que hayas notado que las manipulaciones siguen un guion pre escrito. Entonces, antes de una pr\u00f3xima conversaci\u00f3n manipuladora o inmediatamente despu\u00e9s de una:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb repasa mentalmente el escenario de la conversaci\u00f3n: lo que suele suceder, lo que suele hacer el manipulador, lo que dice, con qu\u00e9 amenaza, c\u00f3mo act\u00faa;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb escribe tus propias acciones: c\u00f3mo sueles responder, c\u00f3mo tratas de defenderte;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cb piensa c\u00f3mo puedes cambiar tus propias acciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo: si sueles guardar silencio, puedes empezar a dar argumentos; si por lo general tratas de convencer acaloradamente al manipulador, simplemente di \u201cno\u201d y guarda silencio. Tienes derecho a hacer eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el momento de la manipulaci\u00f3n, debes tener una forma r\u00e1pida de recuperarte y entrar en un estado estable. Por ejemplo, puedes presionar la punta de la lengua contra el paladar. O tratar de concentrarte en inhalar y exhalar lenta, tranquila y no muy profundamente durante el mayor tiempo posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas no siempre manipulan intencionalmente, a veces es la \u00fanica forma de comunicaci\u00f3n que conocen. No conocen otra forma. As\u00ed que tus nuevas reacciones a la presi\u00f3n de tus padres bien pueden cambiar su comportamiento.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La manipulaci\u00f3n es un problema com\u00fan en las relaciones entre los hijos adultos y tus padres. Las manipulaciones a menudo se disfrazan de cari\u00f1o o \u201ccr\u00edtica razonable\u201d cuando en realidad no lo son. Hemos recopilado las formas m\u00e1s comunes de manipulaci\u00f3n para que te resulte m\u00e1s f\u00e1cil identificar d\u00f3nde se pueden violar tus l\u00edmites. Manipulaci\u00f3n:&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/en\/las-principales-manipulaciones-de-los-padres-y-como-resistirlas\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Las principales manipulaciones de los padres y c\u00f3mo resistirlas<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":979076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[83,833,877,883,936,977],"class_list":["post-979080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-amar","tag-manipulaciones","tag-miedo","tag-mindspa","tag-ninos","tag-padres"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/979080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/comments?post=979080"}],"version-history":[{"count":1,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/979080\/revisions"}],"predecessor-version":[{"id":979082,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/979080\/revisions\/979082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media\/979076"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media?parent=979080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/categories?post=979080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/tags?post=979080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}