



{"id":977747,"date":"2024-12-09T22:04:48","date_gmt":"2024-12-09T22:04:48","guid":{"rendered":"https:\/\/mindspa.me\/?p=977747"},"modified":"2024-12-09T22:04:50","modified_gmt":"2024-12-09T22:04:50","slug":"sobre-la-gente-y-la-sed","status":"publish","type":"post","link":"https:\/\/mindspa.me\/en\/sobre-la-gente-y-la-sed\/","title":{"rendered":"Sobre la gente y la sed"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-1024x683.jpg\" alt=\"\" class=\"wp-image-977743\" style=\"width:260px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-1024x683.jpg 1024w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-300x200.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-768x512.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/12\/pexels-fotios-photos-1346155-1-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Es un caluroso d\u00eda de verano.<\/p>\n\n\n\n<p>El sol est\u00e1 ardiendo, el aire se siente denso y pesado.<\/p>\n\n\n\n<p>Te mueres de sed.<\/p>\n\n\n\n<p>La sed te atrae a un puesto de bebidas brillante.<\/p>\n\n\n\n<p>Ves un vaso tentador y sudoroso lleno de gaseosa marr\u00f3n con hielo.<\/p>\n\n\n\n<p>Lo agarras y empiezas a beber con avidez.<\/p>\n\n\n\n<p>Pero&#8230;<\/p>\n\n\n\n<p>No te sientes satisfecho.<\/p>\n\n\n\n<p>Tomas un segundo vaso con la esperanza de que te ayude a humedecer tu garganta seca y con picaz\u00f3n.<\/p>\n\n\n\n<p>Bebes trago tras trago&#8230;<\/p>\n\n\n\n<p>Pero la sed no desaparece.<\/p>\n\n\n\n<p>Cuanto m\u00e1s bebes este tentador l\u00edquido gaseoso, m\u00e1s fuerte se vuelve tu sed.<\/p>\n\n\n\n<p>Es una tortura.<\/p>\n\n\n\n<p>Te enojas.<\/p>\n\n\n\n<p>Te sientes mal.<\/p>\n\n\n\n<p>Eso es porque no puedes saciar la sed con un refresco dulce.<\/p>\n\n\n\n<p>Necesitas agua para eso.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><!--<ul class=\"products columns---><!--\">-->\n<style>\n \n    .woocommerce span.onsale{\n        display: none;\n    }\n    .woocommerce-Price-amount.amount{\n        color: #fff;\n    }\n    .often_buy-list::before, .often_buy-list::after{\n        display: none!important;\n    }\n    .related.products h2{\n        margin-bottom: 40px;\n    }\n<\/style>\n<ul class=\"often_buy-list\">\n\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\t\u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 40 \u0434\u043d\u0435\u0439\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/977747?add-to-cart=961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Add to cart: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u201cLudopat\u00eda\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04ec1545b8c\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\tDuration: 30 days\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/977747?add-to-cart=11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Add to cart: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u201cSuperar una separaci\u00f3n (para mujer)\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04ec1546912\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p>En realidad, no estamos hablando de bebidas.<\/p>\n\n\n\n<p>Estamos hablando de relaciones.<\/p>\n\n\n\n<p>La gente a menudo trata de satisfacer su sed de amor con una relaci\u00f3n que no sirve para nada.<\/p>\n\n\n\n<p>Eligen personas que les atraigan, pero nunca les dar\u00e1n lo suficiente para saciar su sed.<\/p>\n\n\n\n<p>Est\u00e1n atormentadas y agotadas, se secan.<\/p>\n\n\n\n<p>Aprende a elegir bien las bebidas y las personas.<\/p>\n\n\n\n<p>Para que puedas saciar tu sed, y no dejar que empeore.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Es un caluroso d\u00eda de verano. El sol est\u00e1 ardiendo, el aire se siente denso y pesado. Te mueres de sed. La sed te atrae a un puesto de bebidas brillante. Ves un vaso tentador y sudoroso lleno de gaseosa marr\u00f3n con hielo. Lo agarras y empiezas a beber con avidez. Pero&#8230; No te sientes&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/en\/sobre-la-gente-y-la-sed\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Sobre la gente y la sed<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":977743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[164,194,2734,2736,525,883,2735],"class_list":["post-977747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-bienestar","tag-calma","tag-cascada","tag-deshidracion","tag-estres","tag-mindspa","tag-sed"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/977747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/comments?post=977747"}],"version-history":[{"count":1,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/977747\/revisions"}],"predecessor-version":[{"id":977748,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/977747\/revisions\/977748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media\/977743"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media?parent=977747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/categories?post=977747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/tags?post=977747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}