



{"id":960524,"date":"2024-06-25T15:48:19","date_gmt":"2024-06-25T15:48:19","guid":{"rendered":"https:\/\/mindspa.me\/?p=960524"},"modified":"2024-06-25T15:48:24","modified_gmt":"2024-06-25T15:48:24","slug":"una-persona-codependiente","status":"publish","type":"post","link":"https:\/\/mindspa.me\/en\/una-persona-codependiente\/","title":{"rendered":"Una Persona Codependiente"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-1024x683.jpg\" alt=\"\" class=\"wp-image-960529\" style=\"width:249px;height:auto\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-1024x683.jpg 1024w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-300x200.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-768x512.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/06\/pexels-amina-filkins-5424687-2-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u00bfQui\u00e9n es una persona codependiente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una persona para quien es esencial ser necesitado e indispensable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una persona que a menudo se siente resentida porque el comportamiento de los dem\u00e1s no cumple con sus expectativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una persona que elige la manipulaci\u00f3n en lugar de una comunicaci\u00f3n abierta y segura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una persona que cree que puede cambiar a alguien: inspirar, ense\u00f1ar, reeducar, remodelar. Solo necesitas presionar los botones correctos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una persona que en el fondo cree que la dependencia es m\u00e1s confiable que el amor. Y realmente no quieren que su pareja pueda prescindir de su relaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una persona que indirecta o expl\u00edcitamente controla a sus seres queridos (su pareja, amigos o familiares).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una persona que transfiere la responsabilidad de su condici\u00f3n, comportamiento y decisiones a otros. Sus frases t\u00edpicas incluyen: \u201cMe haces sentir mal\u201d o \u201cMe est\u00e1s obligando a hacer esto\u201d.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><ul class=\"products columns-2\">\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 961407 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/960524?add-to-cart=961407\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Add to cart: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u201cLudopat\u00eda\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_961407\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"USD\" data-redraw-id=\"6a5766845bca5\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>99.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 99.99&#036;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>44.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 44.99&#036;.<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n            <div class=\"product_meta\">\n\n                \n                \n                    \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 11403 \u0434\u043d\u0435\u0439\n\n                \n\n                \n            <\/div>\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/960524?add-to-cart=11403\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Add to cart: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u201cSuperar una separaci\u00f3n (para mujer)\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_11403\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"USD\" data-redraw-id=\"6a5766845c3ee\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>99.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 99.99&#036;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>44.99<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 44.99&#036;.<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una persona que lucha por comprender sus verdaderos deseos y necesidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siempre piensan que los dem\u00e1s saben m\u00e1s que uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una persona que trata de ganar poder sobre su pareja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya sea a trav\u00e9s de la agresi\u00f3n y la represi\u00f3n, o mediante el servilismo, la impotencia y el placer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una persona que se justifica y acepta las cosas que no le convienen, que le hacen da\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La codependencia es un rasgo de personalidad que se desarrolla en la infancia bajo la influencia de escenarios y actitudes familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afortunadamente, puedes resolverlo como adulto. Nuestro curso Codependency te beneficiar\u00e1 mucho. Lo encontrar\u00e1s en la secci\u00f3n de Cursos.<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es una persona codependiente? Es una persona para quien es esencial ser necesitado e indispensable. Una persona que a menudo se siente resentida porque el comportamiento de los dem\u00e1s no cumple con sus expectativas. Una persona que elige la manipulaci\u00f3n en lugar de una comunicaci\u00f3n abierta y segura. Es una persona que cree que&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/en\/una-persona-codependiente\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Una Persona Codependiente<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":960529,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[100,194,393,525,883,927,1164],"class_list":["post-960524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-ansiedad","tag-calma","tag-dependencia","tag-estres","tag-mindspa","tag-nervioso","tag-relacion"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/960524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/comments?post=960524"}],"version-history":[{"count":0,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/960524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media\/960529"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media?parent=960524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/categories?post=960524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/tags?post=960524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}