



{"id":8364,"date":"2021-09-12T15:31:06","date_gmt":"2021-09-12T15:31:06","guid":{"rendered":"https:\/\/www.mindspa.me\/?p=8364"},"modified":"2021-09-12T15:31:06","modified_gmt":"2021-09-12T15:31:06","slug":"alguien-me-debe-dinero-pero-no-lo-devuelven","status":"publish","type":"post","link":"https:\/\/mindspa.me\/en\/alguien-me-debe-dinero-pero-no-lo-devuelven\/","title":{"rendered":"Alguien me debe dinero, pero no lo devuelven"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"http:\/\/onelink.to\/mindspa\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/vxY6hTW\/Download-Mindspa-ES.png\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5.jpg\" alt=\"\" class=\"wp-image-8356\" width=\"257\" height=\"172\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5.jpg 980w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-600x404.jpg 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-64x43.jpg 64w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-300x202.jpg 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-768x517.jpg 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-18x12.jpg 18w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-930x620.jpg 930w, https:\/\/mindspa.me\/wp-content\/uploads\/2021\/09\/Nuovo-progetto-2-5-500x337.jpg 500w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" \/><\/figure><\/div>\n\n\n\n<p>Quiz\u00e1s, solo el tema del dinero tiene m\u00e1s tab\u00faes que el tema del sexo. Es dif\u00edcil discutir el salario al solicitar un trabajo (dir\u00e9 m\u00e1s, dir\u00e1n que pienso demasiado en m\u00ed mismo, dir\u00e9 menos, me equivocar\u00e9), no es f\u00e1cil ponerse de acuerdo sobre la contribuci\u00f3n de todos al presupuesto familiar. Pero la cuesti\u00f3n de la devoluci\u00f3n del dinero prestado rompe todos los r\u00e9cords en cuanto a la incomodidad de un posible conflicto.<\/p>\n\n\n\n<p>Suzi dice: una amiga me debe dinero, pero, aparentemente, no me lo devolver\u00e1. Y es inc\u00f3modo para m\u00ed recordarle: no quiero parecer demasiado materialista.<\/p>\n\n\n\n<p>Ivan sol\u00eda prestar dinero a su colega Keith. Solo un poquito: ya sea por un caf\u00e9 (\u201coh, dej\u00e9 el dinero en mi chaqueta\u201d) o por cigarrillos (\u201cOlvid\u00e9 por completo que me estoy quedando sin\u201d), luego para almorzar (\u201camigo, si no es demasiado dif\u00edcil para ti\u201d) &#8212; y Keith nunca los devolvi\u00f3. Iv\u00e1n se sinti\u00f3 inc\u00f3modo, pero dud\u00f3 en record\u00e1rselo, son solo unos pocos d\u00f3lares aqu\u00ed y all\u00e1&#8230; Si fuera una gran suma, ser\u00eda una historia diferente&#8230;<\/p>\n\n\n\n<p>Robert le prest\u00f3 dinero a su primo para una lavadora. El acuerdo era por un mes, pero ya han pasado cuatro meses. Durante este tiempo, el primo incluso se fue de vacaciones, y aun as\u00ed, hay silencio sobre el dinero &#8230; Robert est\u00e1 enojado, pero no dice nada, despu\u00e9s de todo, son familia&#8230;<\/p>\n\n\n\n<p>Por cierto, \u00bfpor qu\u00e9 nos resulta tan inc\u00f3modo recordar el dinero que tanto nos cost\u00f3 ganar? \u00bfQu\u00e9 hay dentro de nosotros que pesa sobre nuestra lengua, y vacilamos angustiosamente y permanecemos en silencio, incapaces de decir una simple frase?<\/p>\n\n\n\n<p>Suzi, por ejemplo, expres\u00f3 una idea importante: no quiero parecer demasiado materialista. Ivan tiene miedo de parecer mezquino &#8212; parece que si le recuerda a Keith sobre el dinero, parecer\u00e1 un taca\u00f1o. Los lazos familiares impiden que Robert hable de la deuda: somos una familia, \u00bfc\u00f3mo puedo decir simplemente &#171;devu\u00e9lveme mi dinero&#187;?<\/p>\n\n\n\n<p>Resulta que todos tienen sus propias actitudes en la cabeza, lo que puede interferir en gran medida con la comunicaci\u00f3n normal. Pero recordar tu dinero no es ser demasiado materialista, sino una acci\u00f3n completamente adecuada. Tal vez sea un centavo &#8212; pero es tu centavo, y depende de ti deshacerte de \u00e9l y no de otra persona. El hecho de que el dinero fuera tomado por un familiar tampoco es un argumento. Cuando prestes a cualquier persona, debes discutir los t\u00e9rminos del pr\u00e9stamo con mucha claridad (\u00a1en voz alta!). De lo contrario, ser\u00e1 un regalo, no un pr\u00e9stamo. Y ambos lados deber\u00edan verlo de la misma manera.<\/p>\n\n\n\n<p>Recordar la deuda es un papel desagradecido. Para muchos, esto es dif\u00edcil e incluso embarazoso. Suzi mencion\u00f3 el sentimiento de una terrible humillaci\u00f3n ante la sola idea de tal di\u00e1logo. \u00bfDe d\u00f3nde provienen estas emociones? Cada caso es \u00fanico, pero, muy probablemente, algo dentro de nosotros entra en conflicto: si te recuerdo el dinero, soy malo (codicioso, mezquino, falto de tacto) &#8230; Tiene sentido explorar tus puntos de vista sobre este tema con m\u00e1s detalle.<\/p>\n\n\n<div align=\"center\"><img decoding=\"async\" src=\"https:\/\/i.ibb.co\/nfNTjqX\/ES-Refund-catalog.gif\"><\/div>\n<p><div class=\"woocommerce columns-2\"><!--<ul class=\"products columns---><!--\">-->\n<style>\n \n    .woocommerce span.onsale{\n        display: none;\n    }\n    .woocommerce-Price-amount.amount{\n        color: #fff;\n    }\n    .often_buy-list::before, .often_buy-list::after{\n        display: none!important;\n    }\n    .related.products h2{\n        margin-bottom: 40px;\n    }\n<\/style>\n<ul class=\"often_buy-list\">\n\n\n<li class=\"often_buy-list-item product type-product post-961407 status-publish first instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ludopat\u00eda\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2024\/07\/Gambling-Problem_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\t\u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c: 40 \u0434\u043d\u0435\u0439\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/ludopatia_es\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/8364?add-to-cart=961407\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"961407\" data-product_sku=\"961407\" aria-label=\"Add to cart: \u201cLudopat\u00eda\u201d\" rel=\"nofollow\" data-success_message=\"\u201cLudopat\u00eda\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04f982108dd\"  data-product-id=\"961407\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n\n<li class=\"often_buy-list-item product type-product post-11403 status-publish last instock product_cat-cursos has-post-thumbnail sale virtual sold-individually taxable purchasable product-type-simple\">\n\n\n\n\n\n\n<a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\">\n<div class=\"product-welcome__slide\"><img decoding=\"async\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png\" alt=\"\"><\/div>\n<\/a>\n\n\n    <div class=\"sp-product-image\"><div class=\"img-wrap\">\n\t\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Superar una separaci\u00f3n (para mujer)\" srcset=\"https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-300x300.png 300w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-150x150.png 150w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-768x768.png 768w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-12x12.png 12w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-600x600.png 600w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES-100x100.png 100w, https:\/\/mindspa.me\/wp-content\/uploads\/2022\/10\/Post-Breakup-F_ES.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div>\n    <div class=\"often_buy-list-item-dop\">\n        <div class=\"often_buy-list-item-duration\">\n\t\t<div class=\"product_meta\">\n\n\t\t\t\n\t\t\t\t\t\t\tDuration: 30 days\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n        <\/div>\n        <div class=\"often_buy-list-item-button\">\n            <div class=\"nv-card-content-wrapper\"><a href=\"https:\/\/mindspa.me\/en\/c\/superar-una-separacion-para-mujer\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            Read more\n            <\/a><a href=\"\/en\/wp-json\/wp\/v2\/posts\/8364?add-to-cart=11403\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"11403\" data-product_sku=\"11403\" aria-label=\"Add to cart: \u201cSuperar una separaci\u00f3n (para mujer)\u201d\" rel=\"nofollow\" data-success_message=\"\u201cSuperar una separaci\u00f3n (para mujer)\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\n\t<span class=\"price\"><span class=\"woocs_price_code\" data-currency=\"RUB\" data-redraw-id=\"6a04f982119b2\"  data-product-id=\"11403\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7999&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Original price was: 7999&nbsp;&#x440;..<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3599&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#x440;.<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Current price is: 3599&nbsp;&#x440;..<\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul>\n<\/div><\/br><\/p>\n\n\n\n<p>Pero, \u00bfqu\u00e9 hacer si ya sucedi\u00f3 una situaci\u00f3n en la que no recuperaste tu dinero, c\u00f3mo record\u00e1rselo al deudor?<\/p>\n\n\n\n<p>\u2022 Es absolutamente normal estar interesado en lo que pas\u00f3 con tu dinero. Por lo tanto, cuando se acerque la fecha de vencimiento, haz una pregunta simple, clara y espec\u00edfica: &#171;\u00bfCu\u00e1ndo crees que podr\u00e1s devolver el dinero que te prest\u00e9?&#187;<\/p>\n\n\n\n<p>&#171;Natalie, \u00bfcu\u00e1ndo tendr\u00e1s la oportunidad de devolverme los $100 que te preste hace dos meses?&#187;<\/p>\n\n\n\n<p>\u2022 Apoya el recordatorio indicando por qu\u00e9 es necesario devolver el dinero ahora:<\/p>\n\n\n\n<p>\u201cMi familia y yo nos iremos de vacaciones la pr\u00f3xima semana &#8212; Necesito este dinero. \u00bfCu\u00e1ndo puedes devolverlo: ma\u00f1ana o el mi\u00e9rcoles? &#171;<\/p>\n\n\n\n<p>\u2022 Puedes hacer preguntas sobre para qu\u00e9 se tom\u00f3 el dinero. Esto ayudar\u00e1 a establecer un puente hacia la pregunta del dinero, o tal vez no sea necesario y el deudor mismo sacar\u00e1 a relucir la deuda.<\/p>\n\n\n\n<p>&#171;\u00bfC\u00f3mo est\u00e1 tu nueva caminadora? \u00bfLa usas regularmente, te gusta?&#187;<\/p>\n\n\n\n<p>\u2022 Si es demasiado dif\u00edcil hablar de dinero \u201cdiciendo palabras con tu boca\u201d, usa mensajer\u00eda instant\u00e1nea, siguiendo las mismas reglas.<\/p>\n\n\n\n<p>\u2022 Si un plan de pagos a plazos es aceptable para ti, ofrece esta opci\u00f3n si est\u00e1s seguro de las dificultades financieras del deudor.<\/p>\n\n\n\n<p>\u201cSi es dif\u00edcil devolverlo todo de una vez, \u00bfquiz\u00e1s puedas devolverlo con el tiempo? Por ejemplo, \u00bf$100 al mes funcionar\u00e1n para ti? &#171;<\/p>\n\n\n\n<p>\u2022 Si han pasado todas las fechas l\u00edmite y no se devuelve el dinero, puedes decir algo como: \u201cAnthony, estuve feliz de poder ayudarte con el dinero para tu proyecto de renovaci\u00f3n el verano pasado. Ahora, yo mismo necesito dinero con urgencia para resolver mis problemas, y estoy seguro de que t\u00fa tambi\u00e9n me ayudar\u00e1s devolvi\u00e9ndome el dinero antes del fin de semana. S\u00e9 que t\u00fa y yo somos buenos amigos&#8230; &#187;&nbsp;<\/p>\n\n\n\n<p>Y lo principal &#8212; debes hablar. Estar en silencio y enojado no es una estrategia, nunca vale la pena a largo plazo. Cualquier duda se puede resolver cuando se expresa de forma correcta y delicada.<\/p>\n\n\n\n<p>P.S. Por cierto, result\u00f3 que la amiga de Suzi hab\u00eda olvidado la deuda y le agradeci\u00f3 el recordatorio, estaba terriblemente avergonzada&#8230;<\/p>\n\n\n\n<p>Keith cre\u00eda sinceramente que esto no era un pr\u00e9stamo, sino un favor &#8212; despu\u00e9s de todo, nunca hab\u00eda discutido los t\u00e9rminos del pr\u00e9stamo con Ivan.<\/p>\n\n\n\n<p>Y Robert todav\u00eda ten\u00eda que hablar con su primo, y acordaron la fecha del reembolso, aunque el primo parec\u00eda querer olvidarlo. ?<\/p>\n\n\n\n<\/br><div align=\"center\"><p style=\"color:#408AC4\"><b>Ay\u00fadanos a crecer en Instagram \ud83d\udc47<\/b><\/p><\/div><div class=\"elfsight-app-4226308b-9430-46cd-a5ae-753c637281df\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1s, solo el tema del dinero tiene m\u00e1s tab\u00faes que el tema del sexo. Es dif\u00edcil discutir el salario al solicitar un trabajo (dir\u00e9 m\u00e1s, dir\u00e1n que pienso demasiado en m\u00ed mismo, dir\u00e9 menos, me equivocar\u00e9), no es f\u00e1cil ponerse de acuerdo sobre la contribuci\u00f3n de todos al presupuesto familiar. Pero la cuesti\u00f3n de la&hellip;&nbsp;<a href=\"https:\/\/mindspa.me\/en\/alguien-me-debe-dinero-pero-no-lo-devuelven\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Alguien me debe dinero, pero no lo devuelven<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":8356,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[88,105,292,375,422,502,883,927,1061],"class_list":["post-8364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp","tag-amistad","tag-apatia-2","tag-conflicto","tag-deber","tag-dinero","tag-envidia","tag-mindspa","tag-nervioso","tag-pobreza"],"_links":{"self":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/8364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/comments?post=8364"}],"version-history":[{"count":0,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/posts\/8364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media\/8356"}],"wp:attachment":[{"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/media?parent=8364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/categories?post=8364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindspa.me\/en\/wp-json\/wp\/v2\/tags?post=8364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}